{"id":16690,"date":"2009-11-09T14:02:16","date_gmt":"2009-11-09T18:02:16","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16690"},"modified":"2009-11-09T14:02:16","modified_gmt":"2009-11-09T18:02:16","slug":"finep-destina-r-30-milhoes-para-pesquisas-em-saneamento-e-habitacao","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/finep-destina-r-30-milhoes-para-pesquisas-em-saneamento-e-habitacao\/16690","title":{"rendered":"FINEP destina R$ 30 milh\u00f5es para pesquisas em saneamento e habita\u00e7\u00e3o"},"content":{"rendered":"<p>A <strong>FINEP<\/strong> em parceria com o Minist\u00e9rio das Cidades destinar\u00e1 R$ 30 milh\u00f5es para apoio a projetos de pesquisa inovadores em saneamento b\u00e1sico e habita\u00e7\u00e3o. Ser\u00e3o R$ 15 milh\u00f5es para cada \u00e1rea, conforme a chamada p\u00fablica j\u00e1 dispon\u00edvel no site da empresa, na se\u00e7\u00e3o Chamadas Abertas.<\/p>\n<p><a href=\"http:\/\/www.finep.gov.br\/fundos_setoriais\/acao_transversal\/editais\/SANEAMENTO_E_HABITA%C3%87%C3%83O_versao_final.pdf\" target=\"_blank\">Clique aqui<\/a> para acessar a chamada p\u00fablica.<\/p>\n<p>Os recursos ser\u00e3o aplicados na forma\u00e7\u00e3o de redes de coopera\u00e7\u00e3o de pesquisa que v\u00e3o atuar na busca de solu\u00e7\u00f5es para a melhoria das condi\u00e7\u00f5es de vida da popula\u00e7\u00e3o. Um dos objetivos \u00e9 contribuir com o programa do Governo Federal \u201cMinha casa, minha vida\u201d, que prev\u00ea a constru\u00e7\u00e3o de um milh\u00e3o de moradias para fam\u00edlias com renda mensal de at\u00e9 10 sal\u00e1rios m\u00ednimos. A ideia \u00e9 desenvolver tecnologias inovadoras que ajudem a baratear os custos de constru\u00e7\u00e3o, opera\u00e7\u00e3o e manuten\u00e7\u00e3o dessas novas habita\u00e7\u00f5es.<br \/>\n\u00a0<br \/>\nPodem se candidatar institui\u00e7\u00f5es cient\u00edficas e tecnol\u00f3gicas, p\u00fablicas ou privadas sem fins lucrativos, aptas ao desenvolvimento de pesquisa inovadora nas \u00e1reas definidas. Essas ICTs, que compor\u00e3o as Redes Cooperativas de Pesquisa, devem apresentar as suas propostas por interm\u00e9dio do formul\u00e1rio de sele\u00e7\u00e3o, dispon\u00edvel para download na p\u00e1gina da FINEP (<a href=\"http:\/\/www.finep.gov.br\/\" target=\"_blank\">www.finep.gov.br<\/a>), at\u00e9 o dia 11 de dezembro de 2009.<\/p>\n<p>As \u00e1reas contempladas no edital ser\u00e3o divididas em temas priorit\u00e1rios, seis deles ligados a saneamento b\u00e1sico e quatro relativos \u00e0 habita\u00e7\u00e3o, onde atuar\u00e3o as redes. Na chamada \u201c\u00c1rea 1\u201d (saneamento b\u00e1sico), os temas s\u00e3o os seguintes: tratamento de \u00e1guas de abastecimento; tratamento terci\u00e1rio de esgoto sanit\u00e1rio; tratamento de lixiviado; manejo de \u00e1guas pluviais; consumo de \u00e1gua e energia el\u00e9trica nos sistemas urbanos de abastecimento de \u00e1gua e tratamento do lodo de fossas s\u00e9pticas.<br \/>\n\u00a0<br \/>\nJ\u00e1 na \u201c\u00c1rea 2\u201d (habita\u00e7\u00e3o), ser\u00e3o apoiados os segmentos de tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o aplicadas \u00e0 constru\u00e7\u00e3o; uso racional da \u00e1gua, gera\u00e7\u00e3o de energia renov\u00e1vel e aumento da efici\u00eancia energ\u00e9tica na habita\u00e7\u00e3o de interesse social; avalia\u00e7\u00e3o de desempenho de tecnologias inovadoras; e solu\u00e7\u00f5es tecnol\u00f3gicas aplicadas \u00e0 produ\u00e7\u00e3o e \u00e0 montagem de componentes e de sistemas produtivos.<br \/>\n\u00a0<br \/>\nA primeira etapa do edital termina com a divulga\u00e7\u00e3o do resultado das institui\u00e7\u00f5es selecionadas, que ser\u00e3o conhecidas no dia 24 de mar\u00e7o de 2010. Ap\u00f3s esta data, ter\u00e1 in\u00edcio a segunda etapa, com o processo de forma\u00e7\u00e3o das Redes Cooperativas. O resultado final da chamada p\u00fablica estar\u00e1 dispon\u00edvel a partir do dia 18 de agosto de 2010.<br \/>\n\u00a0<br \/>\nAl\u00e9m do valor do FNDCT, ser\u00e3o disponibilizados recursos n\u00e3o reembols\u00e1veis da Caixa Econ\u00f4mica Federal no valor total de R$ 4,1 milh\u00f5es, destinados \u00e0 avalia\u00e7\u00e3o e divulga\u00e7\u00e3o de resultados dos projetos executados no \u00e2mbito das Redes Cooperativas de Pesquisa, nos temas priorit\u00e1rios definidos.<\/p>\n<p>Departamento de Comunica\u00e7\u00e3o da FINEP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A FINEP em parceria com o Minist\u00e9rio das Cidades destinar\u00e1 R$ 30 milh\u00f5es para apoio a projetos de pesquisa inovadores em saneamento b\u00e1sico e habita\u00e7\u00e3o. Ser\u00e3o R$ 15 milh\u00f5es para cada \u00e1rea, conforme a chamada p\u00fablica j\u00e1 dispon\u00edvel no site da empresa, na se\u00e7\u00e3o Chamadas Abertas. Clique aqui para acessar a chamada p\u00fablica. Os recursos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":{"0":"post-16690","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-inscricao","7":"category-oportunidades","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16690"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16690\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}