{"id":16633,"date":"2009-11-09T00:10:11","date_gmt":"2009-11-09T04:10:11","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16633"},"modified":"2009-11-09T00:10:11","modified_gmt":"2009-11-09T04:10:11","slug":"previsao-do-tempo-e-temperatura-na-regiao-sul-de-09-a-1111","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-e-temperatura-na-regiao-sul-de-09-a-1111\/16633","title":{"rendered":"Previs\u00e3o do tempo e temperatura na Regi\u00e3o Sul de 09 a 11\/11"},"content":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Sul em 09\/11\/2009: No norte do PR: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. No leste do PR e no nordeste de SC: nublado com chuva isolada a qualquer hora. Nas demais \u00e1reas do PR: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva. No leste de SC e no nordeste do RS: inst\u00e1vel com varia\u00e7\u00e3o de nuvens e chuva a qualquer hora. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 26C no sudoeste do RS. Temperatura m\u00ednima: 18C na Serra Geral.\u00a0<br \/>\n10\/11\/2009: No litoral norte de SC e no litoral do PR: nublado com chuva isolada a qualquer hora. No oeste do PR e de SC e no extremo sul do RS: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Nas demais \u00e1reas do RS: sol entre poucas nuvens. Nas demais \u00e1reas do PR e de SC: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva. As temperaturas ficar\u00e3o est\u00e1veis.<\/p>\n<p>Tend\u00eancia: No norte do RS, em SC e no sudoeste do PR: nublado com pancadas de chuva a qualquer hora do dia. Na faixa central do RS: nublado com chuva isolada a qualquer hora. No leste do PR e no nordeste de SC: encoberto com chuva isolada. Nas demais \u00e1reas do PR: sol com varia\u00e7\u00e3o de nuvens e uma pequena possibilidade de pancadas de chuva. Nas demais \u00e1reas do RS: sol com varia\u00e7\u00e3o de nuvens. As temperatura seguir\u00e3o est\u00e1veis.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Sul em 09\/11\/2009: No norte do PR: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. No leste do PR e no nordeste de SC: nublado com chuva isolada a qualquer hora. Nas demais \u00e1reas do PR: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[327],"tags":[],"class_list":["post-16633","post","type-post","status-publish","format-standard","category-clima","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16633"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16633\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}