{"id":166096,"date":"2019-01-18T23:56:52","date_gmt":"2019-01-19T01:56:52","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=166096"},"modified":"2019-01-18T19:58:37","modified_gmt":"2019-01-18T21:58:37","slug":"resumo-novela-teresa-21-01-teresa-procura-fernando-para-se-queixar-de-arthur","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/resumo-novela-teresa-21-01-teresa-procura-fernando-para-se-queixar-de-arthur\/166096","title":{"rendered":"Resumo novela \u201cTeresa\u201d 21\/01: Teresa procura Fernando para se queixar de Arthur"},"content":{"rendered":"<p> <strong><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-153986\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa-sbt-360x300.jpg\" alt=\"\" width=\"360\" height=\"300\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa-sbt-360x300.jpg 360w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa-sbt-224x187.jpg 224w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa-sbt-150x125.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa-sbt.jpg 503w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/>Resumo novela \u201cTeresa\u201d 21\/01 <\/em><\/strong>: no cap\u00edtulo 076(*) da novela, segunda-feira, 21 janeiro, Joana, chorando, diz a Teresa que Roberto vai se casar. Teresa responde que \u00e9 o melhor que ela se case com Heitor, porque assim viver\u00e1 como uma rainha. Joana responde que se deu conta de que, ainda que Heitor a presenteie com mil coisas, nunca poder\u00e1 am\u00e1-lo como ama Roberto. Rubens diz a Esperan\u00e7a que sabe que ela est\u00e1 gr\u00e1vida de um filho seu. Ela ainda tenta negar, mas acaba confessando que realmente a crian\u00e7a \u00e9 de Rubens.<\/p>\n<p>Martin diz a Aurora que Paloma deixou uma carta que o recomenda como tesoureiro da funda\u00e7\u00e3o. Esperan\u00e7a diz a Teresa que Rubens a procurou com interesse em seu filho, mas que isso n\u00e3o o impedir\u00e1 de seguir com sua vida. Teresa diz a Mariano que Nico deve ser muito perigoso. Teresa diz a Tito que a pol\u00edcia est\u00e1 atr\u00e1s dele, assim o melhor seria que ele fosse embora para sempre, pois n\u00e3o ir\u00e1 poder ajud\u00e1-lo. Armando diz a Teresa que, segundo Ramon, ela foi atr\u00e1s de Mariano.<\/p>\n<p>Teresa aceita que o procurou, mas para pedir que a deixasse em paz. Teresa, fingindo-se de ofendida, reclama com Arthur que ele segue duvidando dela, por isso tirou Mariano da funda\u00e7\u00e3o de Paloma. Ela afirma que tem raz\u00f5es para sentir ci\u00fames, porque Paloma a disse que esteve com ele um pouco antes de sofrer o acidente. Luisa escuta quando Arthur diz a Fernando que Teresa j\u00e1 sabe que ele fez amor com Paloma. Teresa, chorando, procura Fernando para se queixar de Arthur.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cTeresa\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>&#8220;Teresa&#8221; \u00e9 uma jovem dominada pela ambi\u00e7\u00e3o, mas n\u00e3o est\u00e1 disposta a trabalhar para melhorar sua condi\u00e7\u00e3o social e opta pelo caminho do engano e da trai\u00e7\u00e3o. Seus pais fizeram um grande sacrif\u00edcio para lhe dar uma vida digna e sem car\u00eancias, mas para ela nada \u00e9 suficiente. Mariano est\u00e1 loucamente apaixonado por ela, a apoia incondicionalmente e est\u00e1 sempre a sua disposi\u00e7\u00e3o. Mas ela, apesar de gostar de Mariano, o v\u00ea apenas como algo de sua propriedade. Sempre que tem oportunidade, deixa o jovem para ir atr\u00e1s de homens com poder e fortuna. Ela s\u00f3 volta a ficar com ele quando sabe que h\u00e1 outras mulheres interessadas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cTeresa\u201d 21\/01 : no cap\u00edtulo 076(*) da novela, segunda-feira, 21 janeiro, Joana, chorando, diz a Teresa que Roberto vai se casar. Teresa responde que \u00e9 o melhor que ela se case com Heitor, porque assim viver\u00e1 como uma rainha. Joana responde que se deu conta de que, ainda que Heitor a presenteie com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":82052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,372,343],"tags":[441],"class_list":["post-166096","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-sbt","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/teresa_resumo_novela_sbt_capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/166096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=166096"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/166096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/82052"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=166096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=166096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=166096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}