{"id":16451,"date":"2009-11-06T14:26:22","date_gmt":"2009-11-06T18:26:22","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16451"},"modified":"2009-11-06T14:26:22","modified_gmt":"2009-11-06T18:26:22","slug":"oleo-de-amendoim-o-amigo-do-coracao","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/oleo-de-amendoim-o-amigo-do-coracao\/16451","title":{"rendered":"\u00d3leo de amendoim: o amigo do cora\u00e7\u00e3o"},"content":{"rendered":"<p>Como diz o ditado &#8220;O h\u00e1bito faz o monge&#8221;, s\u00e3o os pequenos costumes saud\u00e1veis que proporcionam a melhoria na qualidade de vida das pessoas. Trocar, por exemplo, o uso de gorduras pesadas por similares mais leves durante a prepara\u00e7\u00e3o dos alimentos \u00e9 uma maneira de n\u00e3o apenas evitar problemas para a sa\u00fade, mas tamb\u00e9m de contribuir com uma melhor degusta\u00e7\u00e3o dos alimentos.\u00a0Com a crescente preocupa\u00e7\u00e3o das pessoas em se manter a sa\u00fade em dia, sobretudo nas quest\u00f5es nutricionais, e ao mesmo tempo n\u00e3o perder o prazer durante a refei\u00e7\u00e3o, \u00e9 preciso escolher os ingredientes apropriados para que essa receita d\u00ea certo. Um tipo de gordura que pertence \u00e0 escala de ingredientes que unem o \u00fatil ao agrad\u00e1vel \u00e9 o <strong>\u00f3leo de amendoim<\/strong>, que pode ser usado no preparo das mais diversas receitas, preservando o bem-estar do organismo e o sabor dos alimentos.<\/p>\n<p><strong> Reduz o colesterol e previne doen\u00e7as card\u00edacas<\/strong><br \/>\nSabe-se que o colesterol em excesso \u00e9 extremamente prejudicial ao cora\u00e7\u00e3o. Importantes pesquisas t\u00eam demonstrado que o uso do \u00f3leo de amendoim pode diminuir o risco de doen\u00e7as cardiovasculares. Segundo um estudo realizado pela Universidade do Estado da Pensilv\u00e2nia, substituindo-se 50% da gordura derivada de \u00f3leos de soja, milho ou animal, por gorduras provenientes do amendoim, \u00e9 poss\u00edvel reduzir significativamente a produ\u00e7\u00e3o do colesterol ruim no sistema sangu\u00edneo.<\/p>\n<p>Segundo o Dr. Penny Kris Etherton, respons\u00e1vel pelo departamento de nutri\u00e7\u00e3o da Universidade, isto ocorre porque o \u00f3leo de amendoim \u00e9 combinado de altos \u00edndices de gordura monoinsaturada &#8211; que aumenta o colesterol sadio &#8211; e baixos \u00edndices de gordura saturada &#8211; encontradas na gordura animal, ricas em colesterol ruim.<\/p>\n<p>De acordo com a nutricionista Gislaine Arantes Sales Anvanello, este produto n\u00e3o cont\u00e9m gorduras que entopem o mioc\u00e1rdio, como em outros \u00f3leos. &#8220;O consumo do \u00f3leo de amendoim \u00e9 uma excelente forma de se combater o principal vil\u00e3o do cora\u00e7\u00e3o, o colesterol alto, evitando, assim, doen\u00e7as cardiovasculares&#8221;, afirma.<\/p>\n<p>Importante fonte de energia e vitaminas<\/p>\n<p>O \u00f3leo de amendoim tamb\u00e9m se destaca pela rica base de nutrientes que possui. Composto pelos nutrientes E, K e \u00d4mega, \u00e9 um oleaginoso com alto valor energ\u00e9tico.<\/p>\n<p>A vitamina E, por exemplo, \u00e9 um poderoso antioxidante capaz de defender o organismo das agress\u00f5es externas e ajudar na absor\u00e7\u00e3o da vitamina A. J\u00e1 o \u00d4mega 6, um \u00e1cido gordo poliinsaturado, \u00e9 essencial na estrutura\u00e7\u00e3o das membranas celulares do organismo, no sistema de coagula\u00e7\u00e3o (prevenindo as hemorragias) e na prote\u00e7\u00e3o da pele.<\/p>\n<p>A nutricionista Gislaine Anvanello menciona que uma das principais caracter\u00edsticas do \u00f3leo de amendoim \u00e9 o alt\u00edssimo teor de vitamina E. &#8220;Por causa desta vitamina, ele \u00e9 respons\u00e1vel pela elimina\u00e7\u00e3o de radicais livres que podem danificar c\u00e9lulas sadias no organismo&#8221;, diz.<\/p>\n<p>Segundo a especialista em alimentos e dietas naturais Silvia Amaral, o \u00f3leo de amendoim tem cerca de 28% de prote\u00edna em sua composi\u00e7\u00e3o e por isso sua carga energ\u00e9tica \u00e9 t\u00e3o intensa. &#8220;Este \u00f3leo \u00e9 \u00fatil no combate e preven\u00e7\u00e3o a doen\u00e7as de pele, para o metabolismo e \u00e9 usado tamb\u00e9m contra infec\u00e7\u00f5es&#8221;, afirma.<\/p>\n<p>N\u00e3o interfere no sabor natural dos alimentos<\/p>\n<p>Diferente de outros, o uso do \u00f3leo de amendoim n\u00e3o interfere no sabor dos alimentos. O preparo das refei\u00e7\u00f5es pode ser feito sem que o \u00f3leo absorva o sabor da comida e o transfira para outros alimentos, mantendo, desta forma, o sabor natural dos ingredientes. Outro fator interessante \u00e9 que o \u00f3leo possui um alto ponto de fuma\u00e7a, ou smoke point. O que significa que a sua temperatura se mant\u00e9m alta por mais tempo, proporcionando economia para o consumidor. O uso desse composto \u00e9 ideal para cozinhar, fritar, temperar saladas e tamb\u00e9m como margarina.<\/p>\n<p>Consumir \u00f3leo de amendoim pode ser uma op\u00e7\u00e3o mais saud\u00e1vel, dur\u00e1vel e econ\u00f4mica comparada aos outros tipos. Mas, a especialista em alimentos e dietas naturais, Silvia Amaral, alerta que o produto n\u00e3o pode ser hidrogenado. &#8220;Pois perde as propriedades e come\u00e7a a fazer mal&#8221;, conclui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como diz o ditado &#8220;O h\u00e1bito faz o monge&#8221;, s\u00e3o os pequenos costumes saud\u00e1veis que proporcionam a melhoria na qualidade de vida das pessoas. Trocar, por exemplo, o uso de gorduras pesadas por similares mais leves durante a prepara\u00e7\u00e3o dos alimentos \u00e9 uma maneira de n\u00e3o apenas evitar problemas para a sa\u00fade, mas tamb\u00e9m de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-16451","post","type-post","status-publish","format-standard","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16451"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16451\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}