{"id":16446,"date":"2009-11-06T14:16:09","date_gmt":"2009-11-06T18:16:09","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16446"},"modified":"2009-11-06T14:16:09","modified_gmt":"2009-11-06T18:16:09","slug":"climatempo-grande-massa-de-ar-quente-cobre-o-brasil","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/climatempo-grande-massa-de-ar-quente-cobre-o-brasil\/16446","title":{"rendered":"Climatempo &#8211; grande massa de ar quente cobre o Brasil"},"content":{"rendered":"<p><strong><span style=\"font-weight: normal;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10683\" title=\"climatempo\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/climatempo.jpg\" alt=\"climatempo\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/climatempo.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/climatempo-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/span>Climatempo Meteorologia<\/strong> &#8211; uma grande massa de ar quente cobre o Brasil e deixa as temperaturas elevadas. No Sul, uma frente fria est\u00e1 bloqueada no RS e novos temporais podem ocorrer ao longo desta sexta-feira. No Sudeste, a instabilidade diminui em parte da Regi\u00e3o com a entrada de ar seco. O c\u00e9u est\u00e1 com poucas nuvens no RJ, no ES e no centro-leste mineiro. Climatempo Meteorologia informa que a massa de ar quente que predomina sobre quase todo o Sudeste do Brasil deixa o tempo aberto, com sol forte em todo o Rio de Janeiro. Esta massa de ar bloqueia a passagem das frentes frias que se aproximam no Rio Grande do Sul desviando estes sistemas para o oceano.<\/p>\n<p>Segundo a Climatempo Meteorologia, com a persist\u00eancia do ar quente a temperatura durante esta semana esteve elevada e o calor foi forte no Sudeste. No Rio de Janeiro al\u00e9m do ar quente temos tamb\u00e9m a influ\u00eancia da baixa umidade que dificulta a forma\u00e7\u00e3o de nebulosidade, com poucas nuvens temos mais horas de sol, o que for\u00e7a a temperatura a disparar. Nesta quinta-feira, dia 05 de novembro, a m\u00e1xima registrada pelo Instituto Nacional de Meteorologia \u2013 INMET foi de 40 graus e 2 d\u00e9cimos na Pra\u00e7a Mau\u00e1, centro da Cidade. Esta \u00e9 a maior temperatura j\u00e1 registrada neste ano de 2009. A esta\u00e7\u00e3o da Pra\u00e7a Mau\u00e1 opera desde 2002 e, em novembro de 2004, a m\u00e1xima registrada na esta\u00e7\u00e3o foi de 40 graus e 5 d\u00e9cimos. Em novembro de 2003, o calor tamb\u00e9m foi forte na esta\u00e7\u00e3o, com m\u00e1xima de 40 graus. A sexta-feira tamb\u00e9m foi quente na cidade do Rio. \u00c0s 11 horas da manh\u00e3 a temperatura j\u00e1 era de 36 graus na Zona Oeste e 35 graus na Zona Norte.<\/p>\n<p>Climatempo Meteorologia informa que, com o predom\u00ednio do ar quente a temperatura ainda fica alta e o calor ainda \u00e9 intenso neste fim de semana diminuindo s\u00f3 a partir de segunda-feira.<\/p>\n<p>Nas demais \u00e1reas da Regi\u00e3o e no Centro-Oeste, o ar quente e \u00famido forma nuvens que deixam o tempo inst\u00e1vel. No Norte, as nuvens mais pesadas cobrem o AC, o AM e RO.<\/p>\n<p>Sobre o Grupo Climatempo &#8211; O Grupo Climatempo \u00e9 a maior empresa privada de meteorologia do pa\u00eds. Uma holding formada pela Climatempo Consultoria, Ag\u00eancia Climatempo, a TV Climatempo e a CLIMANET (Internet, servi\u00e7os de tecnologia e inform\u00e1tica). Atualmente, o Grupo Climatempo fornece conte\u00fado para os principais portais do pa\u00eds, mais de 50 retransmissoras de televis\u00e3o do Brasil, r\u00e1dios e tem cerca de mil clientes. Os dois principais segmentos atendidos s\u00e3o o de agroneg\u00f3cios e meios de comunica\u00e7\u00e3o. Al\u00e9m destes, fornece conte\u00fado meteorol\u00f3gico estrat\u00e9gico para produtoras, a ind\u00fastria eletroeletr\u00f4nica e t\u00eaxtil, com\u00e9rcio, moda e turismo, constru\u00e7\u00e3o civil, setor de energia, entre outros setores.<\/p>\n<p>O Grupo \u00e9 presidido pelo meteorologista Carlos Magno, um dos primeiros comunicadores da profiss\u00e3o no Pa\u00eds, com mais de 23 anos de carreira, que ajudou a mudar a cultura que o brasileiro tinha sobre a meteorologia. O Grupo Climatempo conta ainda com Ana L\u00facia Frony vice-presidente, Renato Urbinder, s\u00f3cio-diretor (Diretor de Neg\u00f3cios e Projetos Especiais), e os diretores executivos Gilca Palma (Climatempo Meteorologia), Andr\u00e9 Madeira (Ag\u00eancia Climatempo) e o jornalista Paulo Polli (TV Climatempo) no Conselho Consultivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Climatempo Meteorologia &#8211; uma grande massa de ar quente cobre o Brasil e deixa as temperaturas elevadas. No Sul, uma frente fria est\u00e1 bloqueada no RS e novos temporais podem ocorrer ao longo desta sexta-feira. No Sudeste, a instabilidade diminui em parte da Regi\u00e3o com a entrada de ar seco. O c\u00e9u est\u00e1 com poucas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327,376],"tags":[],"class_list":{"0":"post-16446","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-clima","8":"category-clima-brasil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16446"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16446\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}