{"id":164334,"date":"2019-01-03T14:02:58","date_gmt":"2019-01-03T16:02:58","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=164334"},"modified":"2019-01-03T19:38:12","modified_gmt":"2019-01-03T21:38:12","slug":"resumo-novela-as-aventuras-de-poliana-04-01-bento-e-jefferson-sao-escolhidos-para-estudar-na-ruth-goulart","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/resumo-novela-as-aventuras-de-poliana-04-01-bento-e-jefferson-sao-escolhidos-para-estudar-na-ruth-goulart\/164334","title":{"rendered":"Resumo novela \u201cAs Aventuras de Poliana\u201d 04\/01: Raquel grita desesperadamente"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-148662\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-novela-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-novela-400x267.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-novela-250x167.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-novela-150x100.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-novela.jpg 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Resumo novela \u201cAs Aventuras de Poliana\u201d 04\/01 <\/em><\/strong>: no cap\u00edtulo 168(*) da novela, resumo de sexta-feira, 04 de janeiro, D\u00e9bora diz para Claudia e Gl\u00f3ria que Lu\u00edsa \u00e9 paranoica. Sophie \u00e9 assaltada. Mirela pensa em Luca Tuber e fica confusa. Rato amea\u00e7a Jefferson para que ele leve os celulares roubados para que sejam desbloqueados. O comit\u00ea do La\u00e7o Azul se re\u00fane para decidir quem vai conseguir as bolsas de estudo. Bento \u00e9 um dos escolhidos e Poliana vibra de alegria. Raquel acorda com o besouro de Lorena em cima dela e grita desesperadamente. Kessya encontra uma sacola com celulares roubados em casa. Sophie liga para o celular do telefone da escola e Kessya atende sem saber. Depois, ela confronta Jefferson sobre os celulares roubados. Guilherme aconselha Ciro sobre como lidar com as malcria\u00e7\u00f5es de Filipa. Jefferson diz para Kessya que dar\u00e1 um jeito nessa confus\u00e3o.<\/p>\n<p>Poliana faz um cartaz especial para receber Bento na escola, e Jo\u00e3o fica chateado. Kessya devolve o celular para Sophie, dizendo que o encontrou na comunidade. Algumas crian\u00e7as zombam do fato de Bento andar de cadeira de rodas, e Jo\u00e3o fica furioso. Gleyce \u00e9 informada de que Jefferson foi selecionado para estudar na Ruth Goulart. Joana decide provocar ci\u00fames em S\u00e9rgio dando aten\u00e7\u00e3o para Waldisney. Euclides, o besouro de Lorena, some. \u00c9ric pisa no inseto e Lorena fica arrasada. Durval beija Claudia, e Lorena flagra os dois.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cAs Aventuras de Poliana\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Poliana \u00e9 uma menina extrovertida e de bom cora\u00e7\u00e3o que viajava o Brasil com seus pais, Lorenzo e Alice, no grupo circense Trupe Vagalume. Aos onze anos a garota v\u00ea seu mundo desabar quando seus pais falecem e ela tem que ir morar em S\u00e3o Paulo com sua tia Lu\u00edsa, uma mulher rica e severa, a qual ela n\u00e3o conhecia e que n\u00e3o queria cuidar dela, embora sinta que \u00e9 sua obriga\u00e7\u00e3o pela alma de sua irm\u00e3. Apesar do jeito da rigidez da tia, Poliana decide ter uma vis\u00e3o positiva e inabal\u00e1vel da vida, mesmo nos momentos de dificuldade, tentando levar um pouco de felicidade para a vida de cada um dos seus novos amigos e vizinhos, como o Sr. Pendleton, um homem rico e infeliz por nunca ter tido filhos. Ela vai estudar no col\u00e9gio de Ruth, uma diretora de bom cora\u00e7\u00e3o que a ajuda a se adaptar, mas tem que lidar com as vilanias de Mirela, garota mais velha que n\u00e3o aceita perder a popularidade para uma novata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cAs Aventuras de Poliana\u201d 04\/01 : no cap\u00edtulo 168(*) da novela, resumo de sexta-feira, 04 de janeiro, D\u00e9bora diz para Claudia e Gl\u00f3ria que Lu\u00edsa \u00e9 paranoica. Sophie \u00e9 assaltada. Mirela pensa em Luca Tuber e fica confusa. Rato amea\u00e7a Jefferson para que ele leve os celulares roubados para que sejam desbloqueados. O [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":148663,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[477,379,372,343],"tags":[441],"class_list":["post-164334","post","type-post","status-publish","format-standard","has-post-thumbnail","category-as-aventuras-de-poliana","category-novelas","category-sbt","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/as-aventuras-de-poliana-sbt.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/164334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=164334"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/164334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148663"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=164334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=164334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=164334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}