{"id":16385,"date":"2009-11-05T21:10:53","date_gmt":"2009-11-06T01:10:53","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16385"},"modified":"2009-11-05T21:10:53","modified_gmt":"2009-11-06T01:10:53","slug":"a-bruxa-esta-solta-em-pela-estrada-afora","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/a-bruxa-esta-solta-em-pela-estrada-afora\/16385","title":{"rendered":"A bruxa est\u00e1 solta em Pela Estrada Afora"},"content":{"rendered":"<p>A bruxa anda solta na edi\u00e7\u00e3o deste s\u00e1bado (7\/11) do programa <strong>Pela Estrada Afora<\/strong>, que a <strong>TV Cultura<\/strong> apresenta \u00e0s 11h30. Isso porque a famosa personagem dos contos de fadas circula pela cidade grande em busca da Branca de Neve e acaba causando muitos transtornos e confus\u00e3o.<\/p>\n<p>Desta vez, o escritor Lobato solta a imagina\u00e7\u00e3o para transmitir \u00e0s crian\u00e7as, em uma hist\u00f3ria leve e informativa, no\u00e7\u00f5es importantes de tr\u00e2nsito, como atravessar corretamente na faixa de pedestres e obedecer \u00e0 sinaliza\u00e7\u00e3o.<\/p>\n<p>No conto, a bruxa desembarca no mundo real atr\u00e1s da Branca de Neve e se depara com uma realidade totalmente diferente da sua: muitos carros, barulho e pessoas por todos os lados. No meio do caminho, ela encontra os meninos Rafa e Pedro e se surpreende ao perceber que eles n\u00e3o t\u00eam medo algum dela.<\/p>\n<p>Irritada, a bruxa imp\u00f5e que eles a ajudem a encontrar a Branca de Neve e a levem de volta para o seu mundo. Os garotos enganam a pobre malvada dizendo n\u00e3o saber onde est\u00e1 a princesa e a levam at\u00e9 uma locadora de filmes. No percurso, eles ensinam a feiticeira a ser uma pedestre respons\u00e1vel.<\/p>\n<p>Produzido em parceria com o Denatran (Departamento Nacional de Tr\u00e2nsito), Pela Estrada Afora aborda quest\u00f5es de tr\u00e2nsito de maneira did\u00e1tica e bem humorada, misturando personagens de f\u00e1bulas e situa\u00e7\u00f5es reais do cotidiano. Os epis\u00f3dios envolvem o universo das crian\u00e7as e transmitem informa\u00e7\u00f5es para motoristas e pedestres, com dicas de preven\u00e7\u00e3o de acidentes, de como andar e agir corretamente nas ruas, aproveitar melhor os benef\u00edcios dos transportes coletivos, entre outros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A bruxa anda solta na edi\u00e7\u00e3o deste s\u00e1bado (7\/11) do programa Pela Estrada Afora, que a TV Cultura apresenta \u00e0s 11h30. Isso porque a famosa personagem dos contos de fadas circula pela cidade grande em busca da Branca de Neve e acaba causando muitos transtornos e confus\u00e3o. Desta vez, o escritor Lobato solta a imagina\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[343],"tags":[],"class_list":{"0":"post-16385","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-televisao","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16385"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16385\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}