{"id":16378,"date":"2009-11-05T21:03:30","date_gmt":"2009-11-06T01:03:30","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16378"},"modified":"2009-11-05T21:03:30","modified_gmt":"2009-11-06T01:03:30","slug":"desejo-por-doces-pode-causar-hiperinsulina-na-tpm","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/desejo-por-doces-pode-causar-hiperinsulina-na-tpm\/16378","title":{"rendered":"Desejo por doces pode causar hiperinsulina na TPM"},"content":{"rendered":"<p>Que mulher nunca passou pela enorme vontade de comer doces numa situa\u00e7\u00e3o de <strong>nervosismo<\/strong> na \u00e9poca da <strong>TPM<\/strong>? Mesmo consciente de que pode ser prejudicial \u00e0 sa\u00fade, ningu\u00e9m resiste a um bom chocolate, bolos e tortas para acalmar os \u00e2nimos. Mas como administrar a culpa?<\/p>\n<p>A busca por a\u00e7\u00facar \u00e9 constante e em muitos casos ocorrem altera\u00e7\u00f5es psicol\u00f3gicas consider\u00e1veis, tais como irritabilidade e hostilidade em rela\u00e7\u00e3o \u00e0s pessoas mais pr\u00f3ximas. A principal causa na mudan\u00e7a de humor est\u00e1 associada \u00e0 equil\u00edbrio dos n\u00edveis de serotonina no organismo. O d\u00e9ficit deste componente gera o mau humor, al\u00e9m da vontade de comer doces e certos tipos de carboidratos, tais como p\u00e3es e massas.<\/p>\n<p>Devido a este fato, a ingest\u00e3o destes alimentos cal\u00f3ricos em grande quantidade aparece com mais freq\u00fc\u00eancia, acarretando s\u00e9rios problemas, inclusive cardiovasculares.<br \/>\nA sa\u00fade da mulher n\u00e3o \u00e9 s\u00f3 mantida atrav\u00e9s de horm\u00f4nios, mas por fatores heredit\u00e1rios, estilo de vida, freq\u00fc\u00eancia e intensidade de suas atividades f\u00edsicas. Estabelecer bons h\u00e1bitos alimentares logo cedo pode fazer a diferen\u00e7a.<\/p>\n<p>Para amenizar esses sintomas, recomenda-se que sejam feitas refei\u00e7\u00f5es pequenas e freq\u00fcentes, \u00e0 base de frutas &#8211; como ma\u00e7\u00e3s, ameixas, bananas, cerejas e damasco seco. Um bom exerc\u00edcio sempre facilitar\u00e1 a redu\u00e7\u00e3o da hiperinsulinemia no corpo, que nada mais \u00e9 que o aumento da secre\u00e7\u00e3o de insulina pelo organismo.<\/p>\n<p>*Dra. Sylvana Braga (www.sylvanabraga.com.br) \u00e9 m\u00e9dica ortomolecular, nutrologista, reumatologista e fisiatra com cl\u00ednica no Rio de Janeiro e em S\u00e3o Paulo. \u00c9 autora do livro \u201cDieta Ortomolecular \u2013 O Segredo de Rejuvenescer em Total Harmonia\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que mulher nunca passou pela enorme vontade de comer doces numa situa\u00e7\u00e3o de nervosismo na \u00e9poca da TPM? Mesmo consciente de que pode ser prejudicial \u00e0 sa\u00fade, ningu\u00e9m resiste a um bom chocolate, bolos e tortas para acalmar os \u00e2nimos. Mas como administrar a culpa? A busca por a\u00e7\u00facar \u00e9 constante e em muitos casos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-16378","post","type-post","status-publish","format-standard","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16378"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16378\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}