{"id":16280,"date":"2009-11-05T11:39:45","date_gmt":"2009-11-05T15:39:45","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16280"},"modified":"2009-11-05T11:49:55","modified_gmt":"2009-11-05T15:49:55","slug":"receita-federal-abre-segunda-feira-911-consulta-ao-6%c2%ba-lote-irpf-20082009","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/receita-federal-abre-segunda-feira-911-consulta-ao-6%c2%ba-lote-irpf-20082009\/16280","title":{"rendered":"Receita Federal abre segunda-feira (9\/11) consulta ao 6\u00ba Lote IRPF (2008\/2009)"},"content":{"rendered":"<p>A <strong>Receita Federal<\/strong> do Brasil libera \u00e0s 9 horas da pr\u00f3xima segunda-feira (9\/11), consulta ao 6\u00ba lote de restitui\u00e7\u00f5es multi-exerc\u00edcio do Imposto de Renda da Pessoa F\u00edsica (ano calend\u00e1rio 2009 e 2008).\u00a0No dia 16 de novembro de 2009 ser\u00e3o creditadas, simultaneamente, as restitui\u00e7\u00f5es da Receita Federal referentes aos exerc\u00edcios de 2009 e 2008 para um total de 2.138.113 contribuintes, totalizando R$ 2 bilh\u00f5es de reais.\u00a0<\/p>\n<p>Para o exerc\u00edcio de 2009, ser\u00e3o creditadas restitui\u00e7\u00f5es para 2.125.588 contribuintes, totalizando R$ 1.967.796.186,84, acrescidos de 5,39% (Selic de maio a novembro\/2009).\u00a0<\/p>\n<p>J\u00e1 para o lote residual da Receita Federal de 2008, as restitui\u00e7\u00f5es totalizam R$ 32.203.813,16, com corre\u00e7\u00e3o de 17,46% (Selic de maio de 2008 a novembro de 2009). Foram contemplados 12.525 contribuintes.\u00a0<\/p>\n<p>Para saber se ter\u00e1 a restitui\u00e7\u00e3o Receita Federal liberada nesse lote, o contribuinte poder\u00e1 acessar a p\u00e1gina da Receita na Internet (<a href=\"http:\/\/www.receita.fazenda.gov.br\" target=\"_blank\">www.receita.fazenda.gov.br<\/a>) ou ligar para o Receitafone 146, informando o n\u00famero do CPF.\u00a0<\/p>\n<p>Caso o valor n\u00e3o seja creditado, o contribuinte dever\u00e1 se dirigir ou ligar para uma das ag\u00eancias do Banco do Brasil ou para o \u2018BB responde\u2019 4004-0001 (capitais) ou 0800-729-0001 (demais localidades), para agendar o cr\u00e9dito em conta-corrente ou poupan\u00e7a em seu nome, em qualquer banco.\u00a0<\/p>\n<p>A restitui\u00e7\u00e3o Receita Federal ficar\u00e1 dispon\u00edvel no banco por um ano. Se o contribuinte n\u00e3o fizer o resgate nesse prazo, dever\u00e1 requer\u00ea-la mediante Formul\u00e1rio Eletr\u00f4nico (Pedido de Pagamento de Restitui\u00e7\u00e3o), dispon\u00edvel na p\u00e1gina da Receita Federal na Internet.\u00a0<\/p>\n<p>A consulta ao extrato de processamento da declara\u00e7\u00e3o, tamb\u00e9m, poder\u00e1 ser feita na Internet (<a href=\"http:\/\/www.receita.fazenda.gov.br\" target=\"_blank\">www.receita.fazenda.gov.br<\/a>).<\/p>\n<p>Fonte: Secretaria da Receita Federal do Brasil &#8211; SRFB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal do Brasil libera \u00e0s 9 horas da pr\u00f3xima segunda-feira (9\/11), consulta ao 6\u00ba lote de restitui\u00e7\u00f5es multi-exerc\u00edcio do Imposto de Renda da Pessoa F\u00edsica (ano calend\u00e1rio 2009 e 2008).\u00a0No dia 16 de novembro de 2009 ser\u00e3o creditadas, simultaneamente, as restitui\u00e7\u00f5es da Receita Federal referentes aos exerc\u00edcios de 2009 e 2008 para um [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":{"0":"post-16280","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-economia","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16280"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16280\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}