{"id":161569,"date":"2018-12-11T13:24:24","date_gmt":"2018-12-11T15:24:24","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=161569"},"modified":"2018-12-18T16:53:05","modified_gmt":"2018-12-18T18:53:05","slug":"novela-malhacao-marcio-se-aventura-na-cozinha","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-malhacao-marcio-se-aventura-na-cozinha\/161569","title":{"rendered":"Novela \u201cMalha\u00e7\u00e3o\u201d: M\u00e1rcio se aventura na cozinha"},"content":{"rendered":"<p> <strong><em>Novela \u201cMalha\u00e7\u00e3o\u201d Vidas Brasileiras:<\/em><\/strong> M\u00e1rcio (Andr\u00e9 Luiz Frambach) levou t\u00e3o a s\u00e9rio as aulas de Ros\u00e1lia (Guta Stresser) que agora anda se aventurando na cozinha. O adolescente prepara uma receita que deixa todo mundo com \u00e1gua na boca. E o nome do doce j\u00e1 tem nome: Rafarelo. &#8220;Fica a dica de presente comest\u00edvel pros seus amigos tamb\u00e9m, M\u00e1rcio! Nossa, o cheiro t\u00e1 maravilhoso&#8221;, elogia Maria Alice (Alice Milagres), antes mesmo de experimentar. &#8220;\u00c9&#8230; Esse doce a\u00ed que c\u00ea inventou \u00e9 bem gostoso mesmo, d\u00e1 pra comer&#8221;, brinca Alex (Daniel Rangel).<\/p>\n<p>P\u00e9rola, Maria Alice e Alex est\u00e3o por perto, prontos para atacar o doce, mas M\u00e1rcio avisa. &#8220;Segura a onda, galera, que essa leva de Rafarelo j\u00e1 \u00e9 pra vender amanh\u00e3 no col\u00e9gio&#8221;, diz. P\u00e9rola faz drama, diz que tem bastante, e Alex incentiva o amigo a dividir a cria\u00e7\u00e3o gastron\u00f4mica. &#8220;Pois \u00e9, deixa de ser muquirana.&#8221;, diz. &#8220;OK, eu vou liberar um pedacinho pra cada um&#8221;, diz o adolescente. Depois de ceder e ganhar elogio da namorada, os amigos ainda pedem mais um peda\u00e7o, mas M\u00e1rcio recusa. &#8220;N\u00e3o, chega. Assim voc\u00eas v\u00e3o acabar me levando \u00e0 fal\u00eancia! Amigos, amigos, neg\u00f3cios \u00e0 parte.&#8221;<\/p>\n<p>\u201cMalha\u00e7\u00e3o\u201d Vidas Brasileiras \u00e9 a vig\u00e9sima sexta temporada da soap opera brasileira \u201cMalha\u00e7\u00e3o\u201d, produzida pela Rede Globo e exibida desde 7 de mar\u00e7o de 2018. Escrita por Patr\u00edcia Moretzsohn, com colabora\u00e7\u00e3o de Renata Dias Gomes, Chico Soares, Laura Rissin e Ricardo Tiezzi, e supervis\u00e3o de texto de Daniel Ortiz. \u00c9 dirigida por Thiago Teitelroit, Giovanna Machline, Nath\u00e1lia Warth, Matheus Malafaia, Mayara Aguiar e Caetano Caruso, al\u00e9m de possuir dire\u00e7\u00e3o geral e art\u00edstica de Nat\u00e1lia Grimberg. A temporada se passa no Rio de Janeiro e \u00e9 baseada na telenovela canadense 30 vies de Fabienne Larouche, que foi indicada quatro vezes ao Emmy Internacional.<\/p>\n<p>Conta com Camila Morgado, Carmo Dalla Vecchia, Felipe Rocha, Daniel Rangel, Alice Milagres, Rayssa Bratillieri, Jeniffer Oliveira e Tom Karabachian nos pap\u00e9is principais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cMalha\u00e7\u00e3o\u201d Vidas Brasileiras: M\u00e1rcio (Andr\u00e9 Luiz Frambach) levou t\u00e3o a s\u00e9rio as aulas de Ros\u00e1lia (Guta Stresser) que agora anda se aventurando na cozinha. O adolescente prepara uma receita que deixa todo mundo com \u00e1gua na boca. E o nome do doce j\u00e1 tem nome: Rafarelo. &#8220;Fica a dica de presente comest\u00edvel pros seus [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":148688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[447,379,375,343],"tags":[523],"class_list":["post-161569","post","type-post","status-publish","format-standard","has-post-thumbnail","category-malhacao","category-novelas","category-rede-globo","category-televisao","tag-variedades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/malhacao-6.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/161569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=161569"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/161569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148688"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=161569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=161569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=161569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}