{"id":16093,"date":"2009-11-03T19:07:11","date_gmt":"2009-11-03T23:07:11","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16093"},"modified":"2009-11-03T19:07:11","modified_gmt":"2009-11-03T23:07:11","slug":"amarula-cream-e-tambem-renomado-por-seus-projetos-sustentaveis","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/amarula-cream-e-tambem-renomado-por-seus-projetos-sustentaveis\/16093","title":{"rendered":"Amarula Cream \u00e9 tamb\u00e9m renomado por seus projetos sustent\u00e1veis"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/amarula.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-16094\" title=\"amarula\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/amarula-249x187.jpg\" alt=\"amarula\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amarula-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Nas plan\u00edcies subequatoriais da \u00c1frica existe uma fruta t\u00edpica da regi\u00e3o que n\u00e3o pode ser cultivada pelo homem, a marula. Esse fruto nasce na \u00c1rvore de Marula, tamb\u00e9m conhecida como a &#8220;\u00c1rvore do Elefante&#8221; ou a &#8220;\u00c1rvore do Casamento&#8221;. Envolto a muitos mitos, a fruta \u00e9 o ingrediente primordial do licor Amarula Cream.<\/p>\n<p>Desde 1989 no mercado de bebidas da \u00c1frica do Sul, o Amarula Cream, produzido pelo grupo Distell, j\u00e1 conquistou 150 pa\u00edses com um pouco da ex\u00f3tica fruta africana. O sabor da marula agrada a todos na \u00c1frica e ao resto do mundo atrav\u00e9s do Amarula Cream.<\/p>\n<p>No reino animal, a fruta rica em vitamina C, e com a semente cheia de \u00f3leo natural atrai os elefantes que chegam sozinhos ou em manadas para sacudir as \u00e1rvores at\u00e9 que as frutas caiam ao ch\u00e3o. Uma vez fora do p\u00e9, ela come\u00e7a a fermentar proporcionando um sabor adocicado e levemente alco\u00f3lico. Os elefantes s\u00e3o os principais consumidores do fruto, mas outros animais da savana tamb\u00e9m fazem de tudo pela marula.<\/p>\n<p>Entre os residentes a disputa \u00e9 para casar debaixo da \u00c1rvore de Marula. Acredita-se que essa tenha propriedades afrodis\u00edacas e quem casar-se sob a \u00e1rvore ter\u00e1 felicidade eterna. A copa da \u00e1rvore ser f\u00eamea ou macho determina o sexo do filho do casal, e contribui na cura de doen\u00e7as.<\/p>\n<p>Al\u00e9m de proporcionar um saboroso prazer com o Amarula Cream, marca l\u00edder do mercado no segmento, a bebida tamb\u00e9m est\u00e1 associada a projetos de desenvolvimento econ\u00f4mico. Cerca de um milh\u00e3o e meio de reais s\u00e3o destinados todo ano para a economia local dos residentes que dependem da marula para sobreviver.<\/p>\n<p>Por sua vez os elefantes s\u00e3o beneficiados atrav\u00e9s de a\u00e7\u00f5es de incentivo com o Programa Amarula de Pesquisa sobre o Elefante Africano. N\u00e3o \u00e9 \u00e0 toa que o elefante \u00e9 o s\u00edmbolo da bebida e recebe um cuidado todo especial pela marca.<\/p>\n<p>Eleito por tr\u00eas vezes consecutivas o melhor licor do mundo pela &#8220;The International Wine &amp; Spirit Competition&#8221;, em 2006, 2007 e 2008, o Amarula Cream \u00e9 exemplo de qualidade, sabor, preserva\u00e7\u00e3o ambiental e respeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nas plan\u00edcies subequatoriais da \u00c1frica existe uma fruta t\u00edpica da regi\u00e3o que n\u00e3o pode ser cultivada pelo homem, a marula. Esse fruto nasce na \u00c1rvore de Marula, tamb\u00e9m conhecida como a &#8220;\u00c1rvore do Elefante&#8221; ou a &#8220;\u00c1rvore do Casamento&#8221;. Envolto a muitos mitos, a fruta \u00e9 o ingrediente primordial do licor Amarula Cream. Desde 1989 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-16093","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16093"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16093\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}