{"id":16012,"date":"2009-11-03T16:07:47","date_gmt":"2009-11-03T20:07:47","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16012"},"modified":"2009-11-03T16:07:47","modified_gmt":"2009-11-03T20:07:47","slug":"nova-tecnica-e-esperanca-para-quem-sofre-de-dores-musculares","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/nova-tecnica-e-esperanca-para-quem-sofre-de-dores-musculares\/16012","title":{"rendered":"Nova t\u00e9cnica \u00e9 esperan\u00e7a para quem sofre de dores musculares"},"content":{"rendered":"<p>Uma nova t\u00e9cnica norueguesa de combate \u00e0 dor e que proporciona bem-estar acaba de chegar ao Brasil, exclusivamente em Belo Horizonte. Desenvolvida por m\u00e9dicos e fisioterapeutas, o <strong>Redcord<\/strong> promete <strong>aliviar dores<\/strong>, prevenir <strong>les\u00f5es musculares<\/strong>, melhorar a coordena\u00e7\u00e3o motora e potencializar treinamentos f\u00edsicos. &#8220;Estudos cient\u00edficos de universidades da Europa e EUA mostraram que dor, uso excessivo ou desuso de alguns m\u00fasculos geram sua inibi\u00e7\u00e3o, que normalmente resultam em restri\u00e7\u00f5es de movimento e desempenho de m\u00e1 qualidade, podendo gerar les\u00f5es&#8221;, afirma a precursora da t\u00e9cnica no Brasil, a professora e instrutora mineira Val\u00e9ria Bhering, que far\u00e1 o lan\u00e7amento oficial em seu est\u00fadio, no Lourdes.<\/p>\n<p>A partir deste princ\u00edpio, foram desenvolvidos exerc\u00edcios com o uso da suspens\u00e3o de determinados membros ou do corpo inteiro, atrav\u00e9s de cordas vermelhas (red cords), para estimular a atividade neuromuscular e restabelecendo a for\u00e7a e o equil\u00edbrio do indiv\u00edduo.<\/p>\n<p>O atendimento \u00e9 individualizado e focado na causa, aliviando os sintomas. O primeiro passo \u00e9 a identifica\u00e7\u00e3o dos Weak links (elos fracos) que est\u00e3o ineficientes e por isso n\u00e3o exercem seu papel, o que ocorre ent\u00e3o \u00e9 uma sobrecarga de outros m\u00fasculos ao serem utilizados para a fun\u00e7\u00e3o determinada.<\/p>\n<p>A m\u00e1 interpreta\u00e7\u00e3o do c\u00e9rebro em rela\u00e7\u00e3o \u00e0 atua\u00e7\u00e3o de cada m\u00fasculo gera &#8220;vias alternativas&#8221; e, como conseq\u00fc\u00eancia, causa dor, fadiga e desordens nos movimentos. &#8220;Com a identifica\u00e7\u00e3o desses elos fracos, os fisioterapeutas empregam o pr\u00f3prio peso corporal do indiv\u00edduo nas atividades propostas. Desenvolvida a partir de um abrangente conhecimento em medicina f\u00edsica e neuroci\u00eancia, a t\u00e9cnica \u00e9 capaz de estimular a intera\u00e7\u00e3o entre o c\u00e9rebro e os receptores neuromusculares, possibilitando a ativa\u00e7\u00e3o das fibras adormecidas&#8221;, explica Val\u00e9ria.<\/p>\n<p>Uma das principais vantagens da nova metodologia em rela\u00e7\u00e3o a fisioterapias e tratamentos convencionais s\u00e3o resultados em curto prazo. &#8220;Dependendo do caso, em poucas sess\u00f5es pode ser registrada melhora significativa, tanto em atletas de elite quanto em pacientes com dor cr\u00f4nica ou aguda. Outro ponto positivo \u00e9 que os exerc\u00edcios s\u00e3o sempre livres de dor e sobrecarga podendo ser realizados em pessoas de qualquer idade&#8221;, ressalta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma nova t\u00e9cnica norueguesa de combate \u00e0 dor e que proporciona bem-estar acaba de chegar ao Brasil, exclusivamente em Belo Horizonte. Desenvolvida por m\u00e9dicos e fisioterapeutas, o Redcord promete aliviar dores, prevenir les\u00f5es musculares, melhorar a coordena\u00e7\u00e3o motora e potencializar treinamentos f\u00edsicos. &#8220;Estudos cient\u00edficos de universidades da Europa e EUA mostraram que dor, uso excessivo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-16012","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16012"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16012\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}