{"id":16006,"date":"2009-11-03T20:49:50","date_gmt":"2009-11-04T00:49:50","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16006"},"modified":"2009-11-03T20:49:50","modified_gmt":"2009-11-04T00:49:50","slug":"dupla-sena-808-%e2%80%93-resultado-do-sorteio-desta-terca-feira-0311","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/dupla-sena-808-%e2%80%93-resultado-do-sorteio-desta-terca-feira-0311\/16006","title":{"rendered":"Dupla Sena 808 \u2013 resultado do sorteio desta ter\u00e7a-feira (03\/11)"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/loto11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9673\" title=\"loto1\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/loto11.jpg\" alt=\"loto1\" width=\"150\" height=\"113\" \/><\/a>Dupla Sena 808<\/strong>\u00a0\u2013 o <strong>resultado<\/strong> do sorteio da Dupla Sena 808, que aconteceu nesta ter\u00e7a-feira (<strong>03\/11<\/strong>) em Santa Maria\/RS, foi divulgado pelo caminh\u00e3o da sorte. No \u00faltimo sorteio o premio principal teve um ganhador de Guapia\u00e7u, S\u00e3o Paulo. O premio principal de hoje est\u00e1 estimado em 200 mil reais. Na Dupla Sena, com o mesmo bilhete, voc\u00ea tem 2 chances de ganhar. Voc\u00ea escolhe de 6 a 15 n\u00fameros, entre os 50 dispon\u00edveis no volante, e participa de 2 sorteios por concurso. Se voc\u00ea n\u00e3o acertar 6 n\u00fameros no primeiro sorteio, pode ganhar no segundo. Nele, voc\u00ea ganha se acertar 4, 5 ou 6 n\u00fameros. Voc\u00ea pode deixar, ainda, que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 2, 4 ou 8 concursos consecutivos (Teimosinha). A aposta m\u00ednima, em 6 n\u00fameros, custa apenas R$ 1,00. Quanto mais n\u00fameros jogar, maior \u00e9 o pre\u00e7o da aposta e maiores as suas chances de ganhar.<\/p>\n<p>Confira o resultado da Dupla Sena 808 desta ter\u00e7a-feira (03\/11) &#8211; primeiro sorteio <strong>08\u00a0 09\u00a0 12\u00a0 15\u00a0 27\u00a0 50\u00a0<\/strong>e segundo sorteio <strong>05\u00a0 08\u00a0 16\u00a0 29\u00a0 36\u00a0 47<\/strong>. O pr\u00eamio acumulou e est\u00e1 estimedo em 450 mil reais.<\/p>\n<p>A Dupla Sena \u00e9 sorteada \u00e0s ter\u00e7as e sextas, sempre \u00e0s 20h.<\/p>\n<p>O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o, j\u00e1 computado o adicional destinado ao Minist\u00e9rio do Esporte. Dessa porcentagem, s\u00e3o distribu\u00eddos:<\/p>\n<p>30% entre os acertadores dos 6 n\u00fameros sorteados (Sena) no primeiro sorteio (faixa \u00fanica);<\/p>\n<p>30% entre os acertadores de 6 n\u00fameros sorteados (Sena) no segundo sorteio;<\/p>\n<p>20% entre os acertadores de 5 n\u00fameros (Quina) no segundo sorteio;<\/p>\n<p>20% entre os acertadores de 4 n\u00fameros (Quadra) no segundo sorteio.<\/p>\n<p>N\u00e3o havendo acertador em qualquer faixa de premia\u00e7\u00e3o, o valor acumula para o concurso seguinte, na faixa \u00fanica do primeiro sorteio. N\u00e3o deixe de conferir o seu bilhete de aposta.<\/p>\n<p>Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dupla Sena 808\u00a0\u2013 o resultado do sorteio da Dupla Sena 808, que aconteceu nesta ter\u00e7a-feira (03\/11) em Santa Maria\/RS, foi divulgado pelo caminh\u00e3o da sorte. No \u00faltimo sorteio o premio principal teve um ganhador de Guapia\u00e7u, S\u00e3o Paulo. O premio principal de hoje est\u00e1 estimado em 200 mil reais. Na Dupla Sena, com o mesmo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,360,335],"tags":[],"class_list":["post-16006","post","type-post","status-publish","format-standard","category-brasil","category-dupla-sena","category-loteria","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16006"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16006\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}