{"id":15962,"date":"2009-11-02T02:34:05","date_gmt":"2009-11-02T06:34:05","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15962"},"modified":"2009-11-02T01:12:50","modified_gmt":"2009-11-02T05:12:50","slug":"climatempo-meteorologia-%e2%80%93-boletim-da-chuva-no-feriado-0211","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/climatempo-meteorologia-%e2%80%93-boletim-da-chuva-no-feriado-0211\/15962","title":{"rendered":"Climatempo Meteorologia \u2013 boletim da chuva no feriado (02\/11)"},"content":{"rendered":"<p><strong><span style=\"font-weight: normal;\"><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/climatempo-1109.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11312\" title=\"climatempo 1109\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/climatempo-1109.jpg\" alt=\"climatempo 1109\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/climatempo-1109.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/climatempo-1109-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/span>Climatempo Meteorologia<\/strong> Sudeste &#8211; nesta segunda-feira (02\/11) o sol brilha forte e n\u00e3o chove no sul e no oeste paulista. Nas demais regi\u00f5es de S\u00e3o Paulo, assim como no Sul de Minas o sol aparece entre algumas nuvens e chove de forma passageira a partir do meio da tarde. Nas outras \u00e1reas do Sudeste brasileiro a nebulosidade \u00e9 maior, o sol aparece pouco entre muitas nuvens e ocorrem pancadas de chuva a qualquer hora do dia.<\/p>\n<p>Climatempo Meteorologia Norte &#8211; o c\u00e9u fica com muitas nuvens e chove a qualquer hora em Rond\u00f4nia, no sul do Amazonas e no sudoeste do Par\u00e1. No centro-norte e no leste do Tocantins, no norte e no leste do Par\u00e1, no Amap\u00e1 e nas demais \u00e1reas de Rond\u00f4nia, o sol aparece com for\u00e7a, as nuvens aumentam ao longo do dia e ocorrem pancadas de chuva a partir da tarde. Nas outras \u00e1reas, o sol aparece fraco entre muitas nuvens e ocorrem pancadas de chuva no decorrer do dia.<\/p>\n<p>Climatempo Meteorologia Nordeste &#8211; o tempo fica firme e seco em Sergipe, Alagoas, Pernambuco, na Para\u00edba, no Rio Grande do Norte, no Cear\u00e1, e no centro-norte da Bahia, do Maranh\u00e3o e do Piau\u00ed. Nas demais regi\u00f5es, o sol ainda aparece, mas o tempo abafado provoca a forma\u00e7\u00e3o de nuvens e pancadas de chuva em pontos isolados. A chuva ocorre principalmente no decorrer da tarde.<\/p>\n<p>Climatempo Meteorologia Sul &#8211; nesta segunda-feira o tempo muda no Sul brasileiro. O sol aparece pouco entre muitas nuvens e pancadas de chuva no sul ga\u00facho. Nas demais \u00e1reas da Regi\u00e3o o tempo fica firme e com sol. O c\u00e9u fica com poucas nuvens e n\u00e3o h\u00e1 previs\u00e3o de chuva.<\/p>\n<p>Climatempo Meteorologia Centro-Oeste &#8211; na segunda-feira, o sol aparece entre muitas nuvens e ocorrem pancadas de chuva no decorrer do dia em Goi\u00e1s, no Distrito Federal, no leste de Mato Grosso e no norte de Mato Grosso do Sul. Nas demais \u00e1reas de Mato Grosso, o c\u00e9u fica com muitas nuvens e chove no decorrer do dia. No Sul de Mato Grosso do Sul o tempo fica firme o sol brilha forte e n\u00e3o chove. Nas demais \u00e1reas do Centro-Oeste, o sol brilha forte e o tempo abafado provoca pancadas de chuva principalmente a partir do meio da tarde.<\/p>\n<p>Sobre o Grupo Climatempo &#8211; O Grupo Climatempo \u00e9 a maior empresa privada de meteorologia do pa\u00eds. Uma holding formada pela Climatempo Consultoria, Ag\u00eancia Climatempo, a TV Climatempo e a CLIMANET (Internet, servi\u00e7os de tecnologia e inform\u00e1tica). Atualmente, o Grupo Climatempo fornece conte\u00fado para os principais portais do pa\u00eds, mais de 50 retransmissoras de televis\u00e3o do Brasil, r\u00e1dios e tem cerca de mil clientes. Os dois principais segmentos atendidos s\u00e3o o de agroneg\u00f3cios e meios de comunica\u00e7\u00e3o. Al\u00e9m destes, fornece conte\u00fado meteorol\u00f3gico estrat\u00e9gico para produtoras, a ind\u00fastria eletroeletr\u00f4nica e t\u00eaxtil, com\u00e9rcio, moda e turismo, constru\u00e7\u00e3o civil, setor de energia, entre outros setores.<\/p>\n<p>O Grupo \u00e9 presidido pelo meteorologista Carlos Magno, um dos primeiros comunicadores da profiss\u00e3o no Pa\u00eds, com mais de 23 anos de carreira, que ajudou a mudar a cultura que o brasileiro tinha sobre a meteorologia. O Grupo Climatempo conta ainda com Ana L\u00facia Frony vice-presidente, Renato Urbinder, s\u00f3cio-diretor (Diretor de Neg\u00f3cios e Projetos Especiais), e os diretores executivos Gilca Palma (Climatempo Meteorologia), Andr\u00e9 Madeira (Ag\u00eancia Climatempo) e o jornalista Paulo Polli (TV Climatempo) no Conselho Consultivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Climatempo Meteorologia Sudeste &#8211; nesta segunda-feira (02\/11) o sol brilha forte e n\u00e3o chove no sul e no oeste paulista. Nas demais regi\u00f5es de S\u00e3o Paulo, assim como no Sul de Minas o sol aparece entre algumas nuvens e chove de forma passageira a partir do meio da tarde. Nas outras \u00e1reas do Sudeste brasileiro [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327,376],"tags":[],"class_list":["post-15962","post","type-post","status-publish","format-standard","category-brasil","category-clima","category-clima-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15962"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15962\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}