{"id":15955,"date":"2009-11-02T01:02:37","date_gmt":"2009-11-02T05:02:37","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15955"},"modified":"2009-11-02T01:02:37","modified_gmt":"2009-11-02T05:02:37","slug":"previsao-do-tempo-na-regiao-sudeste-de-02-a-0411","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-sudeste-de-02-a-0411\/15955","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Sudeste de 02 a 04\/11"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo<\/strong> Sudeste 02\/11\/2009: Na capital do RJ e no Vale do Para\u00edba, litoral paulista e no sul de SP: sol com nebulosidade varia\u00e7\u00e3o de nuvens. Em SP: sol com nebulosidade vari\u00e1vel com pancadas de chuva \u00e0 noite. No centro-sul e leste de MG, no Vale Hist\u00f3rico, em boa parte do RJ e no ES: sol com nebulosidade vari\u00e1vel com pancadas de chuva a partir da tarde e localmente forte. No norte e oeste de MG: sol com nebulosidade vari\u00e1vel com pancadas de chuva localmente forte. As temperaturas seguir\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 34C no oeste de SP. Temperatura m\u00ednima: 12C no sul de SP.\u00a0<\/p>\n<p>Previs\u00e3o do tempo 03\/11\/2009: No litoral sul de SP no litoral norte do RJ, no ES e no leste de MG: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva a qualquer momento. No litoral norte de SP e no litoral sul do RJ: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva \u00e0 noite. Nas demais \u00e1reas: sol com nebulosidade vari\u00e1vel com pancadas de chuva. As temperaturas seguir\u00e3o est\u00e1veis.<\/p>\n<p>Previs\u00e3o do tempo Tend\u00eancia: No ES, RJ e litoral norte paulista: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva. Nas demais \u00e1reas: sol com nebulosidade vari\u00e1vel com pancadas de chuva. As temperaturas seguir\u00e3o est\u00e1veis.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo Sudeste 02\/11\/2009: Na capital do RJ e no Vale do Para\u00edba, litoral paulista e no sul de SP: sol com nebulosidade varia\u00e7\u00e3o de nuvens. Em SP: sol com nebulosidade vari\u00e1vel com pancadas de chuva \u00e0 noite. No centro-sul e leste de MG, no Vale Hist\u00f3rico, em boa parte do RJ e no [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[327],"tags":[],"class_list":["post-15955","post","type-post","status-publish","format-standard","category-clima","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15955"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15955\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}