{"id":15804,"date":"2009-10-30T18:57:46","date_gmt":"2009-10-30T22:57:46","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15804"},"modified":"2009-10-30T18:58:28","modified_gmt":"2009-10-30T22:58:28","slug":"rio-grande-do-norte-investira-r-1-bilhao-em-saneamento-basico-ate-2010","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/rio-grande-do-norte-investira-r-1-bilhao-em-saneamento-basico-ate-2010\/15804","title":{"rendered":"Rio Grande do Norte investir\u00e1 R$ 1 bilh\u00e3o em saneamento b\u00e1sico at\u00e9 2010"},"content":{"rendered":"<p>As obras de <strong>saneamento b\u00e1sico no Rio Grande do Norte<\/strong> v\u00e3o ultrapassar a marca de R$ 1 bilh\u00e3o at\u00e9 2010. Somadas, as obras de abastecimento de \u00e1gua e esgotamento sanit\u00e1rio realizadas pelo Governo do Estado desde 2003 at\u00e9 o pr\u00f3ximo ano totalizam R$ 1,06 bilh\u00e3o. A maior parte delas est\u00e1 sendo executada pela Companhia de \u00c1guas e Esgotos do Rio Grande do Norte (Caern), cujo volume investido chega a R$ 686,6 milh\u00f5es, seguida da Secretaria Estadual de Meio Ambiente e Recursos H\u00eddricos (Semarh), que disp\u00f5e de outros R$ 374 milh\u00f5es. Com isso, o Estado ir\u00e1 dobrar a \u00e1rea saneada at\u00e9 o final do ano que vem.<\/p>\n<p>Entre as principais obras realizadas pela Caern em Natal est\u00e3o a Esta\u00e7\u00e3o Central de Tratamento de Esgotos do Baldo, a nova adutora do Jiqui, a implanta\u00e7\u00e3o e amplia\u00e7\u00e3o de redes de esgotos e a troca de tubula\u00e7\u00e3o antiga por nova em v\u00e1rios bairros da capital. Outras obras importantes est\u00e3o sob a responsabilidade da Semarh, como as adutoras Barragem Santa Cruz-Mossor\u00f3, Alto Oeste e terceira etapa da Serra de Santana. &#8220;Este \u00e9 o maior volume de recursos j\u00e1 aplicados em saneamento na hist\u00f3ria do Rio Grande do Norte. E isso s\u00f3 foi poss\u00edvel porque o Estado est\u00e1 equilibrado financeiramente e teve condi\u00e7\u00f5es de contrair financiamentos e investir recursos pr\u00f3prios para realizar estas obras&#8221;, afirma a governadora Wilma de Faria. Segundo ela, o apoio do governo federal, que incentivou obras por meio do PAC, foi fundamental para que o Estado tivesse condi\u00e7\u00f5es de dobrar sua \u00e1rea saneada.<\/p>\n<p>Na Esta\u00e7\u00e3o Central de Tratamento de Esgotos do Baldo, prevista para funcionar a partir de mar\u00e7o do pr\u00f3ximo ano, o governo est\u00e1 investindo R$ 82 milh\u00f5es e vai tratar esgotos de 21 bairros de Natal. Al\u00e9m disso, os dejetos lan\u00e7ados atualmente no rio Potengi de forma in-natura, ser\u00e3o todos desinfectados, atingindo um grau de limpeza dentro dos padr\u00f5es exigidos pelo Conselho Nacional de Meio Ambiente.<\/p>\n<p>A nova adutora do Jiqui, que est\u00e1 em fase de testes, recebe investimentos de R$ 13,6 milh\u00f5es e vai beneficiar 405 mil habitantes com a redu\u00e7\u00e3o do teor de nitrato em alguns pontos de Natal. Na zona Norte da cidade, o governo est\u00e1 executando obras de esgotamento sanit\u00e1rio da Redinha, substituindo trechos da adutora j\u00e1 existente e implantando a nova tubula\u00e7\u00e3o que vai captar \u00e1gua nos po\u00e7os j\u00e1 perfurados nas margens do rio Doce. Essa \u00e1gua de excelente qualidade ser\u00e1 conduzida ao reservat\u00f3rio da Redinha, de onde ser\u00e1 bombeada para diversos bairros da regi\u00e3o.<\/p>\n<p>INVESTIMENTO EM SA\u00daDE<\/p>\n<p>\u00a0&#8220;Obras de saneamento s\u00e3o caras e provocam transtornos porque para implantar tubula\u00e7\u00f5es de \u00e1gua e esgotos \u00e9 necess\u00e1rio escavar o ch\u00e3o e interditar vias. Entretanto, o transtorno passa e o benef\u00edcio permanece para sempre, contribuindo para a sa\u00fade da popula\u00e7\u00e3o&#8221;, destaca o diretor presidente da Caern, Walter Gasi, que \u00e9 engenheiro sanitarista.<\/p>\n<p>Al\u00e9m dos recursos do Governo do Estado, as obras s\u00e3o realizadas com financiamentos dos programas Pr\u00f3-Saneamento, Prodetur, Saneamento para Todos, al\u00e9m da Funda\u00e7\u00e3o Nacional de Sa\u00fade (Funasa) e Or\u00e7amento Geral da Uni\u00e3o, ambos do governo federal. Dados da Organiza\u00e7\u00e3o Mundial de Sa\u00fade apontam que, para cada d\u00f3lar investido em saneamento, os governos economizam quatro d\u00f3lares em sa\u00fade. Atualmente, as chamadas doen\u00e7as de veicula\u00e7\u00e3o h\u00eddrica, como c\u00f3lera e hepatite infecciosa, est\u00e3o entre as principais causas de mortalidade infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As obras de saneamento b\u00e1sico no Rio Grande do Norte v\u00e3o ultrapassar a marca de R$ 1 bilh\u00e3o at\u00e9 2010. Somadas, as obras de abastecimento de \u00e1gua e esgotamento sanit\u00e1rio realizadas pelo Governo do Estado desde 2003 at\u00e9 o pr\u00f3ximo ano totalizam R$ 1,06 bilh\u00e3o. A maior parte delas est\u00e1 sendo executada pela Companhia de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-15804","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15804"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15804\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}