{"id":15799,"date":"2009-10-30T19:00:42","date_gmt":"2009-10-30T23:00:42","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15799"},"modified":"2009-10-30T19:00:42","modified_gmt":"2009-10-30T23:00:42","slug":"especialistas-orientam-na-criacao-de-filhos-gemeos","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/especialistas-orientam-na-criacao-de-filhos-gemeos\/15799","title":{"rendered":"Especialistas orientam na cria\u00e7\u00e3o de filhos g\u00eameos"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/gemeas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-15801\" title=\"gemeas\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/gemeas.jpg\" alt=\"gemeas\" width=\"150\" height=\"113\" \/><\/a>O nascimento de <strong>g\u00eameos<\/strong> \u00e9 cada vez mais comum. As mulheres est\u00e3o tendo filhos mais tarde, e a insemina\u00e7\u00e3o assistida contribui muito para essa mudan\u00e7a. Para orientar pais e futuros pais de <strong>gemelares<\/strong>, Filhos G\u00eameos, lan\u00e7ado pela Publifolha, re\u00fane textos de 53 especialistas que abordam temas como os cuidados na gesta\u00e7\u00e3o, a prepara\u00e7\u00e3o da casa para a chegada dos beb\u00eas, o nascimento e os primeiros dias de vida.<\/p>\n<p>Em linguagem clara e objetiva, o t\u00edtulo traz tamb\u00e9m informa\u00e7\u00f5es importantes sobre amamenta\u00e7\u00e3o, o crescimento, o ingresso na escola, o comportamento, a vida social e o papel dos pais.<\/p>\n<p>Sob a coordena\u00e7\u00e3o dos m\u00e9dicos pediatras Renata Dejtiar Waksman e Cl\u00e1udio Schvartsman, o livro foi desenvolvido por uma equipe de pediatras, obstetras, ortopedistas, enfermeiros e psic\u00f3logos ligados ao Departamento Materno Infantil do Hospital Israelita Albert Einstein, de S\u00e3o Paulo.<\/p>\n<p>Dados sobre irm\u00e3os siameses, gesta\u00e7\u00f5es de m\u00faltiplos, g\u00eameos dizig\u00f3ticos e monozig\u00f3ticos s\u00e3o apresentados de maneira direta e informativa. O livro tamb\u00e9m possui um passo a passo da gesta\u00e7\u00e3o, que conta com imagens de ultrassonografias para ilustrar o per\u00edodo.<\/p>\n<p>\u00a0&#8220;Os textos refletem a experi\u00eancia acumulada por profissionais que atuam nas mais variadas especialidades e oferecem conhecimentos que certamente ir\u00e3o contribuir para todos os que cuidam de crian\u00e7as g\u00eameas. Reunimos informa\u00e7\u00f5es necess\u00e1rias para que os beb\u00eas cres\u00e7am saud\u00e1veis e felizes&#8221;, revela a pediatra Renata Waksman.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O nascimento de g\u00eameos \u00e9 cada vez mais comum. As mulheres est\u00e3o tendo filhos mais tarde, e a insemina\u00e7\u00e3o assistida contribui muito para essa mudan\u00e7a. Para orientar pais e futuros pais de gemelares, Filhos G\u00eameos, lan\u00e7ado pela Publifolha, re\u00fane textos de 53 especialistas que abordam temas como os cuidados na gesta\u00e7\u00e3o, a prepara\u00e7\u00e3o da casa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-15799","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15799"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15799\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}