{"id":15729,"date":"2009-10-29T17:33:28","date_gmt":"2009-10-29T21:33:28","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15729"},"modified":"2009-10-29T17:33:28","modified_gmt":"2009-10-29T21:33:28","slug":"juiz-da-1%c2%aa-zona-eleitoral-cassa-outro-vereador-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/juiz-da-1%c2%aa-zona-eleitoral-cassa-outro-vereador-de-sao-paulo\/15729","title":{"rendered":"Juiz da 1\u00aa Zona Eleitoral cassa outro vereador de S\u00e3o Paulo"},"content":{"rendered":"<p>O juiz da 1\u00aa Zona Eleitoral, Aloisio S\u00e9rgio Rezende Silveira, acolheu pretens\u00e3o do Minist\u00e9rio P\u00fablico Eleitoral (MPE) e cassou o diploma de Marcus Vin\u00edcius de Almeida Ferreira (PR), estendendo os efeitos da decis\u00e3o que o havia declarado ineleg\u00edvel por tr\u00eas anos. A cassa\u00e7\u00e3o ocorre porque Ferreira, conhecido como Quito Formiga, embora diplomado como suplente, ocupa atualmente o cargo de vereador na C\u00e2mara Municipal. Com a decis\u00e3o, s\u00e3o 14 os vereadores da capital cassados por terem suas contas de campanha rejeitadas.<\/p>\n<p>Representa\u00e7\u00f5es<br \/>\nSilveira j\u00e1 julgou 19 das 45 representa\u00e7\u00f5es propostas pelo MPE. O juiz ainda vai revisar as contas de 16 vereadores eleitos, sete suplentes, dois candidatos \u00e0 Prefeitura (Marta Suplicy e Geraldo Alckmin) e do prefeito eleito Gilberto Kassab. Veja abaixo os resultados das contas j\u00e1 julgadas:<\/p>\n<p>Cassados e com inelegibilidade decretada por tr\u00eas anos<br \/>\nAdilson Amadeu (PTB)<br \/>\nAdolfo Quintas Neto (PSDB)<br \/>\nCarlos Alberto Apolin\u00e1rio (DEM)<br \/>\nCarlos Alberto Bezerra J\u00fanior (PSDB)<br \/>\nCl\u00e1udio Roberto Barbosa de Souza (PSDB)<br \/>\nDalton Silvano do Amaral (PSDB)<br \/>\nDomingos Odone Dissei (DEM)<br \/>\nGilson Almeida Barreto (PSDB)<br \/>\nMarta Freire da Costa (DEM)<br \/>\nPaulo S\u00e9rgio Abou Anni (PV)<br \/>\nRicardo Teixeira (PSDB)<br \/>\nUshitaro Kamia (DEM)<br \/>\nWadih Mutran (PP)<br \/>\nMarcus Vin\u00edcius de Almeida Ferreira, o Quito Formiga, suplente empossado vereador (PR)<\/p>\n<p>Contas aprovadas<br \/>\nNoemi Pereira Nonato Cavalcante (PSB) (aprova\u00e7\u00e3o com ressalvas)<br \/>\nAntonio de Paiva Monteiro Filho (PR)<br \/>\nAnt\u00f4nio Floriano Pereira Pesaro (PSDB)<br \/>\nAntonio Goulart dos Reis (PMDB)<br \/>\nEliseu Gabriel (PSB)<\/p>\n<p>Efeito suspensivo<br \/>\nOs 13 cassados entraram com recurso e conseguiram efeito suspensivo \u00e0s decis\u00f5es. Todos aguardam o julgamento dos recursos pelo Tribunal Regional Eleitoral. Quito Formiga tamb\u00e9m recorreu e conseguiu efeito suspensivo \u00e0 decis\u00e3o que o decretou ineleg\u00edvel por tr\u00eas anos e ainda pode recorrer da cassa\u00e7\u00e3o. O motivo da proced\u00eancia das 14 a\u00e7\u00f5es foi o mesmo: recebimento de doa\u00e7\u00f5es irregulares da AIB \u2013 Associa\u00e7\u00e3o Imobili\u00e1ria Brasileira nas elei\u00e7\u00f5es de 2008.<\/p>\n<p>A revis\u00e3o das contas prestadas pelos candidatos ocorre devido \u00e0s representa\u00e7\u00f5es propostas pelo Minist\u00e9rio P\u00fablico Eleitoral, com base no artigo 30-A da lei 9.504\/97 e na lei 64\/90. Esses dispositivos prev\u00eaem a cassa\u00e7\u00e3o de registro e declara\u00e7\u00e3o de inelegibilidade por tr\u00eas anos quando comprovados capta\u00e7\u00e3o ou gastos il\u00edcitos de recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O juiz da 1\u00aa Zona Eleitoral, Aloisio S\u00e9rgio Rezende Silveira, acolheu pretens\u00e3o do Minist\u00e9rio P\u00fablico Eleitoral (MPE) e cassou o diploma de Marcus Vin\u00edcius de Almeida Ferreira (PR), estendendo os efeitos da decis\u00e3o que o havia declarado ineleg\u00edvel por tr\u00eas anos. A cassa\u00e7\u00e3o ocorre porque Ferreira, conhecido como Quito Formiga, embora diplomado como suplente, ocupa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-15729","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15729"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15729\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}