{"id":15607,"date":"2009-10-29T10:08:52","date_gmt":"2009-10-29T14:08:52","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15607"},"modified":"2009-10-29T10:08:52","modified_gmt":"2009-10-29T14:08:52","slug":"alta-tecnologia-para-caes-e-gatos","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/alta-tecnologia-para-caes-e-gatos\/15607","title":{"rendered":"Alta tecnologia para c\u00e3es e gatos"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/puppi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-15608\" title=\"puppi\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/puppi-249x187.jpg\" alt=\"puppi\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/puppi-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Pet shops, canis e resid\u00eancias agora contam com um novo dispositivo para oferecer \u00e1gua e ra\u00e7\u00e3o &#8211; na quantidade desejada e na hora certa &#8211; aos animais de estima\u00e7\u00e3o, e at\u00e9 para a lavagem do canil. O inventor Andres Custodio F\u00fcchter, morador de Crici\u00fama-SC, desenvolveu o Canil Eletr\u00f4nico, que facilita a vida de quem tem de cuidar de um c\u00e3o ou gato, mesmo \u00e0 dist\u00e2ncia.<\/p>\n<p>Segundo ele, a m\u00e1quina pode ser feita de fibra, metal ou pl\u00e1stico e, portanto, \u00e9 resistente at\u00e9 a animais que costumam estragar materiais mais fr\u00e1geis. &#8220;Desenvolvi uma tecnologia capaz de avisar o dono, via celular, que a ra\u00e7\u00e3o ou a \u00e1gua est\u00e1 acabando&#8221;, garante.<\/p>\n<p>O Canil Eletr\u00f4nico \u00e9 composto por: programador eletr\u00f4nico, para comandar o fornecimento de \u00e1gua, ra\u00e7\u00e3o e a lavagem do recinto; celular, ligado ao programador, para contatar o dono em caso de alguma falha; recipientes de ra\u00e7\u00e3o e de \u00e1gua com sensor de quantidade; motores: um lava-jato e outro que gira o bico lava-jato a 180\u00ba; boia d&#8217;\u00e1gua, que identifica a falta de \u00e1gua e permite que, na falta do l\u00edquido, o lava-jato n\u00e3o funcione, evitando a queima do mecanismo. O prot\u00f3tipo de F\u00fcchter \u00e9 feito de fibra e a coifa de alimenta\u00e7\u00e3o, de metal. &#8220;O funcionamento da m\u00e1quina s\u00f3 depende de uma \u00e1rea quadrangular e com ca\u00edda d&#8217;\u00e1gua para uma calha&#8221;, alerta.<\/p>\n<p>O inventor v\u00ea um grande mercado para sua cria\u00e7\u00e3o, principalmente entre os clientes de pet shops. &#8220;A ideia surgiu no momento em que minha mulher e minha filha falaram que queriam ter um c\u00e3o, mas alegaram ter falta de tempo. O bichinho precisa de carinho, tamb\u00e9m, mas pelo menos na aus\u00eancia prolongada de seus donos ou cuidadores, o sistema \u00e9 garantia de que ele n\u00e3o passar\u00e1 fome nem sede&#8221;.<\/p>\n<p>A inten\u00e7\u00e3o do inventor \u00e9 negociar a patente ou conseguir investidores para o dispositivo, que chama carinhosamente de &#8220;dom\u00e9stica canina&#8221;. Empres\u00e1rios interessados em investir no produto devem entrar em contato com a Associa\u00e7\u00e3o Nacional dos Inventores pelo telefone (11) 3873-3211.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pet shops, canis e resid\u00eancias agora contam com um novo dispositivo para oferecer \u00e1gua e ra\u00e7\u00e3o &#8211; na quantidade desejada e na hora certa &#8211; aos animais de estima\u00e7\u00e3o, e at\u00e9 para a lavagem do canil. O inventor Andres Custodio F\u00fcchter, morador de Crici\u00fama-SC, desenvolveu o Canil Eletr\u00f4nico, que facilita a vida de quem tem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-15607","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15607"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15607\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}