{"id":15523,"date":"2009-10-28T18:07:00","date_gmt":"2009-10-28T22:07:00","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15523"},"modified":"2009-10-28T18:07:00","modified_gmt":"2009-10-28T22:07:00","slug":"calvo-eu-conheca-a-tecnica-do-transplante-folicular-coronal","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/calvo-eu-conheca-a-tecnica-do-transplante-folicular-coronal\/15523","title":{"rendered":"Calvo, eu? Conhe\u00e7a a t\u00e9cnica do transplante folicular coronal"},"content":{"rendered":"<p>As t\u00e9cnicas de <strong>transplante capilar<\/strong> evolu\u00edram desde quando foram criadas, h\u00e1 cerca de 50 anos. Atualmente, a t\u00e9cnica mais moderna \u00e9 o Transplante Folicular Coronal, no qual utilizas-se 100% de unidades foliculares (<strong>UFs<\/strong>) individuais no procedimento cir\u00fargico &#8211; cada unidade pode ter de 1 a 4 fios. Os avan\u00e7os no transplante conseguiram oferecer o tipo de resultado h\u00e1 muito esperado: natural, gra\u00e7as \u00e0s unidades foliculares; denso, pela t\u00e9cnica folicular coronal; e cobrindo grandes \u00e1reas, o que resolve a calv\u00edcies da maioria dos casos numa \u00fanica sess\u00e3o, utilizando as Giga Sessions de at\u00e9 5.000 unidades foliculares.<\/p>\n<p>&#8220;O Transplante Folicular Coronal respeita as caracter\u00edsticas naturais do cabelo: \u00e2ngulo, dire\u00e7\u00e3o dos fios (orelha a orelha horizontalmente), mant\u00e9m as varia\u00e7\u00f5es normais de densidade e volume das diferentes regi\u00f5es da cabe\u00e7a, permite colocar as UFs em \u00e2ngulos mais agudos, ou seja, deixa o cabelo mais &#8220;deitado&#8221; como cabelo natural&#8221;, ressalta Dr. Arthur Tykocinski (CRM 66.385), dermatologista especialista pela Sociedade Brasileira de Dermatologia, membro e representante no Brasil da Sociedade Internacional de Cirurgia de Restaura\u00e7\u00e3o Capilar (ISHRS &#8211; International Society of Hair Restoration Surgery) e diretor do Tykocinski Medical Group. Ele foi presidente do 16\u00ba Congresso Mundial de Restaura\u00e7\u00e3o Capilar de Montreal e realizou, recentemente, apresenta\u00e7\u00f5es no 17th Annual Scientific Meeting, evento que aconteceu em Amsterd\u00e3 e reuniu os principais especialistas em transplante capilar do mundo.<\/p>\n<p>Hoje em dia, por exemplo, sabe-se que na linha capilar anterior as unidades foliculares apresentam apenas 1 fio. Assim, o trabalho cuidadoso do transplante, realizado por uma equipe, que re\u00fane 12 pessoas, prima pela arte, pois a t\u00e9cnica j\u00e1 foi superada com o Transplante Folicular Coronal. Assim, permite que cada cirurgi\u00e3o mostre o seu melhor. &#8220;A evolu\u00e7\u00e3o t\u00e9cnica chegou a um ponto em que a arte de cada equipe passa ser o grande diferencial. N\u00e3o basta mais apenas restaurar os cabelos: harmonia e beleza tamb\u00e9m devem ser contemplados, atendendo \u00e0s atuais exig\u00eancias desses homens t\u00e3o vaidosos&#8221;. Todo o processo do Transplante Folicular Coronal \u00e9 bastante complexo, onde cada profissional que participa da equipe exerce uma diferente fun\u00e7\u00e3o. A log\u00edstica passa a ser muito importante, pois coordenar equipes com um total de at\u00e9 20 pessoas exige muito profissionalismo e organiza\u00e7\u00e3o, muito diferente do antigo conceito de consult\u00f3rio m\u00e9dico.<\/p>\n<p>Os orif\u00edcios abertos na \u00e1rea a ser transplantada s\u00e3o incrivelmente pequenos, de 0,55 a 0,8 mm de largura. Com eles, \u00e9 poss\u00edvel aumentar a densidade dos fios, criando um aspecto ao mesmo tempo compacto e volumoso. A cicatriza\u00e7\u00e3o \u00e9 mais r\u00e1pida e as marcas do transplante ficam impercept\u00edveis. O per\u00edodo p\u00f3s-transplante, que, antes causava certo constrangimento, ficou reduzido h\u00e1 poucos dias.<\/p>\n<p>Quem j\u00e1 fez um transplante capilar com t\u00e9cnicas antigas (conhecida como tufos) e n\u00e3o obteve um resultado natural, pode corrigi-lo com outra cirurgia. Sempre \u00e9 poss\u00edvel uma grande melhora no aspecto, mesmo tendo feito um transplante com aqueles antigos tufos, com as novas t\u00e9cnicas existentes que respeitam o desenho do contorno do cabelo. Mas, a abordagem corretiva varia de caso a caso.<\/p>\n<p>No homem, a calv\u00edcie androgen\u00e9tica \u00e9 o quadro mais comum associado \u00e0 perda de cabelos. &#8220;Muitas vezes a calv\u00edcie pode ser agravada pela inflama\u00e7\u00e3o do couro cabeludo que ocorre na dermatite seborr\u00e9ia (caspa). Temos tamb\u00e9m casos de alopecia areata, mas s\u00e3o quedas circunscritas e que podem curar espontaneamente. Assim, quanto mais cedo o paciente procurar um especialista para diagn\u00f3stico e tratamento, melhor&#8221;, finaliza Dr. Arthur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As t\u00e9cnicas de transplante capilar evolu\u00edram desde quando foram criadas, h\u00e1 cerca de 50 anos. Atualmente, a t\u00e9cnica mais moderna \u00e9 o Transplante Folicular Coronal, no qual utilizas-se 100% de unidades foliculares (UFs) individuais no procedimento cir\u00fargico &#8211; cada unidade pode ter de 1 a 4 fios. Os avan\u00e7os no transplante conseguiram oferecer o tipo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-15523","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15523"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15523\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}