{"id":15470,"date":"2009-10-28T10:27:04","date_gmt":"2009-10-28T14:27:04","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15470"},"modified":"2009-10-28T10:27:04","modified_gmt":"2009-10-28T14:27:04","slug":"projeto-pioneiro-aumenta-produtividade-pecuaria-em-ji-parana-ro-sem-destruir-floresta","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/projeto-pioneiro-aumenta-produtividade-pecuaria-em-ji-parana-ro-sem-destruir-floresta\/15470","title":{"rendered":"Projeto pioneiro aumenta produtividade pecu\u00e1ria em Ji-Paran\u00e1 RO sem destruir floresta"},"content":{"rendered":"<p>Um projeto pioneiro &#8211; utilizando novas tecnologias para otimizar \u00e1reas de pastos j\u00e1 existentes &#8211; est\u00e1 promovendo o aumento da produtividade em pequenas e m\u00e9dias propriedades pastoris de Rond\u00f4nia, poupando o desmatamento na Amaz\u00f4nia. A experi\u00eancia vem sendo implementada em 22 propriedades do estado, com apoio e recursos do Minist\u00e9rio do Meio Ambiente (MMA).\u00a0<\/p>\n<p>O sistema silvopastoril, como \u00e9 chamado, foi uma iniciativa experimental, de car\u00e1ter demonstrativo, iniciada em junho de 2006, com encerramento previsto para o final de 2009. O trabalho demonstra que, mesmo quando o assunto \u00e9 cria\u00e7\u00e3o de gado, \u00e9 vi\u00e1vel implementar sistemas que promovam a pecu\u00e1ria associada \u00e0 agroecologia.<\/p>\n<p>Realizado em nove munic\u00edpios pr\u00f3ximos a Ji-Paran\u00e1, segunda maior cidade de Rond\u00f4nia, o projeto demonstrativo &#8220;Agricultores Familiares promovendo o Equil\u00edbrio Ambiental em Rond\u00f4nia&#8221; desenvolveu uma pesquisa para testar e descobrir que tipos de esp\u00e9cies vegetais poderiam ser inseridas em pastos (sistema silvopastoril), com o objetivo de melhorar o microclima, promover maior rendimento econ\u00f4mico e evitar novos desmatamentos na floresta.<\/p>\n<p>Reflorestamento &#8211; A proposta inclui ainda o reflorestamento de matas ciliares, nascentes e \u00e1reas degradadas com vegeta\u00e7\u00e3o nativa e frut\u00edferas, o que ajuda a recompor a cobertura vegetal original e adequar as propriedades \u00e0s exig\u00eancias da legisla\u00e7\u00e3o ambiental.<\/p>\n<p>O projeto \u00e9 feito com a combina\u00e7\u00e3o de \u00e1rvores, pastagem e cria\u00e7\u00e3o de gado numa mesma \u00e1rea, ao mesmo tempo, com o manejo realizado de forma integrada. Outro objetivo \u00e9 incrementar a produtividade por unidade de \u00e1rea com a preserva\u00e7\u00e3o do meio ambiente. Atualmente, a estimativa \u00e9 de que h\u00e1 1,6 cabe\u00e7as de gado por hectare, e o projeto pretende aumentar este \u00edndice para 5,2 animais na mesma \u00e1rea.<\/p>\n<p>A cria\u00e7\u00e3o de animais associada ao plantio de \u00e1rvores em bloco ao longo das pastagens pode reduzir a eros\u00e3o e melhorar a conserva\u00e7\u00e3o da \u00e1gua. Tamb\u00e9m reduz a necessidade de fertilizantes minerais e ajuda a capturar e fixar o carbono. Al\u00e9m disso, diversifica a produ\u00e7\u00e3o, melhora o conforto dos animais e aumenta a biodiversidade e a gera\u00e7\u00e3o de renda dos agricultores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um projeto pioneiro &#8211; utilizando novas tecnologias para otimizar \u00e1reas de pastos j\u00e1 existentes &#8211; est\u00e1 promovendo o aumento da produtividade em pequenas e m\u00e9dias propriedades pastoris de Rond\u00f4nia, poupando o desmatamento na Amaz\u00f4nia. A experi\u00eancia vem sendo implementada em 22 propriedades do estado, com apoio e recursos do Minist\u00e9rio do Meio Ambiente (MMA).\u00a0 O [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-15470","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15470"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15470\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}