{"id":15389,"date":"2009-10-27T23:08:12","date_gmt":"2009-10-28T03:08:12","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15389"},"modified":"2009-10-27T23:08:12","modified_gmt":"2009-10-28T03:08:12","slug":"hepatite-decisao-da-anvisa-amplia-acesso-a-medicamento","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/hepatite-decisao-da-anvisa-amplia-acesso-a-medicamento\/15389","title":{"rendered":"Hepatite: decis\u00e3o da Anvisa amplia acesso a medicamento"},"content":{"rendered":"<p>Hepatite: decis\u00e3o da Anvisa amplia acesso a medicamento<\/p>\n<p>A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (<strong>Anvisa<\/strong>) autorizou o uso do medicamento fumarato de tenofovir desoproxila 300 mg no tratamento da <strong>hepatite B<\/strong> cr\u00f4nica em adultos. A medida consta da RDC 53, publicada no DOU desta ter\u00e7a-feira (27). Utilizado no Brasil como um dos tratamentos para a Aids, o Tenofovir j\u00e1 era usado em pacientes com hepatite B nos Estados Unidos e na Uni\u00e3o Europ\u00e9ia. A amplia\u00e7\u00e3o da indica\u00e7\u00e3o de uso vinha sendo discutida entre a Anvisa e o Minist\u00e9rio da Sa\u00fade desde o inicio de 2009. No decorrer do ano foram realizadas duas reuni\u00f5es com representantes do laborat\u00f3rio fabricante, Gilead, que afirmaram n\u00e3o poder solicitar a inclus\u00e3o da nova indica\u00e7\u00e3o em virtude de um acordo comercial.<\/p>\n<p>Informa\u00e7\u00f5es apuradas pela Anvisa demonstraram que um acordo entre a Gilead e a GSK, outra farmac\u00eautica que j\u00e1 possu\u00eda um medicamento registrado no Brasil para o tratamento da hepatite B, de custo bastante superior ao do Tenofovir, impedia que o Gilead solicitasse a inclus\u00e3o da nova indica\u00e7\u00e3o de uso para o Tenofovir no pa\u00eds.<\/p>\n<p>Diante do fato e com base na rigorosa an\u00e1lise dos dados que sustentaram a aprova\u00e7\u00e3o dessa indica\u00e7\u00e3o pelo FDA, nos Estados Unidos e pela Emea, na Uni\u00e3o Europ\u00e9ia, a Anvisa resolveu aprovar a nova indica\u00e7\u00e3o de uso para o medicamento.<\/p>\n<p>A medida preserva o direito de acesso a um medicamento eficaz e seguro e viabiliza a inclus\u00e3o do Tenofovir na lista de medicamentos de distribui\u00e7\u00e3o gratuita aos portadores da doen\u00e7a. A utiliza\u00e7\u00e3o do medicamento com essa indica\u00e7\u00e3o ser\u00e1 monitorada pelo sistema de farmacovigil\u00e2ncia da Anvisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hepatite: decis\u00e3o da Anvisa amplia acesso a medicamento A Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) autorizou o uso do medicamento fumarato de tenofovir desoproxila 300 mg no tratamento da hepatite B cr\u00f4nica em adultos. A medida consta da RDC 53, publicada no DOU desta ter\u00e7a-feira (27). Utilizado no Brasil como um dos tratamentos para a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":{"0":"post-15389","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-saude-e-vida","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15389"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15389\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}