{"id":15386,"date":"2009-10-27T23:10:59","date_gmt":"2009-10-28T03:10:59","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15386"},"modified":"2009-10-27T23:10:59","modified_gmt":"2009-10-28T03:10:59","slug":"15-dos-acidentes-de-mao-acontecem-em-acidentes-de-transito","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/15-dos-acidentes-de-mao-acontecem-em-acidentes-de-transito\/15386","title":{"rendered":"15% dos acidentes de m\u00e3o acontecem em acidentes de tr\u00e2nsito"},"content":{"rendered":"<p>O feriado de 2 de novembro se aproxima, e com ele as estat\u00edstica de estradas lotadas e acidentes de tr\u00e2nsito, tamb\u00e9m, aumentam em todo pa\u00eds. Por isso, a<strong> Associa\u00e7\u00e3o Brasileira de Cirurgia da M\u00e3o<\/strong> desenvolveu a Campanha Nacional de Preven\u00e7\u00e3o \u00e0 Acidentes e Traumas da M\u00e3o, que faz um alerta para a import\u00e2ncia do cuidado com os acidentes de tr\u00e2nsito envolvendo os membros superiores. Segundo estimativas levantadas pela Associa\u00e7\u00e3o em 12 hospitais brasileiros, 15% dos acidentes de m\u00e3os ocorrem em acidentes de tr\u00e2nsito, grande maioria, devido a imprud\u00eancia dos condutores.<\/p>\n<p>Os motociclistas s\u00e3o os mais vulner\u00e1veis &#8211; pela aus\u00eancia de uma prote\u00e7\u00e3o (como no carro) e a alta velocidade atingida pelas motos, que geram muita energia no impacto ou queda de motocicleta. As m\u00e3os est\u00e3o envolvidas na maioria das atividades desempenhadas pelo ser humano, sendo um de seus principais instrumentos de trabalho, compromet\u00ea-la significa um trauma psicol\u00f3gico e f\u00edsico, al\u00e9m de econ\u00f4mico.<\/p>\n<p>Esse tipo de acidente n\u00e3o ocorre somente nas m\u00e3os, mas em todo o membro superior. Al\u00e9m das fraturas expostas, s\u00e3o bastante t\u00edpicos os casos de perda de subst\u00e2ncia, isto \u00e9, ocorre a perda de tecidos e h\u00e1 necessidade de se reconstruir a integridade do membro, necessitando em muitos casos de t\u00e9cnica microcir\u00fargica.<\/p>\n<p>\u00a0&#8220;Em qualquer acidente, a primeira provid\u00eancia \u00e9 estancar o sangramento atrav\u00e9s de uma compress\u00e3o do local onde est\u00e1 sangrando&#8221;, explica o Dr. Luiz Kimura da Associa\u00e7\u00e3o brasileira de Cirurgia da M\u00e3o. Evitar o uso de torniquetes ou tentar fechar a art\u00e9ria ou veia que est\u00e1 sangrando com uma pin\u00e7a ou qualquer instrumento. Isto danifica o vaso e impede a realiza\u00e7\u00e3o de diversos procedimentos. Nos casos de amputa\u00e7\u00f5es de &#8216;partes&#8217;, colocar a parte amputada em um saco com soro fisiol\u00f3gico limpo e colocar este saco em ambiente resfriado com gelo. Isto aumenta a sobrevida da parte amputada sem causar queimaduras pelo contato direto com o gelo.<\/p>\n<p>Ao menos 50% das m\u00e3os mutiladas no Brasil poderiam ser preservadas se o primeiro atendimento cir\u00fargico fosse especializado. O socorro mal conduzido gera graves sequelas ao acidentado, podendo causar incapacidade funcional irrevers\u00edvel e, \u00e0s vezes, at\u00e9 amputa\u00e7\u00e3o. Por isso, a import\u00e2ncia de se procurar um especialista em cirurgia da m\u00e3o, em casos de acidente no local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O feriado de 2 de novembro se aproxima, e com ele as estat\u00edstica de estradas lotadas e acidentes de tr\u00e2nsito, tamb\u00e9m, aumentam em todo pa\u00eds. Por isso, a Associa\u00e7\u00e3o Brasileira de Cirurgia da M\u00e3o desenvolveu a Campanha Nacional de Preven\u00e7\u00e3o \u00e0 Acidentes e Traumas da M\u00e3o, que faz um alerta para a import\u00e2ncia do cuidado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-15386","post","type-post","status-publish","format-standard","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15386"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15386\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}