{"id":15331,"date":"2009-10-26T19:43:10","date_gmt":"2009-10-26T23:43:10","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15331"},"modified":"2009-10-26T19:43:10","modified_gmt":"2009-10-26T23:43:10","slug":"previsao-do-tempo-na-regiao-centro-oeste-de-27-a-2910","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-centro-oeste-de-27-a-2910\/15331","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Centro-Oeste de 27 a 29\/10"},"content":{"rendered":"<p>Previs\u00e3o do tempo Centro-Oeste 27\/10\/2009: No noroeste de MT: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Nas demais \u00e1reas da Regi\u00e3o: nublado com pancadas de chuva a qualquer hora do dia. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 38C no noroeste de MT. Temperatura m\u00ednima: 18C no sul de MS.<\/p>\n<p>28\/10\/2009: No centro-sul de MS: sol com varia\u00e7\u00e3o de nuvens e uma pequena possibilidade de pancadas de chuva. No norte de MS: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Nas demais \u00e1reas da Regi\u00e3o: nublado com pancadas de chuva a qualquer hora. As temperaturas estar\u00e3o em eleva\u00e7\u00e3o em MS.\u00a0<\/p>\n<p>Tend\u00eancia: No centro-sudoeste de MS: predom\u00ednio de sol. Em GO e no leste de MT: nublado com pancadas de chuva a qualquer hora do dia. No norte de MS e no centro-oeste de MT: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Nas demais \u00e1reas de MS: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo Centro-Oeste 27\/10\/2009: No noroeste de MT: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Nas demais \u00e1reas da Regi\u00e3o: nublado com pancadas de chuva a qualquer hora do dia. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 38C no noroeste de MT. Temperatura m\u00ednima: 18C no sul de MS. 28\/10\/2009: No centro-sul [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[327],"tags":[],"class_list":{"0":"post-15331","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-clima","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15331"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15331\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}