{"id":15218,"date":"2009-10-26T11:12:04","date_gmt":"2009-10-26T15:12:04","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15218"},"modified":"2009-10-26T11:12:04","modified_gmt":"2009-10-26T15:12:04","slug":"pais-antecipa-em-tres-anos-o-uso-de-combustivel-com-5-de-biodiesel","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/pais-antecipa-em-tres-anos-o-uso-de-combustivel-com-5-de-biodiesel\/15218","title":{"rendered":"Pa\u00eds antecipa em tr\u00eas anos o uso de combust\u00edvel com 5% de biodiesel"},"content":{"rendered":"<p>A partir de janeiro de 2010, todos os carros movidos a \u00f3leo diesel no Brasil ter\u00e3o de utilizar uma mistura de 5% de <strong>biodiesel<\/strong> em seu combust\u00edvel. O an\u00fancio foi feito na \u00faltima sexta-feira (23) pelo presidente Luiz In\u00e1cio Lula da Silva, que decidiu antecipar em tr\u00eas anos a obrigatoriedade do uso da mistura, mais conhecida como B5. A medida deve elevar a produ\u00e7\u00e3o de biodiesel para 2,4 bilh\u00f5es de litros no pr\u00f3ximo ano, refor\u00e7ando a posi\u00e7\u00e3o do Pa\u00eds na lideran\u00e7a mundial em energias renov\u00e1veis em escala comercial.\u00a0<\/p>\n<p>A nova mistura ajudar\u00e1 o Pa\u00eds a reduzir a importa\u00e7\u00e3o de diesel, combust\u00edvel mais caro e poluente. O Conselho Nacional de Pol\u00edtica Energ\u00e9tica (CNPE) j\u00e1 havia aprovado a eleva\u00e7\u00e3o do percentual de mistura de 2% para 3%, em julho de 2008, e de 3% para 4%, a partir de julho de 2009. Essas medidas possibilitaram o desenvolvimento dessa nova ind\u00fastria que est\u00e1 se consolidando no Pa\u00eds.<\/p>\n<p>Capacidade instalada &#8211; Hoje, as 43 usinas instaladas em todas as regi\u00f5es do Brasil ter\u00e3o a garantia da exist\u00eancia de um mercado cada vez maior. A capacidade instalada \u00e9 mais do que suficiente para o B5, 3,6 bilh\u00f5es de litros\/ano, e 92% com Selo Combust\u00edvel Social, que \u00e9 o instrumento utilizado pelo governo federal para propiciar a participa\u00e7\u00e3o combinada da agricultura familiar e do agroneg\u00f3cio na cadeia produtiva do biodiesel.<\/p>\n<p>&#8220;Se formos cuidadosos, podemos chegar a B20. As locomotivas j\u00e1 s\u00e3o testadas e produzidas para B20, e a ind\u00fastria automobil\u00edstica j\u00e1 est\u00e1 testando o B20&#8221;, afirmou o presidente.<\/p>\n<p>De acordo com o ministro de Minas e Energia e presidente do Conselho Nacional de Pol\u00edtica Energ\u00e9tica (CNPE), Edison Lob\u00e3o, a determina\u00e7\u00e3o do governo representa um grande avan\u00e7o no Programa Nacional de Produ\u00e7\u00e3o e Uso do Biodiesel. &#8220;Passaremos a ter um combust\u00edvel limpo nos centros urbanos e nas rodovias que ao mesmo tempo gera emprego e renda para a popula\u00e7\u00e3o mais carente com a agricultura familiar&#8221;, afirmou o ministro.<\/p>\n<p>Mistura B5:<\/p>\n<p>&#8211; A antecipa\u00e7\u00e3o poder\u00e1 colocar o Brasil como 2\u00ba maior produtor mundial, somente atr\u00e1s da Alemanha (hoje somos 4\u00ba: 1\u00ba Alemanha, 2\u00ba Estados Unidos e 3\u00ba Fran\u00e7a).<br \/>\n&#8211; H\u00e1 capacidade instalada suficiente (3,6 bilh\u00f5es de litros\/ano), sendo que 92% t\u00eam Selo Combust\u00edvel Social. S\u00e3o 43 usinas com a seguinte distribui\u00e7\u00e3o regional de capacidade: N=5%, NE=19%, CO=33%, SE=18% e S=25%.<br \/>\n&#8211; Mesmo aplicando-se um fator de seguran\u00e7a de 20%, que limita a oferta a 2,9 bilh\u00f5es de litros\/ano (80% de 3,6), a capacidade \u00e9 mais do que suficiente.<br \/>\n&#8211; O desempenho dos produtores nos leil\u00f5es \u00e9 positivo. A performance de entrega est\u00e1 acima de 95%. N\u00e3o h\u00e1 mais problemas de entrega que aconteceram no passado.<br \/>\n&#8211; O mercado de distribui\u00e7\u00e3o est\u00e1 preparado para operar com B5.<br \/>\n&#8211; Este momento de decis\u00e3o do B5 contribui para balizar corretamente o plantio na nova safra, a se iniciar em breve, inclusive para propiciar que as usinas fa\u00e7am mais contratos com a agricultura familiar.<br \/>\n&#8211; Os fabricantes de ve\u00edculos, motores e pe\u00e7as j\u00e1 d\u00e3o garantia para B5.<br \/>\n&#8211; O impacto no pre\u00e7o ao consumidor ser\u00e1 pequeno (+0,5%) e compat\u00edvel com a pr\u00f3pria oscila\u00e7\u00e3o semanal de pre\u00e7os de posto a posto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de janeiro de 2010, todos os carros movidos a \u00f3leo diesel no Brasil ter\u00e3o de utilizar uma mistura de 5% de biodiesel em seu combust\u00edvel. O an\u00fancio foi feito na \u00faltima sexta-feira (23) pelo presidente Luiz In\u00e1cio Lula da Silva, que decidiu antecipar em tr\u00eas anos a obrigatoriedade do uso da mistura, mais [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":["post-15218","post","type-post","status-publish","format-standard","category-brasil","category-economia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15218"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15218\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}