{"id":15173,"date":"2009-10-24T15:57:18","date_gmt":"2009-10-24T19:57:18","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15173"},"modified":"2009-10-24T15:57:18","modified_gmt":"2009-10-24T19:57:18","slug":"estreia-de-michael-jackson-e-projeta-brasil-no-cinemark","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/estreia-de-michael-jackson-e-projeta-brasil-no-cinemark\/15173","title":{"rendered":"Estr\u00e9ia de Michael Jackson e Projeta Brasil no Cinemark"},"content":{"rendered":"<p>O filme <strong>Michael Jackson<\/strong>\u00b4s THIS IS IT tem estr\u00e9ia prevista na rede Cinemark para o dia 28 de Outubro, e oferecer\u00e1 aos f\u00e3s e amantes da m\u00fasica do mundo inteiro imagens raras dos bastidores enquanto o artista criava e ensaiava para seus shows esgotados que se realizariam a partir de julho na 02 Arena, em Londres. O filme foi montado a partir de mais de 100 horas de imagens dos bastidores e de Michael Jackson ensaiando v\u00e1rias m\u00fasicas para o show.<\/p>\n<p>MICHAEL JACKSON\u00b4S THIS IS IT<\/p>\n<p>Elenco: Michael Jackson<\/p>\n<p>Dire\u00e7\u00e3o: Kenny Ortega<\/p>\n<p>G\u00eanero: Document\u00e1rio<\/p>\n<p>Distribuidora: Columbia Tristar<\/p>\n<p>Na segunda-feira (09\/11) o Cinemark do Shopping Mueller exibe filmes nacionais, com ingressos custando apenas R$2,00 na comemora\u00e7\u00e3o dos 10 anos do <strong>Projeta Brasil <\/strong>Cinemark. Este dia ser\u00e1 dedicado exclusivamente \u00e0 exibi\u00e7\u00e3o de filmes nacionais, em seus mais variados g\u00eaneros: com\u00e9dia, fic\u00e7\u00e3o, romance e document\u00e1rio.<\/p>\n<p>Desde 2000, a Rede Cinemark reserva uma segunda-feira de novembro para se dedicar exclusivamente ao cinema nacional. Toda a verba da venda dos ingressos \u00e9 revertida para projetos ligados \u00e0 ind\u00fastria cinematogr\u00e1fica, como premia\u00e7\u00e3o de longas e curtas-metragem, apoio a festivais, restaura\u00e7\u00e3o de c\u00f3pias, realiza\u00e7\u00e3o de campanhas e outros. Esta iniciativa \u00e9 uma homenagem \u00e0 produ\u00e7\u00e3o nacional e uma forma de aproximar o p\u00fablico de cinema dos filmes brasileiros. Com esta a\u00e7\u00e3o o p\u00fablico j\u00e1 chegou a 1,4 milh\u00e3o de espectadores.<\/p>\n<p>Entre os longas-metragens desta edi\u00e7\u00e3o est\u00e3o t\u00edtulos como &#8220;Se Eu Fosse Voc\u00ea 2&#8221; e &#8220;Tempos de Paz&#8221;, de Daniel Filho; &#8220;Os Normais 2 &#8211; A Noite Mais Maluca de Todas&#8221;, de Jos\u00e9 Alvarenga Jr.; &#8220;O Contador de Hist\u00f3rias&#8221;, de Luiz Villa\u00e7a; &#8220;Feliz Natal&#8221;, de Selton Mello; e &#8220;A Mulher Invis\u00edvel&#8221;, de Cl\u00e1udio Torres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O filme Michael Jackson\u00b4s THIS IS IT tem estr\u00e9ia prevista na rede Cinemark para o dia 28 de Outubro, e oferecer\u00e1 aos f\u00e3s e amantes da m\u00fasica do mundo inteiro imagens raras dos bastidores enquanto o artista criava e ensaiava para seus shows esgotados que se realizariam a partir de julho na 02 Arena, em [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-15173","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15173"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15173\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}