{"id":15131,"date":"2009-10-23T17:23:36","date_gmt":"2009-10-23T21:23:36","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=15131"},"modified":"2009-10-23T17:23:36","modified_gmt":"2009-10-23T21:23:36","slug":"previsao-do-tempo-na-regiao-sul-de-24-a-2610","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-sul-de-24-a-2610\/15131","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Sul de 24 a 26\/10"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo<\/strong> Sul 24\/10\/2009: No sul e no sudoeste do RS: nublado com chuva pela manh\u00e3 passando a sol com varia\u00e7\u00e3o de nuvens. No centro-oeste do RS, de SC e no noroeste do PR: poss\u00edveis temporais. No centro e no noroeste do PR, no nordeste do RS e no sudeste de SC: sol com varia\u00e7\u00e3o de nuvens e pancadas de chuva \u00e0 tarde. No leste de SC: sol com varia\u00e7\u00e3o de nuvens e pancadas de chuva \u00e0 noite. Nas demais \u00e1reas do PR: sol entre poucas nuvens. As temperaturas m\u00e1ximas estar\u00e3o em decl\u00ednio no RS. Temperatura m\u00e1xima: 32C no norte do PR. Temperatura m\u00ednima: 10C no sul do RS.<\/p>\n<p>25\/10\/2009: No litoral norte do RS e no litoral sul de SC: nublado com chuva a qualquer hora. No sul e no sudoeste do RS: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva. No centro e no noroeste do RS: sol com varia\u00e7\u00e3o de nuvens. No leste do PR: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva \u00e0 tarde. Nas demais \u00e1reas do PR: nublado com pancadas de chuva a qualquer hora do dia. Nas demais \u00e1reas da Regi\u00e3o: tempo inst\u00e1vel com varia\u00e7\u00e3o de nuvens e chuva a qualquer hora do dia. As temperaturas estar\u00e3o baixas na Regi\u00e3o.<\/p>\n<p>Tend\u00eancia: No litoral norte de SC e no leste do PR: nublado com chuva a qualquer hora do dia. No leste de SC: tempo inst\u00e1vel com varia\u00e7\u00e3o de nuvens e chuva a qualquer hora do dia. No norte do PR: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas. No centro-oeste do RS: sol entre poucas nuvens. Nas demais \u00e1reas da Regi\u00e3o: sol com varia\u00e7\u00e3o de nuvens. As temperaturas m\u00e1ximas estar\u00e3o em eleva\u00e7\u00e3o. Nos pr\u00f3ximos dois dias haver\u00e1 sol entre poucas nuvens na maior parte da Regi\u00e3o Sul.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo Sul 24\/10\/2009: No sul e no sudoeste do RS: nublado com chuva pela manh\u00e3 passando a sol com varia\u00e7\u00e3o de nuvens. No centro-oeste do RS, de SC e no noroeste do PR: poss\u00edveis temporais. No centro e no noroeste do PR, no nordeste do RS e no sudeste de SC: sol com [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[327],"tags":[],"class_list":{"0":"post-15131","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-clima","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=15131"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/15131\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=15131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=15131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=15131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}