{"id":14985,"date":"2009-10-23T11:32:29","date_gmt":"2009-10-23T15:32:29","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14985"},"modified":"2009-10-23T11:32:29","modified_gmt":"2009-10-23T15:32:29","slug":"drenagem-linfatica-manual-durante-a-gestacao","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/drenagem-linfatica-manual-durante-a-gestacao\/14985","title":{"rendered":"Drenagem linf\u00e1tica manual durante a gesta\u00e7\u00e3o"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/gravida4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14986\" title=\"gravida\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/gravida4-249x187.jpg\" alt=\"gravida\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gravida4-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Durante a <strong>gesta\u00e7\u00e3o<\/strong>, alguns fatores como o \u00fatero pressionando as veias, o aumento da progesterona e o sedentarismo facilitam o excesso de ac\u00famulo de l\u00edquido no organismo da mulher. Eles causam sintomas de cansa\u00e7o, sensa\u00e7\u00e3o de pernas pesadas e p\u00e9s inchados. Para reduzir esse ac\u00famulo de l\u00edquidos, o tratamento mais recomendado \u00e9 a <strong>drenagem linf\u00e1tica<\/strong> manual.<\/p>\n<p>Durante a gravidez, momento m\u00e1gico para a mulher, o acompanhamento com um obstetra \u00e9 fundamental. Portanto, exames de rotina, atividades f\u00edsicas, acompanhamento nutricional e alimenta\u00e7\u00e3o saud\u00e1vel s\u00e3o medidas importantes nessa fase.<\/p>\n<p>E para complementar a qualidade e bem-estar da mulher, as sess\u00f5es de drenagem linf\u00e1tica s\u00e3o muito importantes tamb\u00e9m para alguns cuidados que garantem a sa\u00fade e o bem-estar da m\u00e3e e do beb\u00ea. Essa t\u00e9cnica ajuda na redu\u00e7\u00e3o do excesso de l\u00edquido, eliminando tamb\u00e9m dejetos provenientes do metabolismo celular. Desta forma, a drenagem desintoxica o corpo da gestante.<\/p>\n<p>Al\u00e9m do efeito drenante, que restabelece uma circula\u00e7\u00e3o correta, essa atividade tamb\u00e9m estimula o sistema imunol\u00f3gico, melhorando a defesa do organismo.<\/p>\n<p>\u00c9 muito importante ressaltar que a drenagem deve ser realizada por um fisioterapeuta ou por um profissional com conhecimentos da anatomia e fisiologia, pois se realizada de forma errada, al\u00e9m de n\u00e3o surtir efeito, pode provocar hematomas e piorar o incha\u00e7o do corpo.<\/p>\n<p>DRA. T\u00c2NIA ANTONIALLI &#8211; www.drenagem.com.br<\/p>\n<p>Especialista em Fisioterapia Dermato-Funcional pelo Conselho Brasileiro Cultural e Cientifico de Fisioterapia (CBF), e em Sa\u00fade da Mulher no Climat\u00e9rio pela USP, T\u00e2nia Antonialli \u00e9 graduada em Fisioterapia pela Universidade Bandeirante de S\u00e3o Paulo. Atua na \u00e1rea fisioterapeutica h\u00e1 7 anos, e utiliza tecnologia de ponta com produtos e instrumentos importantes para a sa\u00fade e o bem-estar do cliente. Sua cl\u00ednica est\u00e1 localizada em Moema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a gesta\u00e7\u00e3o, alguns fatores como o \u00fatero pressionando as veias, o aumento da progesterona e o sedentarismo facilitam o excesso de ac\u00famulo de l\u00edquido no organismo da mulher. Eles causam sintomas de cansa\u00e7o, sensa\u00e7\u00e3o de pernas pesadas e p\u00e9s inchados. Para reduzir esse ac\u00famulo de l\u00edquidos, o tratamento mais recomendado \u00e9 a drenagem linf\u00e1tica [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-14985","post","type-post","status-publish","format-standard","category-brasil","entry","has-post-thumbnail","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14985"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14985\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}