{"id":14948,"date":"2009-10-23T02:53:11","date_gmt":"2009-10-23T06:53:11","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14948"},"modified":"2009-10-22T23:46:40","modified_gmt":"2009-10-23T03:46:40","slug":"previsao-do-tempo-%e2%80%93-boletim-indica-chuva-forte-nesta-sexta-feira-2310","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-%e2%80%93-boletim-indica-chuva-forte-nesta-sexta-feira-2310\/14948","title":{"rendered":"Previs\u00e3o do tempo \u2013 boletim indica chuva forte nesta sexta-feira (23\/10)"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/previsaotempo0909.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11051\" title=\"previsaotempo0909\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/previsaotempo0909.jpg\" alt=\"previsaotempo0909\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsaotempo0909.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsaotempo0909-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Previs\u00e3o do tempo <\/strong>\u2013 a <strong>meteorologia<\/strong> alerta que nesta sexta-feira (<strong>23\/10<\/strong>), uma zona de converg\u00eancia de umidade provocar\u00e1 pancadas de chuva de forma localmente forte no ES, sul da BA, norte, centro, leste e oeste de MG, GO, DF, norte de MS e MT. \u00c1reas de instabilidade causadas pelo calor e umidade elevados provocar\u00e3o pancadas de chuva no AC, RO, no sul, centro, oeste e norte do AM, sul do PA, RR e TO. Uma massa de ar seco deixar\u00e1 o dia com pouca nebulosidade nas demais \u00e1reas do PA, no leste\/nordeste do AM, no AP e grande parte da Regi\u00e3o Nordeste.<\/p>\n<p>A previs\u00e3o do tempo tamb\u00e9m indica que, no sul de MS, norte de SP, sul e oeste da BA e sul de MG haver\u00e1 sol com aumento de nebulosidade e pancadas de chuva. Em grande parte do RJ o tempo ser\u00e1 inst\u00e1vel, sendo que no norte haver\u00e1 pancadas de chuva. No sul e nordeste de SP o dia ser\u00e1 com varia\u00e7\u00e3o de nebulosidade. No litoral de SC e do PR o c\u00e9u estar\u00e1 nublado. No oeste do RS e de SC e no sudoeste do PR haver\u00e1 predom\u00ednio de sol. As temperaturas estar\u00e3o em eleva\u00e7\u00e3o no Sul.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente.\u00a0Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>Previs\u00e3o do tempo CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo \u2013 a meteorologia alerta que nesta sexta-feira (23\/10), uma zona de converg\u00eancia de umidade provocar\u00e1 pancadas de chuva de forma localmente forte no ES, sul da BA, norte, centro, leste e oeste de MG, GO, DF, norte de MS e MT. \u00c1reas de instabilidade causadas pelo calor e umidade elevados provocar\u00e3o pancadas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327,376],"tags":[],"class_list":{"0":"post-14948","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-clima","8":"category-clima-brasil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14948"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14948\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}