{"id":14833,"date":"2009-10-22T13:28:50","date_gmt":"2009-10-22T17:28:50","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14833"},"modified":"2009-10-22T13:28:50","modified_gmt":"2009-10-22T17:28:50","slug":"mantega-reservas-do-pais-vao-aumentar-com-extracao-do-petroleo-da-camada-pre-sal","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/mantega-reservas-do-pais-vao-aumentar-com-extracao-do-petroleo-da-camada-pre-sal\/14833","title":{"rendered":"Mantega: Reservas do pa\u00eds v\u00e3o aumentar com extra\u00e7\u00e3o do petr\u00f3leo da camada pr\u00e9-sal"},"content":{"rendered":"<p>O ministro da <strong>Fazenda<\/strong>, Guido <strong>Mantega<\/strong>, participou nesta quarta-feira (21\/10) de audi\u00eancia p\u00fablica na Comiss\u00e3o Especial do <strong>Pr\u00e9-Sal<\/strong>\/Petrobras na C\u00e2mara dos Deputados para detalhar a capitaliza\u00e7\u00e3o do pr\u00e9-sal, previsto no Projeto de Lei 5.941. O PL, uma das quatro propostas legislativas que tratam do pr\u00e9-sal, autoriza a Uni\u00e3o a ceder \u00e0 Petrobras o exerc\u00edcio das atividades de pesquisa e lavra de petr\u00f3leo em \u00e1reas n\u00e3o concedidas localizadas no pr\u00e9-sal, at\u00e9 o volume m\u00e1ximo de 5 bilh\u00f5es de barris de petr\u00f3leo.<\/p>\n<p>Durante sua apresenta\u00e7\u00e3o, Mantega destacou que a capitaliza\u00e7\u00e3o da Petrobras \u00e9 uma opera\u00e7\u00e3o segura, sem risco de perdas para a Uni\u00e3o ou para a estatal petrol\u00edfera. &#8220;\u00c9 segura para ambas as partes&#8221;, disse aos parlamentares. Segundo ele, nessa opera\u00e7\u00e3o n\u00e3o h\u00e1 imponderabilidade e ser\u00e3o feitas compensa\u00e7\u00f5es futuras para evitar perdas para a Uni\u00e3o ou a Petrobras.<\/p>\n<p>\u201cN\u00e3o tem incerteza. \u00c9 um jogo de ganha, ganha&#8221;, disse. Numa situa\u00e7\u00e3o hipot\u00e9tica, ele citou que se as reservas forem superiores ao valor estimado de 5 bilh\u00f5es de barris, a Petrobras ter\u00e1 de fazer a compensa\u00e7\u00e3o. Por outro lado, se forem inferiores, caber\u00e1 \u00e0 Uni\u00e3o compensar a Petrobras.<\/p>\n<p>Na avalia\u00e7\u00e3o do ministro, a capitaliza\u00e7\u00e3o \u00e9 o primeiro passo para o Pa\u00eds come\u00e7ar &#8220;a colocar a m\u00e3o&#8221; na riqueza que est\u00e1 no subsolo do pr\u00e9-sal em benef\u00edcio da popula\u00e7\u00e3o. Na pr\u00e1tica, disse, essas reservas refor\u00e7am as reservas internacionais brasileiras porque elas podem ser transformadas em riquezas. &#8220;O Brasil ser\u00e1 um pa\u00eds totalmente seguro&#8221;, disse.<\/p>\n<p>O ministro disse ainda que o governo cuidar\u00e1 para que n\u00e3o haja no Brasil a chamada \u201cdoen\u00e7a holandesa\u201d, que afeta pa\u00edses que t\u00eam muita reserva de g\u00e1s e petr\u00f3leo e come\u00e7am a ter grande fluxo de capital externo, com valoriza\u00e7\u00e3o excessiva da moeda nacional. \u201cQuando isso acontece voc\u00ea deprime a produ\u00e7\u00e3o interna e come\u00e7a a ampliar as importa\u00e7\u00f5es. Isso n\u00f3s n\u00e3o permitiremos\u201d, garantiu Mantega aos parlamentares.<\/p>\n<p>Para evitar esse movimento, o ministro disse que uma parte ou a totalidade dos recursos do pr\u00e9-sal v\u00e3o para um fundo que ter\u00e1 como objetivo regular o fluxo de d\u00f3lares provenientes da explora\u00e7\u00e3o da camada do pr\u00e9-sal. \u201cQuando houver a extra\u00e7\u00e3o, teremos fluxo maior de moeda forte (d\u00f3lar). Podemos aplicar esse dinheiro l\u00e1 fora e tirar a press\u00e3o forte do d\u00f3lar sobre a economia dom\u00e9stica\u201d.<\/p>\n<p>O ministro estimou ainda que a explora\u00e7\u00e3o da camada pr\u00e9-sal poder\u00e1 ampliar em at\u00e9 US$ 400 bilh\u00f5es ou US$ 600 bilh\u00f5es as reservas internacionais do Brasil, hoje no patamar de US$ 230 bilh\u00f5es. \u201cO Brasil ser\u00e1 um pa\u00eds totalmente seguro. E esses d\u00f3lares poder\u00e3o ser utilizados tamb\u00e9m em ben\u00e9fico da popula\u00e7\u00e3o. Poderemos usar uma parcela disso para acelerar os avan\u00e7os na educa\u00e7\u00e3o, em projetos sociais, que \u00e9 uma prioridade do governo, e para equilibrar o or\u00e7amento\u201d, acrescentou.\u00a0<\/p>\n<p>O ministro explicou que o governo ter\u00e1 de enviar um projeto de lei ao Congresso autorizando a transfer\u00eancia da aliena\u00e7\u00e3o das reservas e, em seguida, a Petrobras ter\u00e1 de divulgar uma nota ao mercado informando que est\u00e1 adquirindo esses direitos. Conforme Mantega, ao todo, o processo da capitaliza\u00e7\u00e3o deve durar 90 dias.<\/p>\n<p>De acordo com o ministro, os acionistas minorit\u00e1rios da Petrobras ser\u00e3o avisados da transa\u00e7\u00e3o, que \u00e9 de grande monta, mas n\u00e3o dever\u00e3o exercer plenamente o direito de acompanhar a capitaliza\u00e7\u00e3o da empresa. &#8220;Eles t\u00eam direito de exercer at\u00e9 60% da opera\u00e7\u00e3o desse aumento de capital. Ter\u00e3o 30 dias de prazo para decidir isso, mas provavelmente n\u00e3o exercer\u00e3o porque \u00e9 muito dinheiro&#8221;.<\/p>\n<p>Fonte: Assessoria de Comunica\u00e7\u00e3o Social &#8211; GMF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Fazenda, Guido Mantega, participou nesta quarta-feira (21\/10) de audi\u00eancia p\u00fablica na Comiss\u00e3o Especial do Pr\u00e9-Sal\/Petrobras na C\u00e2mara dos Deputados para detalhar a capitaliza\u00e7\u00e3o do pr\u00e9-sal, previsto no Projeto de Lei 5.941. O PL, uma das quatro propostas legislativas que tratam do pr\u00e9-sal, autoriza a Uni\u00e3o a ceder \u00e0 Petrobras o exerc\u00edcio das [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7],"tags":[],"class_list":["post-14833","post","type-post","status-publish","format-standard","category-brasil","category-economia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14833"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14833\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}