{"id":14597,"date":"2009-10-20T00:20:34","date_gmt":"2009-10-20T04:20:34","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14597"},"modified":"2009-10-19T23:01:47","modified_gmt":"2009-10-20T03:01:47","slug":"previsao-do-tempo-indica-continuidade-de-chuva-em-grande-parte-do-pais","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-indica-continuidade-de-chuva-em-grande-parte-do-pais\/14597","title":{"rendered":"Previs\u00e3o do tempo indica continuidade de chuva em grande parte do Pa\u00eds"},"content":{"rendered":"<p><strong><span style=\"font-weight: normal;\"><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/previsaotempo1109.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11316\" title=\"previsaotempo1109\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/previsaotempo1109.jpg\" alt=\"previsaotempo1109\" width=\"150\" height=\"113\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsaotempo1109.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsaotempo1109-148x112.jpg 148w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/span>Previs\u00e3o do tempo<\/strong> &#8211; nesta ter\u00e7a-feira (<strong>20\/10<\/strong>), a <strong>meteorologia<\/strong> indica que haver\u00e1 muitas nuvens e condi\u00e7\u00f5es para pancadas de chuva que poder\u00e3o ser localmente forte por conta de uma Zona de Converg\u00eancia de Umidade entre o centro-sul da Regi\u00e3o Sudeste, o que inclui o sul de MG, RJ, Tri\u00e2ngulo Mineiro e grande parte de SP, sobre o Centro-Oeste e no sul da regi\u00e3o amaz\u00f4nica. O calor e a umidade ser\u00e3o respons\u00e1veis por pancadas de chuva em grande parte das demais \u00e1reas da Regi\u00e3o Norte, mas de forma isolada. Esperam-se ventos variando de moderados as fortes entre o litoral do RJ e do ES. O tempo estar\u00e1 inst\u00e1vel no litoral da Regi\u00e3o Sul, com varia\u00e7\u00e3o de nebulosidade no interior ga\u00facho e catarinense e possibilidade de pancadas de chuva isoladas no leste, nordeste e norte do PR. Sol entre poucas nuvens em grande parte do Nordeste, com possibilidade de pancadas de chuva no oeste da BA e no sul do MA e do PI.<\/p>\n<p>Previs\u00e3o do tempo <strong>Regi\u00e3o Centro-Oeste<\/strong><\/p>\n<p>20\/10\/2009: Em grande parte da Regi\u00e3o: sol entre muitas nuvens e pancadas isoladas de chuva. Em algumas localidades poder\u00e1 chover forte. As temperaturas seguir\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 38C no norte de MS. Temperatura m\u00ednima: 15C no sul de MS.<\/p>\n<p>Previs\u00e3o do tempo <strong>Regi\u00e3o Nordeste<\/strong><\/p>\n<p>20\/10\/2009: No sul e leste da BA: sol com nebulosidade vari\u00e1vel. No oeste da Regi\u00e3o: sol com varia\u00e7\u00e3o de nuvens e uma pequena possibilidade de pancadas de chuva a qualquer hora. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 37C no norte do PI. Temperatura m\u00ednima: 16C no centro-sul da BA.<\/p>\n<p>Previs\u00e3o do tempo <strong>Regi\u00e3o Norte<\/strong><\/p>\n<p>20\/10\/2009: Em grande parte do TO, no leste do PA e do AP: sol com nebulosidade vari\u00e1vel e pancadas isoladas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre muitas nuvens e pancadas isoladas de chuva. Em algumas localidades poder\u00e1 chover forte. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 40C no nordeste do PA. Temperatura m\u00ednima: 16C no nordeste de RR.<\/p>\n<p>Previs\u00e3o do tempo <strong>Regi\u00e3o Sudeste<\/strong><\/p>\n<p>20\/10\/2009: No sul de SP: sol entre nebulosidade vari\u00e1vel e pancadas de chuva. No norte de MG: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva. Nas demais \u00e1reas da Regi\u00e3o: sol entre muitas nuvens com pancadas isoladas de chuva que ser\u00e3o localmente forte. Ficar\u00e1 ventoso no litoral da Regi\u00e3o. As temperaturas m\u00e1ximas estar\u00e3o amenas no leste da Regi\u00e3o. Temperatura m\u00e1xima: 34C no nordeste de MG. Temperatura m\u00ednima: 12C no leste de SP.<\/p>\n<p>Previs\u00e3o do tempo <strong>Regi\u00e3o Sul<\/strong><\/p>\n<p>20\/10\/2009: No leste do RS e de SC: tempo inst\u00e1vel com curtos per\u00edodos de sol e chuva a qualquer hora do dia. No norte e leste do PR: sol entre nebulosidade vari\u00e1vel e com pancadas de chuva isolada a qualquer hora do dia, que poder\u00e1 ser forte em algumas localidades. Nas demais \u00e1reas do PR: sol com nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva. Nas demais \u00e1reas de SC e do RS: sol entre nuvens. As temperaturas m\u00e1ximas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 32C norte do PR. Temperatura m\u00ednima: 10C na Serra Geral.<\/p>\n<p>Previs\u00e3o do tempo CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo &#8211; nesta ter\u00e7a-feira (20\/10), a meteorologia indica que haver\u00e1 muitas nuvens e condi\u00e7\u00f5es para pancadas de chuva que poder\u00e3o ser localmente forte por conta de uma Zona de Converg\u00eancia de Umidade entre o centro-sul da Regi\u00e3o Sudeste, o que inclui o sul de MG, RJ, Tri\u00e2ngulo Mineiro e grande parte de SP, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327,376],"tags":[],"class_list":["post-14597","post","type-post","status-publish","format-standard","category-brasil","category-clima","category-clima-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14597"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14597\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}