{"id":145393,"date":"2018-07-04T16:39:12","date_gmt":"2018-07-04T19:39:12","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145393"},"modified":"2018-07-04T17:06:43","modified_gmt":"2018-07-04T20:06:43","slug":"resumo-novela-as-aventuras-de-poliana-05-07-luisa-diz-para-poliana-que-ela-vai-ficar-na-escola","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-as-aventuras-de-poliana-05-07-luisa-diz-para-poliana-que-ela-vai-ficar-na-escola\/145393","title":{"rendered":"Resumo novela \u201cAs Aventuras de Poliana\u201d 05\/07: Guilherme tenta falar com a m\u00e3e"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-141221\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/As-Aventuras-de-Poliana-novela-SBT-resumo-capitulo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/As-Aventuras-de-Poliana-novela-SBT-resumo-capitulo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/As-Aventuras-de-Poliana-novela-SBT-resumo-capitulo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cAs Aventuras de Poliana\u201d 05\/07 <\/em><\/strong>: no cap\u00edtulo 037(*) da novela \u201cAs Aventuras de Poliana\u201d, resumo de quinta-feira, 05 de julho, Gleyce v\u00ea Ciro na escola e enquanto conversam, Gabriela passa e cumprimenta ele. Gleyce estranha os dois se conhecerem. Ciro diz que conhece a menina por ser filha do dono da transportadora. M\u00e1rio, Gael e Ben\u00edcio deixam uma c\u00e2mera ligada na escola para tentar filma o fantasma. Sr. Pendleton vai at\u00e9 a empresa O11O para conhecer tudo no local. Ele \u00e9 o investidor que Otto havia avisado Roger. Durante a visita, Roger diz ser muito amigo de Otto. Sr. Pendleton fica encantado em conhecer S\u00e9rgio e Joana. Roger fica inconformado que antes do homem ir embora diga n\u00e3o lembrar seu nome. Marcelo parabeniza Luigi pelo filme feito pelo menino.<\/p>\n<p> Ruth chama Filipa at\u00e9 a diretoria, conversa com ela e faz uma carta de reclama\u00e7\u00e3o que ela deve trazer assinada pelos pais. A diretora afirma ainda que se ela n\u00e3o mudar seu comportamento ter\u00e1 que tomar uma atitude mais severa. Mirela vai falar com Raquel e diz ser besteira elas fingirem ser amigas de outras pessoas sendo que n\u00e3o s\u00e3o. As duas fazem as pazes. Mirela pede uma roupa emprestada para o show. Raquel diz que Mirela \u00e9 interesseira e a expulsa de sua casa. Marcelo tenta conversar com Lu\u00edsa para repensar a decis\u00e3o de tirar Poliana da escola. <\/p>\n<p>Jo\u00e3o vai at\u00e9 a casa de Poliana para tentar animar a amiga. Hel\u00f4 vai at\u00e9 a casa de Lu\u00edsa pedir para que ela n\u00e3o tire Poliana da escola. Kessya e Luigi tamb\u00e9m v\u00e3o at\u00e9 a mans\u00e3o, assim como o menino Jo\u00e3o. Poliana diz para todos que ir\u00e1 pensar se muda de ideia ou n\u00e3o. Guilherme tenta falar com a m\u00e3e, que sumiu e n\u00e3o atende o celular. Lu\u00edsa diz para Poliana que n\u00e3o vai mais tirar ela da escola. Poliana e seus amigos comemoram.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cAs Aventuras de Poliana\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Poliana \u00e9 uma menina extrovertida e de bom cora\u00e7\u00e3o que viajava o Brasil com seus pais, Lorenzo e Alice, no grupo circense Trupe Vagalume. Aos onze anos a garota v\u00ea seu mundo desabar quando seus pais falecem e ela tem que ir morar em S\u00e3o Paulo com sua tia Lu\u00edsa, uma mulher rica e severa, a qual ela n\u00e3o conhecia e que n\u00e3o queria cuidar dela, embora sinta que \u00e9 sua obriga\u00e7\u00e3o pela alma de sua irm\u00e3. Apesar do jeito da rigidez da tia, Poliana decide ter uma vis\u00e3o positiva e inabal\u00e1vel da vida, mesmo nos momentos de dificuldade, tentando levar um pouco de felicidade para a vida de cada um dos seus novos amigos e vizinhos, como o Sr. Pendleton, um homem rico e infeliz por nunca ter tido filhos. Ela vai estudar no col\u00e9gio de Ruth, uma diretora de bom cora\u00e7\u00e3o que a ajuda a se adaptar, mas tem que lidar com as vilanias de Mirela, garota mais velha que n\u00e3o aceita perder a popularidade para uma novata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cAs Aventuras de Poliana\u201d 05\/07 : no cap\u00edtulo 037(*) da novela \u201cAs Aventuras de Poliana\u201d, resumo de quinta-feira, 05 de julho, Gleyce v\u00ea Ciro na escola e enquanto conversam, Gabriela passa e cumprimenta ele. Gleyce estranha os dois se conhecerem. Ciro diz que conhece a menina por ser filha do dono da transportadora. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":141221,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[477,379,372,343],"tags":[441],"class_list":["post-145393","post","type-post","status-publish","format-standard","has-post-thumbnail","category-as-aventuras-de-poliana","category-novelas","category-sbt","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/As-Aventuras-de-Poliana-novela-SBT-resumo-capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145393"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/141221"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}