{"id":145360,"date":"2018-07-04T00:33:24","date_gmt":"2018-07-04T03:33:24","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145360"},"modified":"2018-07-05T19:11:12","modified_gmt":"2018-07-05T22:11:12","slug":"novela-luz-do-sol-resumo-05-07-isabela-revela-segredo-de-nina-a-belquiss","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-luz-do-sol-resumo-05-07-isabela-revela-segredo-de-nina-a-belquiss\/145360","title":{"rendered":"Novela \u201cLuz do Sol\u201d resumo 05\/07: Isabela revela segredo de Nina a Belquiss"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-131397\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cLuz do Sol\u201d resumo 05\/07<\/em><\/strong>: no capitulo 124 (*) da novela \u201cLuz do Sol\u201d, quinta-feira, 05 de julho, Quico mostra \u00e0 Drica o osso humano que encontraram em Angra. Alice conta que encontraram tamb\u00e9m outro osso, que entregaram \u00e0 Bernardo. Eliana recebe liga\u00e7\u00e3o de Vicente e diz a William que vai se encontrar com o filho. Laura pergunta a Paulo como v\u00e3o as investiga\u00e7\u00f5es do assassinato de Mascote e ele diz que tudo leva a crer que Agenor de Souza \u00e9 o autor do crime. A reportagem de TV sobre o caso de Drica \u00e9 exibida. Ver\u00f4nica diz a Hilde que descobriu que Tom \u00e9 o homem da vida dela e vai se casar com ele. Pedro procura Isabela e diz que precisam conversar sobre algo muito importante. Eliana chega ao local combinado e procura por Vicente, quando de repente surge Agenor. <\/p>\n<p>Agenor vai tirar satisfa\u00e7\u00f5es com Eliana por ela ter arrumado outro homem. Pedro confessa a Isabela que est\u00e1 apaixonado por Nina. Ele pede desculpas, mas ela se nega a aceitar. Lorena diz a Valadares que pretende bagun\u00e7ar a cabe\u00e7a de Drica. Agenor diz a Eliana que ainda a ama, e implora que ela n\u00e3o o abandone por outro homem. Isabela pede que Pedro suma de sua vida e atira a alian\u00e7a longe. Juarez revela a Yvonne suas suspeitas sobre Wandinha e decide contar tudo a Maria Eug\u00eania. Isabela tem um ataque de f\u00faria e quebra tudo em seu quarto. <\/p>\n<p>Agenor d\u00e1 a entender que William n\u00e3o \u00e9 quem Eliana pensa e afirma que ele pode ser o mandante do seq\u00fcestro de Drica. Eliana pede para Agenor sumir e diz que da pr\u00f3xima vez que ele a procurar, vai chamar a pol\u00edcia. Milena convida Clemente a passar a noite com ela. Eliana vai tirar satisfa\u00e7\u00f5es com Vicente sobre o encontro arranjado com Antenor. Juarez conta a Maria Eugenia que esteve em Angra para tentar descobrir o que se passa com Wandinha. Willian confessa ao pai que tem medo de se envolver com Eliana e sofrer uma nova decep\u00e7\u00e3o. Cherry procura Odete e prop\u00f5e a ela gravar um CD demo.   <\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cLuz do Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Luz do Sol \u00e9 uma telenovela brasileira produzida pela RecordTV e exibida originalmente entre 21 de mar\u00e7o e 20 de novembro de 2007, em 210 epis\u00f3dios. \u00c9 uma obra representativa na hist\u00f3ria da teledramaturgia da emissora n\u00e3o apenas por isso, mas por ter sido a primeira novela escrita por Ana Maria Moretzsohn para a Record, trazendo a colabora\u00e7\u00e3o de texto de Gustavo Reiz, Ana Clara Santiago, Emilio Boechat e Denise Crispun, com dire\u00e7\u00e3o de Ivan Zettel, F\u00e1bio Junqueira e Jos\u00e9 Carlos Pieri, sob dire\u00e7\u00e3o geral de Ivan Zettel. <\/p>\n<p>Luma Costa interpreta a protagonista, Drica, que foi sequestrada misteriosamente durante sua festa de cinco anos e apareceu afogada em uma praia de pescadores, no qual foi criada sob o nome de Maria Rosa com uma vida humilde. Lu\u00edza Tom\u00e9 e Giuseppe Orist\u00e2nio interpretam os pais biol\u00f3gicos da garota, sendo que enquanto ele desistiu da busca da filha ap\u00f3s 11 anos, ela nunca deixou de busc\u00e1-la, o que acabou ruindo com seu casamento. Patr\u00edcia Fran\u00e7a e Leonardo Br\u00edcio interpretam os pais adotivos de Drica, que criaram-na como filha, sem terem lhe contaram a verdade. Thiago Gagliasso, Paloma Duarte, Petr\u00f4nio Gontijo, Juliana Silveira, Bete Coelho, Floriano Peixoto, Karen Marinho e Let\u00edcia Colin interpretam os demais pap\u00e9is centrais da trama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cLuz do Sol\u201d resumo 05\/07: no capitulo 124 (*) da novela \u201cLuz do Sol\u201d, quinta-feira, 05 de julho, Quico mostra \u00e0 Drica o osso humano que encontraram em Angra. Alice conta que encontraram tamb\u00e9m outro osso, que entregaram \u00e0 Bernardo. Eliana recebe liga\u00e7\u00e3o de Vicente e diz a William que vai se encontrar com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-145360","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145360"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/131397"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}