{"id":14533,"date":"2009-10-19T20:14:29","date_gmt":"2009-10-20T00:14:29","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14533"},"modified":"2009-10-19T20:14:29","modified_gmt":"2009-10-20T00:14:29","slug":"como-prevenir-e-diagnosticar-a-osteoporose","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/como-prevenir-e-diagnosticar-a-osteoporose\/14533","title":{"rendered":"Como prevenir e diagnosticar a osteoporose"},"content":{"rendered":"<p>A <strong>osteoporose<\/strong> pode ser definida como osso poroso e \u00e9 uma doen\u00e7a que se caracteriza pela baixa densidade do esqueleto, resultante da perda gradual e cont\u00ednua do c\u00e1lcio armazenado nos ossos. A osteoporose \u00e9 menos comum no homem do que na mulher e atinge principalmente pessoas idosas. Isso porque uma descalcifica\u00e7\u00e3o \u00f3ssea acontece naturalmente com o envelhecimento, fazendo com que os ossos percam sua rigidez normal e se tornem menos resistente a traumas, ficando, por consequ\u00eancia, mais vulner\u00e1veis a fraturas, especialmente no colo de f\u00eamur, coluna vertebral e punho.<\/p>\n<p>Segundo dados do IBGE &#8211; Instituto Brasileiro de Geografia e Estat\u00edstica, a popula\u00e7\u00e3o brasileira vem envelhecendo nos \u00faltimos anos. A incid\u00eancia desta doen\u00e7a deve, ent\u00e3o, crescer no Brasil. Uma reflex\u00e3o que vem \u00e0 tona neste 20 de outubro, Dia Mundial da Osteoporose.<\/p>\n<p>Segundo a Organiza\u00e7\u00e3o Mundial de Sa\u00fade, um ter\u00e7o das mulheres brancas com mais de 65 anos s\u00e3o portadoras dessa doen\u00e7a. Nos Estados Unidos a osteoporose \u00e9 respons\u00e1vel por mais de 1,5 milh\u00f5es de fraturas por ano. Segundo Mauro Scharf, endocrinologista da DASA, que \u00e9 representada em Mato Grosso pelas marcas Cedic\/Cedilab, um dos principais problemas \u00e9 o diagn\u00f3stico da osteoporose, j\u00e1 que ela \u00e9 uma doen\u00e7a silenciosa e n\u00e3o apresenta sintomas at\u00e9 que aconte\u00e7am as fraturas \u00f3sseas. &#8220;Como normalmente os pacientes s\u00f3 percebem que t\u00eam a doen\u00e7a quando acontece a primeira fratura, \u00e9 pouco comum conseguirmos um diagn\u00f3stico precoce, que seria feito pela densitometria \u00f3ssea, avalia\u00e7\u00e3o cl\u00ednica e pesquisa dos fatores de risco&#8221;, alerta o m\u00e9dico.<\/p>\n<p>Scharf explica que a densitometria \u00f3ssea avalia a densidade dos ossos, em especial a coluna, o quadril e os pulsos. \u00c9 um exame com baixa exposi\u00e7\u00e3o \u00e0 radia\u00e7\u00e3o, que n\u00e3o provoca dor ou desconforto. Ele consegue identificar sinais precoces de osteoporose ou de enfraquecimento \u00f3sseo. A Funda\u00e7\u00e3o Americana de Osteoporose recomenda a realiza\u00e7\u00e3o da densitometria \u00f3ssea de forma preventiva principalmente para mulheres acima de 65 anos, com menopausa precoce ou p\u00f3s-menopausa, em uso de medicamentos cortic\u00f3ides, com diabetes tipo 1, doen\u00e7a hep\u00e1tica, renal ou de tire\u00f3ide.<\/p>\n<p>O m\u00e9dico diz que tamb\u00e9m \u00e9 recomendada para a terceira idade a realiza\u00e7\u00e3o de avalia\u00e7\u00e3o cl\u00ednica rotineira e de hemograma, provas de atividade inflamat\u00f3ria, eletroforese de prote\u00ednas, c\u00e1lcio, f\u00f3sforo, fosfatase alcalina e c\u00e1lcio na urina de 24 horas. Esses exames possibilitam afastar as causas mais comuns de doen\u00e7as que podem causar osteoporose como mieloma m\u00faltiplo, hiperparatiroidismo, osteomal\u00e1cia, hipercalci\u00faria, algumas anemias, doen\u00e7as reum\u00e1ticas e neoplasias. O c\u00e1lcio na urina de 24 horas, al\u00e9m de informar sobre outras causas, possibilita avaliar o balan\u00e7o de c\u00e1lcio.<\/p>\n<p>Para prevenir a doen\u00e7a, Dr. Mauro Scharf d\u00e1 as seguintes dicas: a primeira \u00e9 a alimenta\u00e7\u00e3o rica em c\u00e1lcio. O recomendado \u00e9 800 mg\/dia para adultos jovens e 1.500 mg\/dia para idosos. O c\u00e1lcio pode ser obtido de latic\u00ednios (leite desnatado, iogurtes e queijos magros), verduras verde-escuras como br\u00f3colis, couve, espinafre e escarola ou por suplementa\u00e7\u00e3o medicamentosa prescrita pelo m\u00e9dico.<\/p>\n<p>A segunda dica s\u00e3o os exerc\u00edcios f\u00edsicos, que ajudam a regular e fortalecer a musculatura. O exerc\u00edcio promove o fortalecimento muscular, al\u00e9m de melhorar o equil\u00edbrio, os reflexos e a marcha, reduzindo os riscos de quedas no idoso em aproximadamente 25%.<\/p>\n<p>A terceira dica \u00e9 a vitamina D, formada na pele pela a\u00e7\u00e3o dos raios solares ou obtida atrav\u00e9s dos alimentos (leite e seus derivados, \u00f3leo de f\u00edgado de bacalhau, peixes e camar\u00f5es). A vitamina D \u00e9 a respons\u00e1vel pela absor\u00e7\u00e3o do c\u00e1lcio que ocorre no intestino. A orienta\u00e7\u00e3o do m\u00e9dico \u00e9 incluir 15 minutos de banho de sol (at\u00e9 10h da manh\u00e3 e ap\u00f3s 17h) na rotina di\u00e1ria.<\/p>\n<p>Por fim, o endocrinologista lembra que a ingest\u00e3o alimentar adequada de c\u00e1lcio e a pr\u00e1tica de atividade f\u00edsica devem ter in\u00edcio na inf\u00e2ncia, onde ocorrem a forma\u00e7\u00e3o dos h\u00e1bitos alimentares e a defini\u00e7\u00e3o da massa \u00f3ssea. &#8220;O organismo mant\u00e9m constante uma taxa de c\u00e1lcio e, quando a fonte externa \u00e9 inadequada, o c\u00e1lcio \u00e9 extra\u00eddo dos ossos para manter os n\u00edveis sangu\u00edneos dentro dos valores normais. Por isso, temos que estar atentos desde pequenos&#8221;, finaliza.<\/p>\n<p>Alimentos x Quantidade de C\u00e1lcio<\/p>\n<p>Leite de vaca pasteurizado 1 copo (200 ml) = 246 mg de C\u00e1lcio;<\/p>\n<p>Queijo prato 15 gramas (uma fatia fina) = 126 mg de C\u00e1lcio;<\/p>\n<p>Iogurte 1 pote (200 mg) = 240 mg de C\u00e1lcio;<\/p>\n<p>Espinafre 100 gramas = 79 mg de C\u00e1lcio;<\/p>\n<p>Escarola 100 gramas = 81 mg de C\u00e1lcio;<\/p>\n<p>Folhas de ab\u00f3bora 100 gramas = 477 mg de C\u00e1lcio;<\/p>\n<p>Sardinha 30 gramas (uma por\u00e7\u00e3o pequena) = 86 mg de C\u00e1lcio.<\/p>\n<p>Sobre a DASA :<\/p>\n<p>A DASA \u00e9 a maior empresa de medicina diagn\u00f3stica na Am\u00e9rica Latina em termos de receita bruta e popula\u00e7\u00e3o e a quinta maior rede no mundo. Com mais de 12 mil colaboradores, atende aproximadamente 55 mil pacientes por dia em 328 unidades. Processa em m\u00e9dia, 6,5 milh\u00f5es de exames por m\u00eas. Oferece mais de tr\u00eas mil tipos de exames de an\u00e1lises cl\u00ednicas e diagn\u00f3stico por imagem. Atualmente, o grupo \u00e9 formado por 20 marcas em treze estados &#8211; Delboni Auriemo, Lavoisier e Maximagem, em S\u00e3o Paulo ; Bronstein, L\u00e2mina e MedImagem, no Rio de Janeiro; Club DA, em S\u00e3o Paulo e Rio de Janeiro; Pasteur e Exame, em Bras\u00edlia; MedLabor, em Bras\u00edlia e Tocantins; Curitiba Santa Casa e Frischmann Aisengart, em Curitiba ; Laborat\u00f3rio \u00c1lvaro, em Cascavel e Foz do Igua\u00e7u; Cient\u00edficaLab, no Esp\u00edrito Santo, Minas Gerais, S\u00e3o Paulo e Rio de Janeiro; Image Memorial, em Salvador; VITA L\u00e2mina, em Florian\u00f3polis; Atalaia, em Goi\u00e1s; Cedic e Cedilab no Mato Grosso; e LabPasteur e Unimagem, em Fortaleza.<\/p>\n<p>*Informa\u00e7\u00f5es atualizadas em maio de 2009.<\/p>\n<p>Sobre o Cedic e Cedilab Medicina Diagn\u00f3stica<\/p>\n<p>O Cedic e Cedilab nasceram, respectivamente, h\u00e1 14 e 9 anos no Mato Grosso e s\u00e3o considerados refer\u00eancias para o segmento de medicina diagn\u00f3stica. Juntos, somam mais de 200 colaboradores em nove unidades, que atuam na capital e na regi\u00e3o metropolitana. S\u00e3o realizados mais de tr\u00eas mil tipos de exames de an\u00e1lises cl\u00ednicas e diagn\u00f3sticos por imagem que contemplam servi\u00e7os e solu\u00e7\u00f5es diferenciados com qualidade, rapidez e alto padr\u00e3o de atendimento, como a coleta domiciliar. H\u00e1 dois anos, a marca \u00e9 escolhida como o prestador de servi\u00e7os em medicina diagn\u00f3stica mais lembrado pela popula\u00e7\u00e3o na regi\u00e3o por meio do pr\u00eamio Top of Mind, realizado pela revista RDM, com os institutos Newcomdates Tecnologia da informa\u00e7\u00e3o e Full Time Pesquisa de Mercado . O Cedic e Cedilab fazem parte da DASA, maior empresa de medicina diagn\u00f3stica na Am\u00e9rica Latina e quinta maior no mundo. Para mais informa\u00e7\u00f5es: www.cedic.com.br e www.cedilab.com.br .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A osteoporose pode ser definida como osso poroso e \u00e9 uma doen\u00e7a que se caracteriza pela baixa densidade do esqueleto, resultante da perda gradual e cont\u00ednua do c\u00e1lcio armazenado nos ossos. A osteoporose \u00e9 menos comum no homem do que na mulher e atinge principalmente pessoas idosas. Isso porque uma descalcifica\u00e7\u00e3o \u00f3ssea acontece naturalmente com [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-14533","post","type-post","status-publish","format-standard","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14533"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14533\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}