{"id":14531,"date":"2009-10-19T20:15:56","date_gmt":"2009-10-20T00:15:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14531"},"modified":"2009-10-19T20:15:56","modified_gmt":"2009-10-20T00:15:56","slug":"projeto-interativo-de-nutricao-ensina-adolescentes-a-se-alimentar","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/projeto-interativo-de-nutricao-ensina-adolescentes-a-se-alimentar\/14531","title":{"rendered":"Projeto interativo de nutri\u00e7\u00e3o ensina adolescentes a se alimentar"},"content":{"rendered":"<p>Centro de Atendimento da<strong> UNIFESP<\/strong> prepara oficina com abordagem pratica de acordo com necessidades espec\u00edficas. O Centro de Atendimento e <strong>Apoio ao Adolescente (CAAA)<\/strong> da UNIFESP (Universidade Federal de S\u00e3o Paulo) desenvolveu um projeto interativo de <strong>orienta\u00e7\u00e3o nutricional<\/strong> para oferecer aos jovens alternativas para que cada um aprenda a suprir suas necessidades espec\u00edficas em diferentes situa\u00e7\u00f5es. A Oficina dos Sabores \u00e9 uma abordagem pr\u00e1tica, com prepara\u00e7\u00e3o de receitas e manipula\u00e7\u00e3o de alimentos em diversas combina\u00e7\u00f5es, de acordo com temas pr\u00e9-selecionados.<\/p>\n<p>Quinzenalmente, uma aula \u00e9 oferecida para pequenos grupos que se revezam. A cada m\u00eas um tema diferente \u00e9 abordado, definido conforme as maiores dificuldades encontradas nas consultas realizadas pelas nutricionistas respons\u00e1veis pelo projeto, Abykeyla Mellisse Tosatti, Carla Fiorillo e Patr\u00edcia Ghattas, sob coordena\u00e7\u00e3o de Maria Aparecida Zanetti Passos, que verificaram que tais problemas n\u00e3o s\u00e3o solucionados apenas com a consulta nutricional. Entre os temas est\u00e3o a import\u00e2ncia do caf\u00e9 da manh\u00e3, petiscos saud\u00e1veis, temperos e saladas, os benef\u00edcios das frutas, aproveitamento integral dos alimentos e a rela\u00e7\u00e3o fritura e sa\u00fade. &#8220;Os adolescentes costumam pular refei\u00e7\u00f5es e n\u00e3o h\u00e1 equil\u00edbrio em rela\u00e7\u00e3o \u00e0 qualidade ou \u00e0 quantidade dos alimentos. \u00c9 preciso apresentar as op\u00e7\u00f5es e ensin\u00e1-los a manter esse equil\u00edbrio dentro da realidade deles&#8221;, afirma Carla Fiorillo.<\/p>\n<p>Na adolesc\u00eancia, \u00e9 comum a falta de c\u00e1lcio, entre outras car\u00eancias de nutrientes, pois os h\u00e1bitos alimentares desse grupo geralmente n\u00e3o incluem a ingest\u00e3o da quantidade di\u00e1ria indicada de leite e derivados, que s\u00e3o substitu\u00eddos, muitas vezes, por refrigerantes e sucos artificiais. Al\u00e9m de ser um mineral importante para a forma\u00e7\u00e3o da massa \u00f3ssea, o c\u00e1lcio ajuda o organismo no processo de contra\u00e7\u00e3o muscular. Da mesma forma, manter os n\u00edveis de zinco nesta fase contribui para o crescimento e o desenvolvimento imunol\u00f3gico. No caso das meninas, o in\u00edcio do ciclo menstrual pode provocar a perda de ferro e causar anemia ou fraqueza.<\/p>\n<p>Baseado em especificidades como estas, o projeto Oficina dos Sabores \u00e9 elaborado em torno da corre\u00e7\u00e3o de h\u00e1bitos e n\u00e3o a partir de dietas fechadas ou restritivas. &#8220;Os participantes receber\u00e3o uma apostila com informa\u00e7\u00f5es sobre os alimentos e seus nutrientes para levar para casa e incorporar ao seu dia-a-dia&#8221;, detalha Patr\u00edcia Ghattas. Al\u00e9m da Oficina dos Sabores, no CAAA os adolescentes podem passar por avalia\u00e7\u00e3o m\u00e9dica e acompanhamento multidisciplinar que inclui fonoaudiologia, psicologia e educa\u00e7\u00e3o f\u00edsica.<\/p>\n<p>As inscri\u00e7\u00f5es para a Oficina dos Sabores s\u00e3o gratuitas, est\u00e3o abertas e devem ser feitas pelo telefone (11) 5576-4360, de segunda \u00e0 sexta-feira, das 8h \u00e0s16h.<\/p>\n<p>Sobre a UNIFESP:<\/p>\n<p>Criada em 1933 por um grupo de m\u00e9dicos reunidos em uma sociedade sem fins lucrativos, a Escola Paulista de Medicina (EPM) foi federalizada em 1956 e, em 1994, transformada em Universidade Federal de S\u00e3o Paulo (Unifesp), primeira universidade especializada em sa\u00fade no Pa\u00eds, abrigando em seu curr\u00edculo de gradua\u00e7\u00e3o os cursos de Medicina, Enfermagem, Fonoaudiologia e Tecnologias Oft\u00e1lmica e Radiol\u00f3gica.<\/p>\n<p>Em 2005, iniciou-se o projeto de expans\u00e3o com a cria\u00e7\u00e3o do campus Baixada Santista. Em 2007, dando seguimento ao processo de amplia\u00e7\u00e3o, a Unifesp implantou os campi de Diadema, Guarulhos e S\u00e3o Jos\u00e9 dos Campos. O ambicioso processo de expans\u00e3o fez com que a Universidade saltasse de um para cinco campi e de cinco para 26 cursos. Com os novos campi, a Institui\u00e7\u00e3o deixou de atuar exclusivamente no campo da sa\u00fade, inaugurando cursos nas \u00e1reas de humanas (Guarulhos) e exatas (S\u00e3o Jos\u00e9 dos Campos) e Biol\u00f3gicas (Diadema). Atualmente, a Institui\u00e7\u00e3o conta com 4.545 alunos matriculados nos cursos de gradua\u00e7\u00e3o, al\u00e9m de 17.400 nos cursos de p\u00f3s-gradua\u00e7\u00e3o e demais programas de especializa\u00e7\u00e3o, resid\u00eancia, mestrado e doutorado. A Unifesp oferece 883 docentes, sendo que 93% possuem t\u00edtulo de doutor, um percentual que marca a qualidade de ensino oferecida pela maior universidade federal do Pa\u00eds. Em 1940 a universidade, ent\u00e3o Escola Paulista de Medicina, inaugurou o Hospital S\u00e3o Paulo, primeiro hospital-escola do Pa\u00eds, hoje localizado dentro Campus S\u00e3o Paulo, instalado no bairro Vila Clementino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centro de Atendimento da UNIFESP prepara oficina com abordagem pratica de acordo com necessidades espec\u00edficas. O Centro de Atendimento e Apoio ao Adolescente (CAAA) da UNIFESP (Universidade Federal de S\u00e3o Paulo) desenvolveu um projeto interativo de orienta\u00e7\u00e3o nutricional para oferecer aos jovens alternativas para que cada um aprenda a suprir suas necessidades espec\u00edficas em diferentes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-14531","post","type-post","status-publish","format-standard","category-brasil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14531"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14531\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}