{"id":145277,"date":"2018-07-02T23:35:08","date_gmt":"2018-07-03T02:35:08","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145277"},"modified":"2018-07-04T17:10:15","modified_gmt":"2018-07-04T20:10:15","slug":"novela-bicho-do-mato-resumo-04-07-lili-ordena-que-ruth-e-pedro-deixem-a-sua-casa","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-bicho-do-mato-resumo-04-07-lili-ordena-que-ruth-e-pedro-deixem-a-sua-casa\/145277","title":{"rendered":"Novela \u201cBicho do Mato\u201d resumo 04\/07: Lili ordena que Ruth e Pedro deixem a sua casa"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-119859\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cBicho do Mato\u201d resumo 04\/07<\/em><\/strong>: no capitulo 221 (*) da novela \u201cBicho do Mato\u201d, quarta-feira, 04 de julho, Lili ordena que Ruth e Pedro deixem a sua casa, mas Ruth lembra que aquele apartamento tamb\u00e9m \u00e9 dela e se recusa a sair. Com cinismo, Ruth nega que tenha tentado matar Cec\u00edlia e que nem sequer sabia que ela estava no Pantanal. E que, se Lili estiver incomodada, que saia ela e leve consigo os seus amiguinhos (S\u00edlvia, Em\u00edlio e Roberto). Cec\u00edlia fica decepcionada com o casal, mas Juba lembra que n\u00e3o tem jeito: s\u00f3 v\u00e3o se livrar do garimpo quando Ramalho e Tavinho forem presos. Eduardo vai \u00e0 delegacia: Mariano ganha a liberdade e s\u00f3 pensa em se encontrar com a sua morena.<\/p>\n<p>Yara conta a Jaci que voltar\u00e3o para o Rio com Eduardo, para tranq\u00fcilizar a av\u00f3 B\u00e1rbara. Cajuru chega com a novidade: Carlos e Juliana tomar\u00e3o conta do garimpo. Decepcionadas com a atitude dos dois, Dani, M\u00e1rcia e Rafa v\u00e3o at\u00e9 o garimpo tentar convenc\u00ea-los a voltar para o Rio, mas Iru prefere esperar para saber o que pretendem. Tini\u00e1 adianta que, provavelmente, Juliana e Carlos est\u00e3o vendidos. Hilton encontra Cl\u00e1udia na rua e lhe d\u00e1 de presente um par de algemas para \u2018apimentar\u2019 o namoro. Ela detesta o presente e lembra que, se Hilton n\u00e3o largar a vida de bandido, quem vai acabar algemado \u00e9 ele.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cBicho do Mato\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Em \u201cBicho do Mato\u201d, Juba (Andr\u00e9 Bankoff) foi criado desde pequeno apenas pelo pai, Fernando (Jairo Mattos), na Fazenda Boa Esperan\u00e7a, localizada no centro do Pantanal, vivendo harmoniosamente junto \u00e0 natureza e \u00e0 aldeia ind\u00edgena dos Guapor\u00e1 \u2013 tribo da qual descende Ir\u00fa (Raphael Viana), seu melhor amigo, e Tini\u00e1 (Tha\u00eds Fersoza), que \u00e9 apaixonada por ele. Quem ajudou a cuidar dele foi Francisca (Angelina Muniz), cozinheira que sempre teve o rapaz como um filho e que est\u00e1 dividida entre o amor de Geraldo (S\u00e9rgio Reis) e Mariano (Almir Sater), pe\u00f5es da fazenda que a disputam a todo momento. <\/p>\n<p>A m\u00e3e do rapaz, Laura (Bia Seidl), o abandonou aos seis anos para morar na cidade do Rio de Janeiro e se casar com o ganancioso e inescrupuloso Ramalho (Jonas Bloch), que manda matar Fernando, visando usurpar as terras da fazenda e dos \u00edndios para explorar de uma mina de diamantes descoberta por ele. Paralelamente Juba conhece Cec\u00edlia (Renata Dominguez), uma jovem m\u00e9dica que est\u00e1 visitando o Pantanal e vive um fulminante romance com ele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cBicho do Mato\u201d resumo 04\/07: no capitulo 221 (*) da novela \u201cBicho do Mato\u201d, quarta-feira, 04 de julho, Lili ordena que Ruth e Pedro deixem a sua casa, mas Ruth lembra que aquele apartamento tamb\u00e9m \u00e9 dela e se recusa a sair. Com cinismo, Ruth nega que tenha tentado matar Cec\u00edlia e que nem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-145277","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145277"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/119859"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}