{"id":145160,"date":"2018-06-30T16:12:15","date_gmt":"2018-06-30T19:12:15","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145160"},"modified":"2018-06-30T16:12:15","modified_gmt":"2018-06-30T19:12:15","slug":"resumo-novela-segundo-sol-02-07-karen-se-apresenta-para-trabalhar-com-roberval","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-segundo-sol-02-07-karen-se-apresenta-para-trabalhar-com-roberval\/145160","title":{"rendered":"Resumo novela \u201cSegundo Sol\u201d 02\/07: Karen se apresenta para trabalhar com Roberval"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-140790\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>Resumo novela \u201cSegundo Sol\u201d 02\/07 no cap\u00edtulo 043(*) da novela \u201cSegundo Sol\u201d, resumo de segunda-feira, 02 de julho, Beto afirma a Cacau que a pol\u00edcia est\u00e1 atr\u00e1s de Luzia. Rosa termina o namoro com Valentim e Laureta castiga Galdino por ter ajudado Karola a separar os dois. Rochelle tenta se aproximar de Ac\u00e1cio. Roberval amea\u00e7a Laureta, que afirma n\u00e3o ter medo do empres\u00e1rio. Rochelle e Ac\u00e1cio se beijam na frente de Manuela, que decide usar drogas novamente. Luzia\/Ariella tenta afastar Manuela de Narciso, mas a menina ofende a DJ. Luzia afirma a Groa que Beto seria um bom pai para seus filhos. <\/p>\n<p>Beto pede que Karola fique em sua casa para cuidar de Valentim a seu lado. Remy questiona Dod\u00f4 sobre a paternidade de Badu, e chantageia o pai. Cacau e Groa sugerem que Luzia se afaste de uma vez por todas de Beto. Groa revela a Luzia que Pai Didico deseja lhe passar a administra\u00e7\u00e3o de seu terreiro. Dod\u00f4 passa mal com as provoca\u00e7\u00f5es de Remy, e Nan\u00e1 convoca Nestor para cuidar do marido. Karen se aplica para o emprego de governanta em uma mans\u00e3o, mas descobre que o dono da casa \u00e9 Roberval.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Globo, Novela \u201cSegundo Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Na novela \u201cSegundo Sol\u201d, Salvador, fim dos anos 90. O ax\u00e9 embala o Carnaval da Bahia. S\u00f3 que quem est\u00e1 em plena decad\u00eancia \u00e9 Beto Falc\u00e3o (Em\u00edlio Dantas), que estourou com o sucesso \u201cAx\u00e9 Pel\u00f4\u201d, hit que fez cantar um pa\u00eds inteiro em 94. Agora, o cach\u00ea vem devagar. E para pagar parte das d\u00edvidas da fam\u00edlia, aceita fazer uma pequena apresenta\u00e7\u00e3o em Aracaju. Numa mar\u00e9 de azar \u2013 que salvar\u00e1 sua vida -, Beto perde o voo e a apresenta\u00e7\u00e3o. O avi\u00e3o que ele pegaria cai, e o cantor \u00e9 dado como morto.<\/p>\n<p>A como\u00e7\u00e3o \u00e9 nacional. Do fracasso, Beto Falc\u00e3o reencontra a fama, mas dessa vez na categoria de mito. Em segredo, v\u00ea sua imagem ser ovacionada e os problemas financeiros da fam\u00edlia se solucionarem. Convencido pela namorada, Karola (Deborah Secco), cujo romance n\u00e3o anda l\u00e1 muito bem, e pelo irm\u00e3o interesseiro Remy (Vladimir Brichta), de que se manter \u201cmorto\u201d \u00e9 a melhor op\u00e7\u00e3o, ele deixa a cidade e se refugia na ilha de Boipor\u00e3. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cSegundo Sol\u201d 02\/07 no cap\u00edtulo 043(*) da novela \u201cSegundo Sol\u201d, resumo de segunda-feira, 02 de julho, Beto afirma a Cacau que a pol\u00edcia est\u00e1 atr\u00e1s de Luzia. Rosa termina o namoro com Valentim e Laureta castiga Galdino por ter ajudado Karola a separar os dois. Rochelle tenta se aproximar de Ac\u00e1cio. Roberval amea\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":140790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,375,474,343],"tags":[441],"class_list":["post-145160","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-globo","category-segundo-sol","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145160"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/140790"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}