{"id":145104,"date":"2018-06-29T10:11:09","date_gmt":"2018-06-29T13:11:09","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145104"},"modified":"2018-06-29T10:11:09","modified_gmt":"2018-06-29T13:11:09","slug":"resumo-novela-segundo-sol-30-06-beto-quer-que-cacau-revele-onde-esta-luzia","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-segundo-sol-30-06-beto-quer-que-cacau-revele-onde-esta-luzia\/145104","title":{"rendered":"Resumo novela \u201cSegundo Sol\u201d 30\/06: Beto quer que Cacau revele onde est\u00e1 Luzia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-140790\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>Resumo novela \u201cSegundo Sol\u201d 30\/06 no cap\u00edtulo 042(*) da novela \u201cSegundo Sol\u201d, resumo de s\u00e1bado, 30 de junho, Rosa declara guerra contra Karola, afasta Rochelle de Valentim e sai escondida com ele da festa. Dod\u00f4 pede que Gorete se afaste de Cl\u00f3vis. Karola vai \u00e0 casa dos pais de Rosa. Beto tenta conversar com Valentim sobre o seu namoro. Karola amea\u00e7a Rosa. Galdino foge de Nestor. Nan\u00e1 questiona Gorete sobre o pai de seu filho. Remy usa Badu para obter informa\u00e7\u00f5es sobre Gorete e confronta a massagista. Dod\u00f4 ofende Remy na frente de Beto e Ionan. Doralice reata com Ionan. Laureta descobre a arma\u00e7\u00e3o de Galdino e pune o ajudante. Manuela e Zefa apoiam Karen na decis\u00e3o de procurar emprego como governanta. Severo fala mal de Roberval para Edgar, sem perceber Zefa. Rosa pede para Valentim se afastar dela. Beto exige que Cacau revele o paradeiro de Luzia.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Globo, Novela \u201cSegundo Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Na novela \u201cSegundo Sol\u201d, Salvador, fim dos anos 90. O ax\u00e9 embala o Carnaval da Bahia. S\u00f3 que quem est\u00e1 em plena decad\u00eancia \u00e9 Beto Falc\u00e3o (Em\u00edlio Dantas), que estourou com o sucesso \u201cAx\u00e9 Pel\u00f4\u201d, hit que fez cantar um pa\u00eds inteiro em 94. Agora, o cach\u00ea vem devagar. E para pagar parte das d\u00edvidas da fam\u00edlia, aceita fazer uma pequena apresenta\u00e7\u00e3o em Aracaju. Numa mar\u00e9 de azar \u2013 que salvar\u00e1 sua vida -, Beto perde o voo e a apresenta\u00e7\u00e3o. O avi\u00e3o que ele pegaria cai, e o cantor \u00e9 dado como morto.<\/p>\n<p>A como\u00e7\u00e3o \u00e9 nacional. Do fracasso, Beto Falc\u00e3o reencontra a fama, mas dessa vez na categoria de mito. Em segredo, v\u00ea sua imagem ser ovacionada e os problemas financeiros da fam\u00edlia se solucionarem. Convencido pela namorada, Karola (Deborah Secco), cujo romance n\u00e3o anda l\u00e1 muito bem, e pelo irm\u00e3o interesseiro Remy (Vladimir Brichta), de que se manter \u201cmorto\u201d \u00e9 a melhor op\u00e7\u00e3o, ele deixa a cidade e se refugia na ilha de Boipor\u00e3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cSegundo Sol\u201d 30\/06 no cap\u00edtulo 042(*) da novela \u201cSegundo Sol\u201d, resumo de s\u00e1bado, 30 de junho, Rosa declara guerra contra Karola, afasta Rochelle de Valentim e sai escondida com ele da festa. Dod\u00f4 pede que Gorete se afaste de Cl\u00f3vis. Karola vai \u00e0 casa dos pais de Rosa. Beto tenta conversar com Valentim [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":140790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,375,474,343],"tags":[441],"class_list":["post-145104","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-globo","category-segundo-sol","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145104"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/140790"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}