{"id":145084,"date":"2018-06-29T00:31:12","date_gmt":"2018-06-29T03:31:12","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=145084"},"modified":"2018-06-29T00:31:12","modified_gmt":"2018-06-29T03:31:12","slug":"novela-bicho-do-mato-resumo-02-07-pedro-implora-para-que-ruth-solte-cecilia","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-bicho-do-mato-resumo-02-07-pedro-implora-para-que-ruth-solte-cecilia\/145084","title":{"rendered":"Novela \u201cBicho do Mato\u201d resumo 02\/07: Pedro implora para que Ruth solte Cec\u00edlia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-119859\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cBicho do Mato\u201d resumo 02\/07<\/em><\/strong>: no capitulo 219 (*) da novela \u201cBicho do Mato\u201d, segunda-feira, 02 de julho, Pedro chega e implora para que Ruth solte Cec\u00edlia e que v\u00e3o embora, pois logo Juba e os Guapor\u00e1s chegar\u00e3o ao acampamento. Brand\u00e3o liga para Tavinho, que marca encontro para trocar o diamante por Betinha. Mas, como n\u00e3o est\u00e1 com a pedra, Tavinho revela a Carlos e Juliana que vai matar Brand\u00e3o. Brand\u00e3o sai para encontrar Tavinho, mas, antes, discute com Z\u00e9 Diacho, achando que o comparsa est\u00e1 muito tranq\u00fcilo, sem medo de ele fugir com a pedra. Juba e sua turma atacam os jagun\u00e7os. Frederica fica nervosa quando Juliana e Carlos revelam que Tavinho ir\u00e1 matar Brand\u00e3o.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cBicho do Mato\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Em \u201cBicho do Mato\u201d, Juba (Andr\u00e9 Bankoff) foi criado desde pequeno apenas pelo pai, Fernando (Jairo Mattos), na Fazenda Boa Esperan\u00e7a, localizada no centro do Pantanal, vivendo harmoniosamente junto \u00e0 natureza e \u00e0 aldeia ind\u00edgena dos Guapor\u00e1 \u2013 tribo da qual descende Ir\u00fa (Raphael Viana), seu melhor amigo, e Tini\u00e1 (Tha\u00eds Fersoza), que \u00e9 apaixonada por ele. Quem ajudou a cuidar dele foi Francisca (Angelina Muniz), cozinheira que sempre teve o rapaz como um filho e que est\u00e1 dividida entre o amor de Geraldo (S\u00e9rgio Reis) e Mariano (Almir Sater), pe\u00f5es da fazenda que a disputam a todo momento.<\/p>\n<p>A m\u00e3e do rapaz, Laura (Bia Seidl), o abandonou aos seis anos para morar na cidade do Rio de Janeiro e se casar com o ganancioso e inescrupuloso Ramalho (Jonas Bloch), que manda matar Fernando, visando usurpar as terras da fazenda e dos \u00edndios para explorar de uma mina de diamantes descoberta por ele. Paralelamente Juba conhece Cec\u00edlia (Renata Dominguez), uma jovem m\u00e9dica que est\u00e1 visitando o Pantanal e vive um fulminante romance com ele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cBicho do Mato\u201d resumo 02\/07: no capitulo 219 (*) da novela \u201cBicho do Mato\u201d, segunda-feira, 02 de julho, Pedro chega e implora para que Ruth solte Cec\u00edlia e que v\u00e3o embora, pois logo Juba e os Guapor\u00e1s chegar\u00e3o ao acampamento. Brand\u00e3o liga para Tavinho, que marca encontro para trocar o diamante por Betinha. Mas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-145084","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/bicho_do_mato_novela_record_resumo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=145084"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/145084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/119859"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=145084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=145084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=145084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}