{"id":14498,"date":"2009-10-19T10:25:50","date_gmt":"2009-10-19T14:25:50","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14498"},"modified":"2009-10-19T10:25:50","modified_gmt":"2009-10-19T14:25:50","slug":"macarrao-uma-paixao-mundial","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/macarrao-uma-paixao-mundial\/14498","title":{"rendered":"Macarr\u00e3o: uma paix\u00e3o mundial"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/pasta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14499\" title=\"pasta\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/pasta-249x187.jpg\" alt=\"pasta\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/pasta-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>O <strong>macarr\u00e3o <\/strong>\u00e9 um alimento t\u00e3o popular no mundo que ganhou, h\u00e1 14 anos, uma data para ser festejado: 25 de outubro, Dia Mundial do Macarr\u00e3o. O Brasil, que \u00e9 o terceiro maior fabricante do mundo, ocupa a 12\u00aa posi\u00e7\u00e3o no ranking mundial e a 5\u00aa coloca\u00e7\u00e3o no Ranking das Am\u00e9ricas de consumo per capita, com 6,6 quilos\/ano. Os maiores consumidores per capita s\u00e3o It\u00e1lia, com 28 kg por habitante\/ano, e Venezuela, com 13 kg por habitante\/ano.<\/p>\n<p>De acordo com a Abima (Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de Massas Aliment\u00edcias), o Pa\u00eds tem um grande potencial para elevar o consumo de macarr\u00e3o. Isso se deve \u00e0 boa aceita\u00e7\u00e3o do produto nos lares brasileiros, ao pre\u00e7o baixo e \u00e0s suas caracter\u00edsticas nutricionais.<\/p>\n<p>Segundo Cl\u00e1udio Zan\u00e3o, diretor presidente da Abima, o macarr\u00e3o tem presen\u00e7a garantida na mesa do brasileiro, mas o que falta \u00e9 fazer com que o consumidor prove outros formatos e novas combina\u00e7\u00f5es de massa aliment\u00edcia e molho. S\u00f3 no Brasil s\u00e3o mais de 30 variedades. &#8220;A antiga receita dos tradicionais espaguete e fusilli com molho bolonhesa \u00e9 deliciosa, mas acaba cansando&#8221;, destaca.<\/p>\n<p>Para aumentar o consumo de macarr\u00e3o, a Abima tem promovido uma s\u00e9rie de a\u00e7\u00f5es, entre as quais se destaca a primeira edi\u00e7\u00e3o da &#8220;Rota 25 &#8211; Caminho do Macarr\u00e3o&#8221; que, entre 17 e 31 de outubro, est\u00e1 movimentando a capital paulista com a divulga\u00e7\u00e3o de pratos \u00e0 base de macarr\u00e3o. Dez importantes restaurantes de massas aliment\u00edcias de S\u00e3o Paulo est\u00e3o participando e cada um desenvolveu uma receita exclusiva para o evento.<\/p>\n<p>A iniciativa, criada para festejar o Dia Mundial do Macarr\u00e3o, \u00e9 um projeto piloto e a inten\u00e7\u00e3o dos organizadores \u00e9 que ela passe a ser realizada em outros Estados a partir do pr\u00f3ximo ano. O evento de S\u00e3o Paulo \u00e9 patrocinado pela Adria, Barilla, Petybon e Renata.<\/p>\n<p>O Dia Mundial do Macarr\u00e3o foi criado durante o primeiro congresso mundial sobre o alimento, que reuniu os principais fabricantes do mundo em Roma, na It\u00e1lia, em 1995. &#8220;Al\u00e9m de saboroso, macarr\u00e3o \u00e9 nutritivo e f\u00e1cil de preparar. Ele tamb\u00e9m tem a ver com fam\u00edlia e amigos reunidos em volta da mesa. \u00c9 por isso que ele \u00e9 uma paix\u00e3o e faz a alegria de muita gente&#8221;, destaca Claudio Zan\u00e3o.<br \/>\nEspaguet\u00f4metro<\/p>\n<p>Pelo terceiro ano consecutivo, a Abima promove em conjunto com as empresas associadas, uma a\u00e7\u00e3o de marketing para divulgar o Dia Mundial do Macarr\u00e3o ao p\u00fablico em geral e contribuir com o aumento do consumo per capita de massas aliment\u00edcias no Brasil.<\/p>\n<p>A a\u00e7\u00e3o &#8220;Comprou, Ganhou&#8221; acontece no ponto de venda e, al\u00e9m de despertar o interesse do consumidor, tem o objetivo de fidelizar as marcas participantes. A empresa associada oferece ao consumidor um brinde com a sua logomarca na compra de pacotes de macarr\u00e3o.<\/p>\n<p>Com os resultados alcan\u00e7ados com Porta Retrato Imantado (2007) e Pegador de Macarr\u00e3o (2008), os associados obtiveram um aumento de 25%, em m\u00e9dia, no volume de vendas.<\/p>\n<p>Tal crescimento motivou a Abima a buscar um brinde exclusivo para 2009, negociado e desenvolvido por fornecedor da CCA &#8211; Central de Compras Abima: o Espaguet\u00f4metro &#8211; utens\u00edlio que serve para medir a quantidade de espaguete que ser\u00e1 preparada de acordo com o n\u00famero de pessoas que se pretende servir.<\/p>\n<p>Massas secas<\/p>\n<p>O mercado brasileiro de massas \u00e9 representado por tr\u00eas categorias. As massas secas, do tipo espaguete, gravatinha e parafuso, representam 87% do consumo. O restante do setor \u00e9 representado por 10% de massas instant\u00e2neas e 3% de massas frescas, do tipo ravi\u00f3li e cappeletti.<\/p>\n<p>A ind\u00fastria brasileira produz 1,3 milh\u00e3o de toneladas\/ano, ficando atr\u00e1s apenas da It\u00e1lia e dos Estados Unidos que produzem 3 milh\u00f5es de toneladas e 2 milh\u00f5es de toneladas, respectivamente. O setor, que no Brasil gera 25 mil empregos diretos, registrou em 2008 um faturamento de R$ 5 bilh\u00f5es, o que representa um crescimento de 10% em rela\u00e7\u00e3o ao ano anterior. Nem mesmo a crise global, a depend\u00eancia da importa\u00e7\u00e3o de trigo e os reajustes no pre\u00e7o da mat\u00e9ria-prima sofridos nos \u00faltimos anos, afetaram a produ\u00e7\u00e3o e o consumo no Brasil.<\/p>\n<p>Devido \u00e0 importante participa\u00e7\u00e3o no mercado mundial de massas, o Pa\u00eds foi escolhido para ser a sede do IV World Pasta Congress, que acontece no Rio de Janeiro, em outubro de 2010.<\/p>\n<p>Sobre a Abima<\/p>\n<p>A Abima representa os fabricantes de massas aliment\u00edcias, p\u00e3es industriais e bolos no Brasil. Seus associados s\u00e3o respons\u00e1veis por mais de 85% do mercado nacional de macarr\u00e3o e 60% de p\u00e3es industrializados. A entidade ainda atua como prestadora de servi\u00e7os. Por meio de sua CCA &#8211; Central de Compras Abima, por exemplo, ela colaborou para redu\u00e7\u00e3o de 20% no custo de produ\u00e7\u00e3o de seus associados no ano passado, o que corresponde a R$ 2 milh\u00f5es. Outra preocupa\u00e7\u00e3o da associa\u00e7\u00e3o \u00e9 com a desonera\u00e7\u00e3o fiscal da ind\u00fastria de massas aliment\u00edcias e p\u00e3es industrializados. Uma das propostas em tramita\u00e7\u00e3o \u00e9 a redu\u00e7\u00e3o da contribui\u00e7\u00e3o do PIS\/Cofins que hoje \u00e9 de 9,25%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O macarr\u00e3o \u00e9 um alimento t\u00e3o popular no mundo que ganhou, h\u00e1 14 anos, uma data para ser festejado: 25 de outubro, Dia Mundial do Macarr\u00e3o. O Brasil, que \u00e9 o terceiro maior fabricante do mundo, ocupa a 12\u00aa posi\u00e7\u00e3o no ranking mundial e a 5\u00aa coloca\u00e7\u00e3o no Ranking das Am\u00e9ricas de consumo per capita, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-14498","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14498"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14498\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}