{"id":144969,"date":"2018-06-27T19:29:47","date_gmt":"2018-06-27T22:29:47","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144969"},"modified":"2018-06-29T15:54:38","modified_gmt":"2018-06-29T18:54:38","slug":"novela-luz-do-sol-resumo-29-06-agenor-encontra-caderno-de-fausto","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-luz-do-sol-resumo-29-06-agenor-encontra-caderno-de-fausto\/144969","title":{"rendered":"Novela \u201cLuz do Sol\u201d resumo 29\/06: Dr. Valadares vai \u00e0 casa de Maria Eugenia"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-131397\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cLuz do Sol\u201d resumo 29\/06<\/em><\/strong>: no capitulo 120 (*) da novela \u201cLuz do Sol\u201d, sexta-feira, 29 de junho, Yan faz uma liga\u00e7\u00e3o e pergunta como conseguir\u00e1 entrar no quarto de Isabela no meio da festa. Ele vai em dire\u00e7\u00e3o a um quarto, quando encontra Quico e disfar\u00e7a. Quando Quico sai, Yan entra no quarto de Isabela. Nina encontra o celular da m\u00e3e na cozinha e sai para entreg\u00e1-lo a ela. Leonardo e Zo\u00e9 se beijam. Belquiss pergunta se Marcelo est\u00e1 gostando da festa. Marcelo sai atr\u00e1s de Stella. Belquiss fica enciumada. Kayla chega \u00e0 festa e dan\u00e7a de forma espalhafatosa, causando desconforto. Convidados da festa cumprimentam Pedro, que est\u00e1 se sentindo constrangido com a situa\u00e7\u00e3o e s\u00f3 consegue pensar em Nina. Alice pergunta a Quico se eles tamb\u00e9m v\u00e3o ficar noivos. Odete e Rodolfo dan\u00e7am na festa. Bernardo promete a Drica que n\u00e3o vai deixar que nada os separe. Freddy discute com Kayla pois n\u00e3o queria que ela tivesse ido \u00e0 festa. Juarez questiona porque Freddy mora com Kayla, se n\u00e3o gosta dela. Yan pega um ba\u00fa debaixo da cama de Isabela e encontra um envelope com o DNA falso. Yvonne entra no quarto e surpreende Yan. William comenta com Eliana que achou Pedro tenso. Pedro vai at\u00e9 a sala de jantar e d\u00e1 de cara com Nina. Ela pergunta se ele conhece os noivos. Pedro fica nervoso e quer sair com Nina dali. Belquiss e Isabela entram na sala. Belquiss apresenta os noivos para Nina, que fica chocada e deixa cair uma bandeja no ch\u00e3o.<\/p>\n<p>Nina fica atordoada ao descobrir que Pedro \u00e9 o noivo de Isabela. Pedro se oferece para lev\u00e1-la para casa. Isabela acha que Pedro est\u00e1 exagerando. Nina se recupera e diz que faz quest\u00e3o de ficar na festa. Belquiss tira Pedro e Isabela da cozinha. Yan esconde o envelope debaixo da cama e disfar\u00e7a. Yvonee fica desconfiada e expulsa Yan do quarto de Isabela. Tom diz a Ver\u00f4nica que n\u00e3o \u00e9 gay e afirma que pode provar. Os dois se agarram. Bernardo v\u00ea como Pedro est\u00e1 preocupado e vai conversar com ele. Guiga diz a Georgi que \u00e9 muito dif\u00edcil mudar o mundo e conscientizar as pessoas sobre racismo. Pedro revela a Bernardo que a garota por quem ele se apaixonou est\u00e1 na festa e que ela j\u00e1 sabe que ele \u00e9 noivo de Isabela. Bernardo aconselha Pedro a decidir se ele quer ficar com Nina ou Isabela. Yan liga para Lorena e diz que j\u00e1 encontrou o que ela pediu. Nina se oferece para servir os convidados. Nina encontra Zo\u00e9 na festa e diz que est\u00e1 preparada para quebrar a cara de algu\u00e9m por l\u00e1. Marcelo e Stella brindam a felicidade das filhas Isabela e Drica. Marcelo tenta beijar Stella, que recua. Nina se aproxima de Pedro e Isabela e derruba de prop\u00f3sito o molho em cima de Pedro.<\/p>\n<p>Isabela fica irritada com a falta de cuidado de Nina. Pedro vai para o quarto de Isabela trocar a cal\u00e7a. Freddy agradece a Stella o convite para a festa. Stella diz a Freddy que ele n\u00e3o deveria ter vergonha de Kayla. Nina vai atr\u00e1s de Pedro no quarto de Isabela. Yvonne v\u00ea a cena e fica indignada. Pedro tenta se explicar com Nina e tranca a porta, ficando com a chave. Eles discutem e Nina diz que nunca mais quer v\u00ea-lo. Ela tenta sair do quarto, que est\u00e1 trancado. Yvonne conta a Juarez o que acabou de ver. Isabela chega e pergunta por Pedro. Os dois tentam disfar\u00e7ar e ela fica desconfiada. Belquiss est\u00e1 preocupada com o sumi\u00e7o repentino de Nina. Juarez encontra Bernardo e avisa que Pedro e Nina est\u00e3o no quarto de Isabela. Ele pede que Bernardo o ajude a entreter Isabela. Isabela sobe as escadas em dire\u00e7\u00e3o a seu quarto. Bernardo v\u00ea e chama por ela. Ele pede uma foto com ela, que concorda. Nina come\u00e7a a gritar por socorro, arranca a chave da m\u00e3o de Pedro e sai do quarto. Nina desce as escadas chorando. Freddy discute com Kayla. Yan entra de novo no quarto de Isabela e pega o envelope que tinha escondido. Marcelo oferece uma carona a Belquiss. Ela se oferece para dirigir, pois ele est\u00e1 de pileque. William recomenda a Bernardo que cuide do irm\u00e3o, que parece transtornado. Nina chora e desabafa com Cherry. Pedro, b\u00eabado, circula pela festa e mal consegue andar. Bernardo obriga Pedro a ir embora.<\/p>\n<p>Belquiss coloca Marcelo na cama, maliciosa. Ele pede para ela ficar e os dois se agarram. Yan entrega o envelope com o exame falso para Lorena, e os dois se beijam. Lorena vai \u00e0 casa de Dr. Valadares e elogia seu bom gosto. Ele pergunta se ela soube o que aconteceu a Vladimir e pergunta se ela teve um caso com ele. Ela nega. Valadares diz que seu pr\u00f3ximo encontro ser\u00e1 com Leonardo Alc\u00e2ntara Diniz. Ela acha muito arriscado, pois ele pode reconhec\u00ea-lo. Rick entra no quarto do pai, v\u00ea Belquiss e fica pasmo. Belquiss sai e Marcelo fica atordoado. Xico pergunta a Cl\u00e9o se ela fala sobre orienta\u00e7\u00e3o sexual com Hel\u00f4, que fica chocada, pois diz que Hel\u00f4 n\u00e3o passa de uma menina. Pedro acorda no quarto de Bernardo com ressaca e os dois conversam sobre a noite anterior. Belquiss conta a \u00c2ngela que dormiu com Marcelo. William passa uma lista com apartamentos \u00e0 venda e pede que Eliana escolha um. Ela diz que antes de morarem juntos, ela precisa conversar com Vicente. Milena entra no quarto e discute com Pedro e Bernardo, que a deixam falando sozinha. Dr. Valadares vai \u00e0 casa de Maria Eugenia, que o apresenta a Drica e Leonardo.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cLuz do Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cLuz do Sol\u201d resumo 29\/06: no capitulo 120 (*) da novela \u201cLuz do Sol\u201d, sexta-feira, 29 de junho, Yan faz uma liga\u00e7\u00e3o e pergunta como conseguir\u00e1 entrar no quarto de Isabela no meio da festa. Ele vai em dire\u00e7\u00e3o a um quarto, quando encontra Quico e disfar\u00e7a. Quando Quico sai, Yan entra no quarto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-144969","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144969"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/131397"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}