{"id":144832,"date":"2018-06-26T14:42:18","date_gmt":"2018-06-26T17:42:18","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144832"},"modified":"2018-06-26T14:42:18","modified_gmt":"2018-06-26T17:42:18","slug":"resumo-novela-malhacao-27-06-tito-filma-a-conversa-entre-aloisio-e-garoto","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-malhacao-27-06-tito-filma-a-conversa-entre-aloisio-e-garoto\/144832","title":{"rendered":"Resumo novela \u201cMalha\u00e7\u00e3o\u201d 27\/06: Tito filma a conversa entre Alo\u00edsio e Garoto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-134199\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/malhacao-vidas-brasileiras-2018-resumo-novela-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/malhacao-vidas-brasileiras-2018-resumo-novela-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/malhacao-vidas-brasileiras-2018-resumo-novela-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cMalha\u00e7\u00e3o\u201d 27\/06 <\/em><\/strong>: no cap\u00edtulo 079(*) da novela \u201cMalha\u00e7\u00e3o\u201d, resumo de quarta-feira, 27 de junho, Alex e Flora reagem mal \u00e0 revela\u00e7\u00e3o de Paulo. Gabriela e Rafael ficam indignados com a condi\u00e7\u00e3o que Alo\u00edsio imp\u00f5e para abrir m\u00e3o da guarda de Garoto. Get\u00falio procura a mochila com dinheiro que escondeu com Isadora. Gabriela conversa com Flora e Alex. Garoto marca um encontro com Alo\u00edsio. P\u00e9rola faz uma proposta para Ros\u00e1lia. Get\u00falio pede um emprego no Le Kebek. Alex e Hugo saem para balada. Tito filma a conversa entre Alo\u00edsio e Garoto.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Globo, Novela \u201cMalha\u00e7\u00e3o\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p> Gabriela Fortes (Camila Morgado) \u00e9 uma professora absolutamente apaixonada pela profiss\u00e3o. Sua voca\u00e7\u00e3o vai al\u00e9m do of\u00edcio, est\u00e1 estampada na alma. Corajosa, traz consigo a jovem idealista do passado, que esperava mudar o mundo atrav\u00e9s do seu trabalho em sala de aula. H\u00e1 anos ensina Portugu\u00eas e Literatura no Col\u00e9gio Sapi\u00eancia, escola particular de Botafogo, zona sul do Rio de Janeiro. Apesar de muito envolvida com seus alunos, a cada dia fica mais evidente sua necessidade de se dedicar a um sonho antigo: contribuir com a educa\u00e7\u00e3o de adolescentes carentes, fazer a diferen\u00e7a na vida destes jovens, dando a eles uma possibilidade de um futuro diferente.<\/p>\n<p>E \u00e9 exatamente por ter muita coisa para lidar que, por vezes, deixa de lado sua pr\u00f3pria vida para estar mais pr\u00f3xima dos seus alunos. Casada com Paulo (Felipe Rocha) e m\u00e3e de tr\u00eas filhos \u2013 os g\u00eameos Flora (Jeniffer Oliveira) e Alex (Daniel Rangel) e a pequena Mel (Maria Rita) \u2013, Gabriela se tornou uma mulher mais pragm\u00e1tica. E sua fam\u00edlia se ressente da sua aus\u00eancia, cobrando a presen\u00e7a dela em casa.<\/p>\n<p>O clima em casa piora quando Gabriela \u00e9 surpreendida com uma not\u00edcia inesperada. Empolgada em liderar uma parceria entre o Col\u00e9gio Sapi\u00eancia e a ONG Percurso, que leva jovens de baixa renda para estudar em escolas particulares de alto rendimento, Gabriela descobre que o diretor da organiza\u00e7\u00e3o \u00e9 um grande amor do passado. Rafael (Carmo Dalla Vecchia) foi uma paix\u00e3o mal resolvida da adolesc\u00eancia, com quem dividia os mesmos ideais. O reencontro provoca um rebuli\u00e7o na vida de Gabriela e desestabiliza ainda mais o casamento, j\u00e1 que Paulo n\u00e3o conter\u00e1 seu ci\u00fame ao ver a esposa mergulhada na miss\u00e3o de fazer os novos alunos se destacarem na escola. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cMalha\u00e7\u00e3o\u201d 27\/06 : no cap\u00edtulo 079(*) da novela \u201cMalha\u00e7\u00e3o\u201d, resumo de quarta-feira, 27 de junho, Alex e Flora reagem mal \u00e0 revela\u00e7\u00e3o de Paulo. Gabriela e Rafael ficam indignados com a condi\u00e7\u00e3o que Alo\u00edsio imp\u00f5e para abrir m\u00e3o da guarda de Garoto. Get\u00falio procura a mochila com dinheiro que escondeu com Isadora. Gabriela [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":134199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[447,379,375,343],"tags":[441],"class_list":["post-144832","post","type-post","status-publish","format-standard","has-post-thumbnail","category-malhacao","category-novelas","category-rede-globo","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/malhacao-vidas-brasileiras-2018-resumo-novela.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144832"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/134199"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}