{"id":14231,"date":"2009-10-15T12:38:39","date_gmt":"2009-10-15T16:38:39","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14231"},"modified":"2009-10-15T12:38:39","modified_gmt":"2009-10-15T16:38:39","slug":"lg-apresenta-celular-new-chocolate-bl40-na-futurecom-2009","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/lg-apresenta-celular-new-chocolate-bl40-na-futurecom-2009\/14231","title":{"rendered":"LG apresenta celular new chocolate bl40 na Futurecom 2009"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/lg2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14232\" title=\"lg\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/\/lg2-249x187.jpg\" alt=\"lg\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lg2-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>A LG Electronics mostra pela primeira vez no Brasil, durante o Futurecom 2009, o modelo New Chocolate BL40 &#8211; a quarta gera\u00e7\u00e3o da Black Label Series. Para o evento, que \u00e9 o principal do setor de telecomunica\u00e7\u00f5es e tecnologia da informa\u00e7\u00e3o da Am\u00e9rica Latina, a LG est\u00e1 com um estande de 150m\u00b2, localizado no corredor principal, em que exp\u00f5e ao p\u00fablico os mais modernos celulares do mercado, em ambientes criados de acordo com o diferencial tecnol\u00f3gico de cada um &#8211; High Tech, Smartphone, Messaging, Full Touch, Music e TV Phone.<\/p>\n<p>&#8220;O Futurecom \u00e9 um evento de extrema import\u00e2ncia para a LG, que apresentar\u00e1 ao mercado tend\u00eancias e novidades na sua linha de celular, inclusive para 2010. Esse est\u00e1 sendo um ano muito importante para o segmento, com a introdu\u00e7\u00e3o e evolu\u00e7\u00e3o de tecnologias de converg\u00eancia, e a LG n\u00e3o poderia estar fora dessa grande feira&#8221;, diz Marcus Daniel de Souza Machado, diretor da divis\u00e3o de Celulares da LG Electronics no Brasil.<\/p>\n<p>O New Chocolate \u00e9 a grande aposta da LG, em celulares, para o Natal. Como a mais nova gera\u00e7\u00e3o da Black Label Series &#8211; s\u00e9rie de aparelhos criados para traduzir um estilo de vida que est\u00e1 al\u00e9m de qualquer tend\u00eancia tecnol\u00f3gica ou modismo &#8211; \u00e9 um aparelho sofisticado, com recursos inovadores que certamente mudar\u00e3o a maneira do consumidor interagir com o celular.<\/p>\n<p>Com a exclusiva tela de 4 polegadas, o aparelho oferece a possibilidade de visualizar confortavelmente p\u00e1ginas da web sem usar a barra de rolagem na horizontal, assistir a filmes e jogar games no formato wide HD (21:9), acessar e-mails com painel duplo, entre outras funcionalidades diferenciadas e avan\u00e7adas, como A-GPS, Tecnologia 3G e Wi-Fi, al\u00e9m da premiada interface 3D S-Class &#8211; tudo isso em um celular extremamente fino e leve, com 10,9mm de espessura e apenas 130g.<\/p>\n<p>O produto estar\u00e1 dispon\u00edvel no mercado brasileiro a partir de novembro de 2009.<\/p>\n<p>Conhe\u00e7a outras grandes inova\u00e7\u00f5es apresentadas pela empresa durante a feira, expostas no seu estande (Pavilh\u00e3o B\/ B-19):<\/p>\n<p>HIGH TECH<\/p>\n<p>LG Watch Phone GD910<\/p>\n<p>O LG Watch Phone \u00e9 o primeiro celular-rel\u00f3gio do mercado. Com tela de LCD full touchscreen de 1,43 polegadas de vidro temperado, o LG Watch Phone \u00e9 de a\u00e7o inoxid\u00e1vel, resistente a \u00e1gua e possui tecnologia 3G, tendo, portanto, capacidade para fazer v\u00eddeo-chamada, al\u00e9m de ser pr\u00e1tico e funcional. \u00c9 poss\u00edvel fazer liga\u00e7\u00f5es e escrever mensagens facilmente, utilizando sistema de reconhecimento de fala, al\u00e9m de contar com o recurso &#8220;Text-to-Speech&#8221;, a partir do qual o celular reproduz, via voz, mensagens de texto. As fun\u00e7\u00f5es MP3 Player e Bluetooth\u00ae Est\u00e9reo o tornam ainda mais completo. Pre\u00e7o m\u00e9dio em defini\u00e7\u00e3o.<\/p>\n<p>LG Crystal GD900<\/p>\n<p>O LG Crystal GD900 \u00e9 o primeiro celular com teclado transparente do mundo. \u00c9 um aparelho \u00fanico, arrojado e ideal para aqueles que gostam de design premium e inovador aliado \u00e0s mais avan\u00e7adas tecnologias. Al\u00e9m da tecnologia 3G e Wi-Fi, possui c\u00e2mera digital de 8MP com flash, tela e teclado multi touch &#8211; ideal para aumentar ou diminuir imagens com maior facilidade &#8211; reconhecimento de escrita por gesto. Acesso a redes sociais, entre outros recursos diferenciados. Pre\u00e7o m\u00e9dio em defini\u00e7\u00e3o.<\/p>\n<p>SMARTPHONES<\/p>\n<p>LG GW620<\/p>\n<p>Com o sistema operacional Android do Google, o GW620 \u00e9 o primeiro celular Android da LG: um smartphone com interface gr\u00e1fica amig\u00e1vel e intuitiva, destinado \u00e0queles que aproveitam o celular para outras atividades de entretenimento al\u00e9m de efetuar chamadas. Com foco no acesso a redes sociais, ele possui teclado touchscreen e outro QWERTY estendido, de cinco linhas, para facilitar e proporcionar maior conforto na digita\u00e7\u00e3o de mensagens. Tem ainda tela LCD de 3 polegadas, tecnologia 3G (HSDPA7.2 e HSUPA2.0), c\u00e2mera de 5MP, A-GPS e conex\u00e3o Wi-Fi. Pre\u00e7o m\u00e9dio em defini\u00e7\u00e3o.<\/p>\n<p>LG Sm@rt GW550 Windows Phone<\/p>\n<p>O LG Sm@rt GW550 \u00e9 um smartphone equipado com o sistema operacional Windows Mobile 6.5 customizado, o que garante interface amig\u00e1vel e maior usabilidade ao aparelho. Com formato QWERTY, que facilita a digita\u00e7\u00e3o de mensagens, o celular possui design fino e diferenciado, bordas arredondadas e acabamento premium em preto e prata. Entre seus recursos de destaque, est\u00e3o a tecnologia 3G de alta velocidade (HSDPA7.2), tela de 2.4 polegadas, viva-voz com alto-falante duplo, que aumenta a pot\u00eancia do som e melhora a qualidade e a nitidez da chamada em locais com barulho. Outro diferencial do produto \u00e9 o recurso &#8220;LG Push Mail&#8221;*, sistema de recebimento autom\u00e1tico e instant\u00e2neo de mensagens de e-mail, sem cobran\u00e7a de taxa extra. Produto dispon\u00edvel no mercado no final de outubro\/2009.<\/p>\n<p>*(O LG Push Mail requer tr\u00e1fego de dados durante o processo de download, que pode ser tarifado a crit\u00e9rio da operadora).<\/p>\n<p>LG GT810<\/p>\n<p>O GT810 \u00e9 destinado ao consumidor que procura a melhor tecnologia em smartphone, mas n\u00e3o abre m\u00e3o de ter um celular touchscreen com design diferenciado. Este aparelho, de interface gr\u00e1fica amig\u00e1vel, tem como base o sistema operacional Windows Mobile 6.1 e vem com uma robusta plataforma de hardware para a melhor experi\u00eancia em termos de entretenimento e produtividade. Possibilita uma navega\u00e7\u00e3o plena e em alta velocidade, por meio da tecnologia 3G ou da conex\u00e3o WI-FI. Com ampla visualiza\u00e7\u00e3o na tela de 3 polegadas, o GT810 \u00e9 totalmente sens\u00edvel ao toque e apresenta tamb\u00e9m amplo teclado QWERTY virtual para facilitar a intera\u00e7\u00e3o com o aparelho. Possui ainda c\u00e2mera de 3MP com autofoco, A-GPS e bot\u00e3o de rolagem para melhor integra\u00e7\u00e3o com as fun\u00e7\u00f5es e menus. Produto j\u00e1 dispon\u00edvel no mercado.<\/p>\n<p>MESSAGING<\/p>\n<p>LG Messenger GT360<\/p>\n<p>O celular LG Messenger GT360 \u00e9 feito especialmente para aqueles que querem estar conectados 24 horas por meio de comunicadores instant\u00e2neos, como o Windows Live Messenger. Com conex\u00e3o de Internet para o usu\u00e1rio acessar a Web de onde estiver e teclado QWERTY completo, a divers\u00e3o fica muito mais f\u00e1cil e r\u00e1pida. Outros diferenciais do aparelho s\u00e3o o display de 2.4 polegadas sens\u00edvel ao toque para discagem, cart\u00e3o de mem\u00f3ria de 1GB j\u00e1 incluso, c\u00e2mera de 2.0 MP com Zoom 4x, Bluetooth\u00ae est\u00e9reo, MP3 Player e r\u00e1dio FM. Produto j\u00e1 dispon\u00edvel no mercado nas cores azul, rosa e vermelho.<\/p>\n<p>FULL TOUCH<\/p>\n<p>LG Arena KM900<\/p>\n<p>Ganhador de dois renomados pr\u00eamios em 2009, o LG Arena atingiu a marca global de 1 milh\u00e3o de unidades vendidas. Lan\u00e7ado no Brasil no primeiro semestre de 2009, o LG Arena KM900 chama a aten\u00e7\u00e3o por ser um produto Premium que combina a alta performance \u00e0 experi\u00eancia multim\u00eddia. Com design slim, acabamento metalizado e vidro temperado resistente a riscos, o LG Arena KM900 tem interface 3D S-Class din\u00e2mica e intuitiva, tela de 3 polegadas, tecnologia 3G de alta velocidade (HSDPA 7.2), conex\u00e3o Wi-Fi, transmissor de FM, suporte a multi touch e A-GPS. Possui ainda c\u00e2mera de 5 MP com flash e mem\u00f3ria interna de 8GB expans\u00edvel at\u00e9 32GB, entre outras fun\u00e7\u00f5es avan\u00e7adas. Produto j\u00e1 dispon\u00edvel no mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A LG Electronics mostra pela primeira vez no Brasil, durante o Futurecom 2009, o modelo New Chocolate BL40 &#8211; a quarta gera\u00e7\u00e3o da Black Label Series. Para o evento, que \u00e9 o principal do setor de telecomunica\u00e7\u00f5es e tecnologia da informa\u00e7\u00e3o da Am\u00e9rica Latina, a LG est\u00e1 com um estande de 150m\u00b2, localizado no corredor [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-14231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14231"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14231\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}