{"id":141381,"date":"2018-05-12T19:05:25","date_gmt":"2018-05-12T22:05:25","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=141381"},"modified":"2018-05-12T19:05:25","modified_gmt":"2018-05-12T22:05:25","slug":"resumo-novela-carinha-de-anjo-14-05-cristovao-descobre-a-mentira-de-leonardo","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-carinha-de-anjo-14-05-cristovao-descobre-a-mentira-de-leonardo\/141381","title":{"rendered":"Resumo novela \u201cCarinha de Anjo\u201d 14\/05: Crist\u00f3v\u00e3o descobre a mentira de Leonardo"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-99331\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cCarinha de Anjo\u201d 14\/05 <\/em><\/strong>: no cap\u00edtulo 386(*) da novela \u201cCarinha de Anjo\u201d, resumo de segunda-feira, 14 de maio, B\u00e1rbara e Frida decidem fazer uma rota alternativa das freiras e demais colegas da escola que est\u00e3o em passeio em um parque. Ribeiro revela para Peixoto que Haydee est\u00e1 mudada e arrependida. Adolfo recebe Haydee no apartamento dos L\u00e1rios e a mulher se emociona. O homem diz n\u00e3o conseguir pensar em mais ningu\u00e9m. B\u00e1rbara perde os \u00f3culos em um brinquedo alto e fica assustada. Haydee elogia a comida preparada por Adolfo, enquanto o homem conta que est\u00e1 apaixonado por ela. Adolfo comenta que Gustavo est\u00e1 separado de Cec\u00edlia por conta de algumas fotos que deve ser fruto de uma arma\u00e7\u00e3o para separ\u00e1-los. Haydee v\u00ea as fotos e diz para Adolfo que lembra que a mulher das imagens esteve em sua casa para falar com Fl\u00e1vio. <\/p>\n<p>Os dois v\u00e3o correndo para a casa dela, pois Haydee possui uma grava\u00e7\u00e3o do acontecimento. Um empres\u00e1rio pede para falar com Crist\u00f3v\u00e3o e diz que os \u00e1rabes est\u00e3o de volta ao Brasil e querem falar com ele, desde o \u00faltimo contrato. Crist\u00f3v\u00e3o n\u00e3o entende o ocorrido, pois quem fechou o neg\u00f3cio com os \u00e1rabes foi um homem que usou o nome dele em v\u00e3o. Crist\u00f3v\u00e3o ent\u00e3o finge que sabe de tudo para poder provar que \u00e9 inocente para Gustavo. Haydee mostra o v\u00eddeo com \u00e1udio da negocia\u00e7\u00e3o de Fl\u00e1vio para separar Cec\u00edlia e Gustavo. A mulher pede para Adolfo mostrar o v\u00eddeo para Gustavo e Cec\u00edlia, pois possui a obriga\u00e7\u00e3o de fazer o que \u00e9 certo. B\u00e1rbara \u00e9 resgatada com a ajuda de Dulce Maria e fica chateada que Frida lhe largou sozinha. <\/p>\n<p>B\u00e1rbara abra\u00e7a Dulce e lhe agradece. In\u00e1cio e Diana anunciam para Zeca e Miguel que eles v\u00e3o gravar um CD por uma gravadora. Crist\u00f3v\u00e3o conta para Cec\u00edlia e F\u00e1tima sobre os \u00e1rabes para confirmar que Leonardo esteve por tr\u00e1s de todo golpe na Rey Caf\u00e9. Cec\u00edlia vai at\u00e9 a casa de Estef\u00e2nia para conseguir fotos de seu casamento com objetivo que os \u00e1rabes indiquem para Crist\u00f3v\u00e3o quem foi fechar o contrato se passado por ele. Haydee expulsa Fl\u00e1vio de casa. Fl\u00e1vio amea\u00e7a agredir a m\u00e3e, mas Adolfo aparece e interv\u00e9m.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cCarinha de Anjo\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Carinha de Anjo \u00e9 uma telenovela brasileira produzida e exibida originalmente pelo SBT desde o dia 21 de novembro de 2016, substituindo o hor\u00e1rio anteriormente ocupado por C\u00famplices de um Resgate. A telenovela \u00e9 inspirada na mexicana Carita de \u00e1ngel, que, por sua vez, \u00e9 um remake de Mundo de juguete, ambas produzidas pela Televisa e que haviam sido baseadas na trama argentina escrita por Abel Santa Cruz, Pap\u00e1 coraz\u00f3n. Esta ser\u00e1 a segunda adapta\u00e7\u00e3o brasileira da obra original argentina, visto que a Rede Tupi apresentou em 1976 a sua primeira vers\u00e3o, chamada de Papai Cora\u00e7\u00e3o. A nova vers\u00e3o \u00e9 escrita por Leonor Corr\u00eaa, com supervis\u00e3o de \u00cdris Abravanel e dire\u00e7\u00e3o geral de Ricardo Mantoanelli. A trama conta com Lorena Queiroz, Bia Arantes, Carlo Porto, Priscila Sol, Dani Gondim, Karin Hils, Eliana Guttman e Lucero nos pap\u00e9is principais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cCarinha de Anjo\u201d 14\/05 : no cap\u00edtulo 386(*) da novela \u201cCarinha de Anjo\u201d, resumo de segunda-feira, 14 de maio, B\u00e1rbara e Frida decidem fazer uma rota alternativa das freiras e demais colegas da escola que est\u00e3o em passeio em um parque. Ribeiro revela para Peixoto que Haydee est\u00e1 mudada e arrependida. Adolfo recebe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":99331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[452,379,372,343],"tags":[441],"class_list":["post-141381","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carinha-de-anjo","category-novelas","category-sbt","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/141381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=141381"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/141381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/99331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=141381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=141381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=141381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}