{"id":141032,"date":"2018-05-08T16:50:45","date_gmt":"2018-05-08T19:50:45","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=141032"},"modified":"2018-05-08T21:16:47","modified_gmt":"2018-05-09T00:16:47","slug":"resumo-novela-celebridade-09-05-renato-consegue-imagens-de-laura-com-traficante","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-celebridade-09-05-renato-consegue-imagens-de-laura-com-traficante\/141032","title":{"rendered":"Resumo novela \u201cCelebridade\u201d 09\/05: Renato consegue imagens de Laura com traficante"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/celebridade_novela_resumo_glogo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-127142\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/celebridade_novela_resumo_glogo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/celebridade_novela_resumo_glogo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cCelebridade\u201d 09\/05 <\/em><\/strong>: no cap\u00edtulo 104(*) da novela \u201cCelebridade\u201d, resumo de quarta-feira, 09 de maio, Laura conta a raz\u00e3o de seu \u00f3dio por Maria Clara, que se impressiona. Vladimir ouve a hist\u00f3ria de Darlene, acha que ela foi baixa e expulsa-a de sua casa. Jaqueline aceita carona e carinhos de Vladimir. In\u00e1cio conversa com Fernando sobre a m\u00e3e e mostra-se preocupado por ela distorcer a realidade. Fernando assume que est\u00e1 namorando T\u00e2nia. Ademar pede que Ernesto lhe arranje um emprego, mas este o humilha. Renato e Ana Paula armam uma estrat\u00e9gia para que Laura entre em um mega investimento imobili\u00e1rio e aplique todo seu dinheiro. Peixoto avisa que Maria Clara foi enquadrada em tr\u00e1fico, que \u00e9 crime inafian\u00e7\u00e1vel, mas que ele vai entrar com um h\u00e1beas corpus. <\/p>\n<p>A imprensa cerca Maria Clara, quando ela est\u00e1 sendo transferida para o Rio. Renato vai com Felipe \u00e0 sala de Beatriz e Laura tamb\u00e9m se interessa em ver o projeto. Fernando se choca ao saber que Maria Clara foi presa. Ubaldo avisa que Felipe ligou e Laura garante que quer entrar no investimento. Ana Paula garante a Renato que ela mordeu a isca. Maria Clara volta para casa e chora abra\u00e7ada com a filha. Bruno surpreende Laura na sala da presid\u00eancia, vendo o dossi\u00ea do empreendimento. Renato vai ao hotel, onde Manolo viu Laura. Hugo tenta atenuar, mas Maria Clara est\u00e1 convencida. Laura mente a Bruno, dizendo que estava lendo uma carta de amigos dos Estados Unidos. Maria Clara garante que vai provar o envolvimento de Laura na sua pris\u00e3o. Bruno d\u00e1 uma olhada no papel que Laura guardou na bolsa. Renato consegue a lista dos h\u00f3spedes do hotel do Rio no dia em que Laura esteve l\u00e1. Laura se re\u00fane com Ubaldo e Felipe e expulsa Ana Paula da conversa. Bruno comenta com Cristiano e No\u00eamia que n\u00e3o havia carta alguma e que vai descobrir se Laura esconde alguma coisa do seu passado. <\/p>\n<p>Renato pede que Yolanda d\u00ea uma festa em homenagem a Ubaldo. No\u00eamia vai morar com Cristiano e Zeca vibra. Paulo C\u00e9sar e Sandra curtem estar morando juntos. Laura sabe que a Vasconcelos vai investir no empreendimento e resolve colocar toda a sua grana no neg\u00f3cio. Beatriz ouve de novo a amea\u00e7a pelo telefone. Renato descobre que Laura foi ao tal hotel se encontrar com o traficante, ao ver o nome dele no jornal. Renato garante a Joel que vai descobrir a prova da liga\u00e7\u00e3o entre Laura e o traficante. Maria Clara fecha a empresa Melo Diniz e chora nos bra\u00e7os de Hugo. Seguindo conselho de Ana Paula, Ubaldo aconselha Laura a investir no empreendimento, que ele garante ajud\u00e1-la se ela precisar de dinheiro. Nelito faz charme para Eliete, que gosta. Vladimir lembra a Nelito que ele precisa pagar o col\u00e9gio dos filhos. Renato pede a Tony, seguran\u00e7a do hotel, para ver as fitas da seguran\u00e7a. <\/p>\n<p>Laura apresenta Marcos a Ubaldo e Herc\u00edlia, avisando que ele vai morar na casa. Ubaldo comemora a publica\u00e7\u00e3o de sua entrevista na revista. Renato consegue as imagens de Laura com o traficante. Bruno descobre o nome da pessoa com quem Laura foi para os Estados Unidos. Cristiano n\u00e3o se conforma ao saber que Jairo fugiu. Fernando conversa com Beatriz sobre o envolvimento de Renato com bandidos e pede que ele seja afastado. Nelito pede empr\u00e9stimo a um agiota e paga a Vladimir. Laura n\u00e3o emprega Ademar e humilha-o. Ademar e Ernesto brigam. Ernesto liga para o delegado e conta que o isqueiro encontrado na sala de Lineu pertence a Ademar. Beatriz conversa com Renato, que nega todas as acusa\u00e7\u00f5es.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Globo, Novela \u201cCelebridade\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>A trama tem como eixo central a rivalidade entre duas mulheres: a bem-sucedida empres\u00e1ria e ex-modelo Maria Clara Diniz, dona da produtora Mello Diniz, e a dissimulada e ardilosa Laura Prudente da Costa, que se aproxima de Maria Clara dizendo ser sua maior admiradora e consegue um emprego em sua empresa, tramando na verdade tomar posse de tudo que \u00e9 seu. Para realizar o plano de destruir a rival, Laura conta com a ajuda de Marcos, seu namorado e c\u00famplice. Eles come\u00e7am a trabalhar, respectivamente, como assistente e motorista de Maria Clara, e aos poucos v\u00e3o se infiltrando na vida da celebridade. A dupla de vil\u00f5es \u2013 a Cachorra e o Mich\u00ea, como Laura e Marcos se chamavam mutuamente \u2013 planeja cada passo cuidadosamente para que Maria Clara seja derrubada e caluniada.<\/p>\n<p>Apenas em um certo ponto da trama \u00e9 explicado que a raz\u00e3o do \u00f3dio \u00e9, na verdade, vingan\u00e7a. A can\u00e7\u00e3o Musa de Ver\u00e3o \u2013 uma esp\u00e9cie de Garota de Ipanema \u2013, que tornara Maria Clara famosa e rica, \u00e9 uma fraude e n\u00e3o foi escrita por Wagner, falecido noivo da empres\u00e1ria, nem teve Maria Clara como inspira\u00e7\u00e3o. A can\u00e7\u00e3o foi composta pelo padrasto de Laura, Ubaldo, em homenagem \u00e0 sua m\u00e3e Mar\u00edlia, por\u00e9m foi roubada por Wagner, que a registrou e lan\u00e7ou como obra sua e colocou Maria Clara como sua musa inspiradora. O roubo da can\u00e7\u00e3o contou com a ajuda de Ernesto, irm\u00e3o de Wagner, e do empres\u00e1rio Lineu, que tirou proveito da tramoia. Enquanto isso Laura viu sua fam\u00edlia ruir e amargar uma vida miser\u00e1vel na pobreza. Ubaldo matou Wagner para vingar-se e passou 15 anos na pris\u00e3o, enquanto a m\u00e3e de Laura morreu ap\u00f3s uma depress\u00e3o desenvolvida pelo acontecimento, deixando a garota criando-se sozinha, vivendo de caridade e planejando vingar-se daqueles que destru\u00edram sua fam\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cCelebridade\u201d 09\/05 : no cap\u00edtulo 104(*) da novela \u201cCelebridade\u201d, resumo de quarta-feira, 09 de maio, Laura conta a raz\u00e3o de seu \u00f3dio por Maria Clara, que se impressiona. Vladimir ouve a hist\u00f3ria de Darlene, acha que ela foi baixa e expulsa-a de sua casa. Jaqueline aceita carona e carinhos de Vladimir. In\u00e1cio conversa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":127142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,375,343],"tags":[441],"class_list":["post-141032","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-globo","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/celebridade_novela_resumo_glogo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/141032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=141032"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/141032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/127142"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=141032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=141032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=141032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}