{"id":140989,"date":"2018-05-08T00:49:16","date_gmt":"2018-05-08T03:49:16","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=140989"},"modified":"2018-05-09T21:09:35","modified_gmt":"2018-05-10T00:09:35","slug":"novela-luz-do-sol-resumo-09-05-stella-esbofeteia-freddy","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-luz-do-sol-resumo-09-05-stella-esbofeteia-freddy\/140989","title":{"rendered":"Novela \u201cLuz do Sol\u201d resumo 09\/05: Stella esbofeteia Freddy"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-131397\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cLuz do Sol\u201d resumo 09\/05<\/em><\/strong>: no capitulo 083 (*) da novela \u201cLuz do Sol\u201d, quarta-feira, 09 de maio, Agenor pede \u00e0 mulher que recupere a correntinha e a chave para descobrir quem mandou seq\u00fcestrar a Drica. Para Agenor, esta ser\u00e1 a \u00fanica maneira de proteger Drica, pois teme que a menina se lembre de algo, atraindo quem quer acabar com ela. Stella fica pasma ao saber que Freddy comprou uma casa no condom\u00ednio deles para viver com Kayla. Leonardo conta que Freddy amea\u00e7ou jogar sujo e exigir a guarda dos dois filhos dele. Eliana pede a Marcelo que n\u00e3o defenda Agenor e fica contrariada ao ver a farta mesa de lanche que Drica p\u00f4s para as visitas, lembrando que n\u00e3o s\u00e3o ricos. <\/p>\n<p>Stella avisa a fam\u00edlia que vai \u00e0 casa de Freddy. Eliana diz que n\u00e3o quer mais ver Agenor, que vai a Angra e manda Drica vender camar\u00f5es.Mascote olha com maldade Drica surfando. Georgi entrega a carta de Drica a Bernardo. Drica volta do mar e v\u00ea seus camar\u00f5es jogados no ch\u00e3o. Ela joga o resto no lixo e Mascote se aproxima com cinismo querendo comprar um espeto. Lorena promete Isabela a pegar o exame de Drica no laborat\u00f3rio. Stella entra na casa de Freddy e se anuncia como Stella Alc\u00e2ntara Diniz.<\/p>\n<p>Stela d\u00e1 um grito com Kayla que sai de fininho. Freddy diz que far\u00e1 exame de DNA nos seus dois filhos e que, vai querer a cust\u00f3dia caso sejam mesmo o pai deles. Stella esbofeteia Freddy vaticinando que seus filhos jamais se misturar\u00e3o com as vadias dele. Isabela defende o pai, dizendo que a culpa de tudo que aconteceu foi de Drica. Stella avisa a filha que se ela ficar a favor do pai, que pode fazer as malas para viver com ele e com a secret\u00e1ria do estaleiro na vizinhan\u00e7a. Eliana liga para William que sai para encontr\u00e1-la. Sem a barba e o bigode, Tom vai pedir a\u00e7\u00facar a Baba Edith para fazer um bolo. William se encontra com Eliana em Saquarema, que chora abra\u00e7ada a ele. Vicente tenta beijar Drica avisa que ir\u00e1 embora para sempre se ele fizer isto novamente, pois ele \u00e9 seu irm\u00e3o.<\/p>\n<p>Num restaurante de Saquarema, Eliana prepara William para ouvir o que tem a dizer, pedindo que ele jure que a conversa ficar\u00e1 entre eles. Ver\u00f4nica fica chocada ao chegar em casa e se deparar com Tom em conversa animad\u00edssima com Bab\u00e1 Edith e Joaquim. Bab\u00e1 oferece bolo a Ver\u00f4nica, que acha delicioso. Tom diz que ele fez o bolo e ela se engasga. Tom diz a Ver\u00f4nica que n\u00e3o precisam ir a restaurante algum, que podem ficar por ali mesmo, fazem uma foto, e pronto. Ela discorda, pois n\u00e3o foi o que combinaram com Ot\u00e1vio. Sai a revista com as fotos de Nina com Felipe Dylon \u2013 ela teme que os f\u00e3s de Luckystar a reconhe\u00e7am.No jantar, Ver\u00f4nica e Tom trocam elogios. Ao saber o que Freddy falou para Drica, Xico diz a Stella estar torcendo ainda mais para ser o pai verdadeiro da menina. Eliana conta tudo o que Agenor lhe disse para William, que resolve ir com ela a Angra e ajud\u00e1-la a descobrir que foi que mandou seq\u00fcestrar Drica.  <\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cLuz do Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cLuz do Sol\u201d resumo 09\/05: no capitulo 083 (*) da novela \u201cLuz do Sol\u201d, quarta-feira, 09 de maio, Agenor pede \u00e0 mulher que recupere a correntinha e a chave para descobrir quem mandou seq\u00fcestrar a Drica. Para Agenor, esta ser\u00e1 a \u00fanica maneira de proteger Drica, pois teme que a menina se lembre de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-140989","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=140989"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/131397"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=140989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=140989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=140989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}