{"id":140792,"date":"2018-05-05T05:32:52","date_gmt":"2018-05-05T08:32:52","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=140792"},"modified":"2018-05-05T05:33:40","modified_gmt":"2018-05-05T08:33:40","slug":"novela-segundo-sol","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-segundo-sol\/140792","title":{"rendered":"Novela &#8220;Segundo Sol&#8221;: elenco e personagens"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-140790\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela &#8220;Segundo Sol&#8221;<\/em><\/strong> elenco e personagens: Beto Falc\u00e3o (Em\u00edlio Dantas) foi um \u00edcone do ax\u00e9 na d\u00e9cada de 90. O cantor teve muito dinheiro e fama, levou milhares de f\u00e3s atr\u00e1s do seu trio el\u00e9trico, mas, em 1999, est\u00e1 em franca decad\u00eancia. Por conting\u00eancias do destino, ele \u00e9 dado como morto e a not\u00edcia provoca uma grande como\u00e7\u00e3o, fazendo com que as vendas de suas obras disparem.<\/p>\n<p>Convencido pelo irm\u00e3o Remy (Vladimir Brichta) e pela namorada Karola (Deborah Secco) de que se manter morto \u00e9 o melhor a fazer, ele se refugia numa ilha da Bahia com outra identidade e se apaixona por Luzia (Giovanna Antonelli). Por\u00e9m, o fantasma de seu passado atormenta o seu presente e destr\u00f3i a sua vida e a de sua amada. Ap\u00f3s uma passagem de tempo que traz os personagens a 2018, o acerto de contas com o destino pode cobrar justi\u00e7a das atitudes de Remy, Karola e Laureta (Adriana Esteves), enquanto Luzia vai lutar pela reconstru\u00e7\u00e3o de sua fam\u00edlia, que foi despeda\u00e7ada h\u00e1 quase 20 anos. Eis sua nova chance, seu &#8220;Segundo Sol&#8221;.<\/p>\n<p>Confira a lista do elenco e personagens da Novela &#8220;Segundo Sol&#8221;:<\/p>\n<p>Adriana Esteves ser\u00e1 a vil\u00e3 Laureta;<br \/>\nAndr\u00e9 Dias ser\u00e1 o island\u00eas Groa na pr\u00f3xima novela das 9, &#8220;Segundo Sol&#8221;, amigo fiel de Luzia, interpretada por Giovanna Antonelli;<br \/>\nArlete Salles (Nan\u00e1);<br \/>\nArmando Babaioff (Ionan). O ator ser\u00e1 Ionan, um dos quatro irm\u00e3os da fam\u00edlia Falc\u00e3o;<br \/>\nCaco Ciocler (Edgar);<br \/>\nChay Suede (\u00cdcaro);<br \/>\nDanilo Ferreira (Ac\u00e1cio);<br \/>\nDanilo Mesquita (Valentim);;<br \/>\nDeborah Secco (Karola) \u00e9 a vil\u00e3 Karola;<br \/>\nEm\u00edlio Dantas (Beto Falc\u00e3o) \u00e9 o cantor de ax\u00e9;<br \/>\nFabiula Nascimento (Cacau) \u00e9 irm\u00e3 de Luzia, em &#8220;Segundo Sol&#8221;;<br \/>\nFabr\u00edcio Boliveira (Roberval);<br \/>\nFrancisco Cuoco (Nestor);<br \/>\nGiovanna Antonelli (Luzia) se apaixonar\u00e1 por Beto Falc\u00e3o;<br \/>\nGiovanna Lancellotti (Rochelle), ser\u00e1 uma personagem de car\u00e1ter duvidoso;<br \/>\nJos\u00e9 de Abreu (Dod\u00f4);<br \/>\nLeticia Colin (Rosa);<br \/>\nLu\u00eds Lobianco (Cl\u00f3vis) ser\u00e1 Cl\u00f3vis, irm\u00e3o de Beto Falc\u00e3o, Remy e Ionan;<br \/>\nLuisa Arraes (Manuela);<br \/>\nMaria Lu\u00edsa Mendon\u00e7a (Karen);;<br \/>\nNanda Costa (Maura);<br \/>\nOdilon Wagner (Severo);<br \/>\nRoberta Rodrigues (Doralice);<br \/>\nRoberto Bonfim (Agenor);<br \/>\nThalita Carauta (Gorete);<br \/>\nVladimir Brichta (Remy). Um vil\u00e3o de peso e disposto a se dar bem: esse ser\u00e1 o irm\u00e3o e empres\u00e1rio de Beto Falc\u00e3o.<\/p>\n<p>O elenco conta ainda com Claudia di Moura, no papel de Zefa; Kelzy Ecard como Nice; Osmar Silveira como Narciso; Paulo Borges como Edilei; Carol Fazu no papel de Selma; Narcival Rubens vivendo Galdino; Zeca de Abreu como Janu\u00e1ria, entre outros.<\/p>\n<p>&#8220;Segundo Sol&#8221; \u00e9 sua pr\u00f3xima novela das 9, escrita por Jo\u00e3o Emanuel Carneiro, com dire\u00e7\u00e3o art\u00edstica de Dennis Carvalho e dire\u00e7\u00e3o geral de Maria de M\u00e9dicis. A estreia est\u00e1 prevista para 14 de maio.<\/p>\n<p>Fonte &#8220;Segundo Sol&#8221; &#8211; Rede Globo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela &#8220;Segundo Sol&#8221; elenco e personagens: Beto Falc\u00e3o (Em\u00edlio Dantas) foi um \u00edcone do ax\u00e9 na d\u00e9cada de 90. O cantor teve muito dinheiro e fama, levou milhares de f\u00e3s atr\u00e1s do seu trio el\u00e9trico, mas, em 1999, est\u00e1 em franca decad\u00eancia. Por conting\u00eancias do destino, ele \u00e9 dado como morto e a not\u00edcia provoca [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":140790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,474,343],"tags":[440],"class_list":{"0":"post-140792","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-segundo-sol","10":"category-televisao","11":"tag-noticia-novela","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/segundo-sol-resumo-novela-globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=140792"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/140790"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=140792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=140792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=140792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}