{"id":14042,"date":"2009-10-13T22:15:46","date_gmt":"2009-10-14T02:15:46","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=14042"},"modified":"2009-10-13T22:15:46","modified_gmt":"2009-10-14T02:15:46","slug":"previsao-do-tempo-na-regiao-sudeste-de-14-a-1609","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/previsao-do-tempo-na-regiao-sudeste-de-14-a-1609\/14042","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Sudeste de 14 a 16\/09"},"content":{"rendered":"<p><strong>Previs\u00e3o do tempo na Regi\u00e3o Sudeste<\/strong> em 14\/10\/2009: No leste de SP: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva \u00e0 tarde. No noroeste do RJ, no ES e no leste de MG: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas \u00e0 tarde. Nas demais \u00e1reas do RJ: sol entre poucas nuvens. Nas demais \u00e1reas da Regi\u00e3o: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas. As temperaturas m\u00e1ximas estar\u00e3o em eleva\u00e7\u00e3o em SP. Temperatura m\u00e1xima: 34C no oeste de SP. Temperatura m\u00ednima: 11C no sul de SP.\u00a0<\/p>\n<p>Previs\u00e3o do tempo 15\/10\/2009: No centro-sul e oeste de SP: nublado com pancadas de chuva localmente forte a qualquer hora do dia. No norte de MG: sol entre poucas nuvens. Nas demais \u00e1reas da Regi\u00e3o: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. Em alguns pontos isolados poder\u00e1 chover forte. As temperaturas estar\u00e3o est\u00e1veis na Regi\u00e3o.<\/p>\n<p>Tend\u00eancia: No litoral de SP e do RJ: nublado com chuva a qualquer hora do dia. No extremo norte de MG: sol entre poucas nuvens. Nas demais \u00e1reas da Regi\u00e3o: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas de chuva. As temperaturas continuar\u00e3o est\u00e1veis na Regi\u00e3o. Haver\u00e1 condi\u00e7\u00f5es de pancadas isoladas de chuva em praticamente toda a Regi\u00e3o nos pr\u00f3ximos dois dias.<\/p>\n<p>O Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos \u2013 CPTEC, do Instituto Nacional de Pesquisas Espaciais \u2013 INPE \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Os supercomputadores vetoriais SX-6 e SX-4 fabricados pela NEC Corporation do Jap\u00e3o, possuem capacidade de processar at\u00e9 768 bilh\u00f5es e 16 bilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo respectivamente. Recentemente adquirido da \u201cNEC Corporation do Jap\u00e3o\u201d um cluster com 1100 processadores fabricado pela \u201cSUN Microsystem\u201d com a capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Isso significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.\u00a0<\/p>\n<p>CPTEC\/INPE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Sudeste em 14\/10\/2009: No leste de SP: sol com nebulosidade vari\u00e1vel e uma pequena possibilidade de pancadas de chuva \u00e0 tarde. No noroeste do RJ, no ES e no leste de MG: sol com varia\u00e7\u00e3o de nuvens e pancadas isoladas \u00e0 tarde. Nas demais \u00e1reas do RJ: sol entre poucas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":["post-14042","post","type-post","status-publish","format-standard","category-brasil","category-clima","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=14042"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/14042\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=14042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=14042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=14042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}