{"id":140308,"date":"2018-04-26T14:58:16","date_gmt":"2018-04-26T17:58:16","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=140308"},"modified":"2018-04-26T14:58:16","modified_gmt":"2018-04-26T17:58:16","slug":"resumo-novela-carinha-de-anjo-26-04-leonardo-encontra-adolfo-na-casa-de-gustavo","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/resumo-novela-carinha-de-anjo-26-04-leonardo-encontra-adolfo-na-casa-de-gustavo\/140308","title":{"rendered":"Resumo novela \u201cCarinha de Anjo\u201d 26\/04: Leonardo encontra Adolfo na casa de Gustavo"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-99331\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg\" alt=\"carinha_de_anjo_sbt_novela_resumo_capitulo\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cCarinha de Anjo\u201d 26\/04<\/em><\/strong>: no cap\u00edtulo 374(*) da novela \u201cCarinha de Anjo\u201d, resumo de quinta-feira, 26 de abril, Cec\u00edlia mostra para a Madre Superiora e o Padre Gabriel as fotos que recebeu. A religiosa diz que ela n\u00e3o pode agir de forma impulsiva. O padre estranha as imagens, pois Gustavo nunca desrespeitou nenhuma mulher. Adolfo decide ir passear no parque e diz para Silvestre lhe acompanhar. Cec\u00edlia vai conversar com Gustavo, mas n\u00e3o deixa ele encostar nela. A mulher joga as fotos que recebeu no ch\u00e3o. Gustavo diz que as fotos s\u00e3o uma arma\u00e7\u00e3o e explica o que aconteceu. <\/p>\n<p>Cec\u00edlia n\u00e3o abre espa\u00e7o para conversar a respeito e diz que quer o div\u00f3rcio. Gustavo diz que vai provar para Cec\u00edlia que tudo n\u00e3o passou de uma arma\u00e7\u00e3o e que Dulce Maria n\u00e3o pode perceber que eles est\u00e3o separados. Leonardo vai at\u00e9 a casa de Gustavo e Adolfo v\u00ea o rapaz. Silvestre estranha que os dois se conhecem. Adolfo diz para Leonardo que parece que Gustavo traiu Cec\u00edlia. Adolfo acaba soltando que acha Dulce bem engra\u00e7adinha. Leonardo inventa que precisa ir embora, pois essa n\u00e3o deve ser uma boa hora para falar com Gustavo.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cCarinha de Anjo\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Carinha de Anjo \u00e9 uma telenovela brasileira produzida e exibida originalmente pelo SBT desde o dia 21 de novembro de 2016, substituindo o hor\u00e1rio anteriormente ocupado por C\u00famplices de um Resgate. A telenovela \u00e9 inspirada na mexicana Carita de \u00e1ngel, que, por sua vez, \u00e9 um remake de Mundo de juguete, ambas produzidas pela Televisa e que haviam sido baseadas na trama argentina escrita por Abel Santa Cruz, Pap\u00e1 coraz\u00f3n. Esta ser\u00e1 a segunda adapta\u00e7\u00e3o brasileira da obra original argentina, visto que a Rede Tupi apresentou em 1976 a sua primeira vers\u00e3o, chamada de Papai Cora\u00e7\u00e3o. A nova vers\u00e3o \u00e9 escrita por Leonor Corr\u00eaa, com supervis\u00e3o de \u00cdris Abravanel e dire\u00e7\u00e3o geral de Ricardo Mantoanelli. A trama conta com Lorena Queiroz, Bia Arantes, Carlo Porto, Priscila Sol, Dani Gondim, Karin Hils, Eliana Guttman e Lucero nos pap\u00e9is principais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cCarinha de Anjo\u201d 26\/04: no cap\u00edtulo 374(*) da novela \u201cCarinha de Anjo\u201d, resumo de quinta-feira, 26 de abril, Cec\u00edlia mostra para a Madre Superiora e o Padre Gabriel as fotos que recebeu. A religiosa diz que ela n\u00e3o pode agir de forma impulsiva. O padre estranha as imagens, pois Gustavo nunca desrespeitou nenhuma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":99331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[452,379,372,343],"tags":[441],"class_list":["post-140308","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carinha-de-anjo","category-novelas","category-sbt","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/carinha_de_anjo_sbt_novela_resumo_capitulo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=140308"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/99331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=140308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=140308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=140308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}