{"id":140129,"date":"2018-04-27T12:38:34","date_gmt":"2018-04-27T15:38:34","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=140129"},"modified":"2018-05-01T06:54:32","modified_gmt":"2018-05-01T09:54:32","slug":"novela-luz-do-sol-resumo-30-04-cherry-engana-belquiss","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2018\/novela-luz-do-sol-resumo-30-04-cherry-engana-belquiss\/140129","title":{"rendered":"Novela \u201cLuz do Sol\u201d resumo 30\/04: Cleo conta a Zo\u00e9 que Xico a convidou para jantar"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-131397\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cLuz do Sol\u201d resumo 30\/04<\/em><\/strong>: no capitulo 076 (*) da novela \u201cLuz do Sol\u201d, segunda-feira, 30 de abril, Leonardo se anima em ir ao show de Luckystar ao saber que Zo\u00e9 vai ser a DJ. Drica conta a Bernardo que Hel\u00f4 resolveu se juntar com Isabela pra armar alguma contra ela. Clemente mente para Kayla dizendo que n\u00e3o achou seu celular. Entre a lista de exig\u00eancias de seu camarim, Luckystar pediu brigadeiro Branco, que Belquiss lembra que \u00e9 o favorito de Nina. Odete diz a Kayla que Milena andou procurando pelo celular dela no estaleiro. Leonardo marca reuni\u00e3o extraordin\u00e1ria para avisar que Milena suspendeu o vale-transporte e de alimenta\u00e7\u00e3o dos funcion\u00e1rios do estaleiro. Milena diz que n\u00e3o \u00e9 obrigada a bancar a comida e transporte para a gentalha. Odete explica que \u00e9 obrigada sim e por lei. Orientado por Hel\u00f4, Yan elogia o visual de Drica e de Giorgi, banca o simp\u00e1tico e se despede avisando que se encontrar\u00e3o no show. A atriz entrega a Rick e Zo\u00e9 que fiou Lorena quem a contratou. Zo\u00e9 diz a Rick. Que contar\u00e1 tudo a Leonardo somente para que ele saiba at\u00e9 que ponto Lorena pode chegar, mas que acha dif\u00edcil ele perdo\u00e1-la. Ver\u00f4nica sai com Priscila para paquerarem num vel\u00f3rio.<\/p>\n<p>Priscila chora ao lado do caix\u00e3o de um defunto e apanha da vi\u00fava que a confunde com mais uma das amantes do marido. Partem para outra capela, onde o defunto era jogador de v\u00f4lei, de 40 anos, e o vel\u00f3rio est\u00e1 cheio de amigos sarados. Ver\u00f4nica vai consolar um bonit\u00e3o e quase apanha da mulher dele. Um outro a olha muito, mas o namorado deste chega e o carrega: \u00e9 gay. Tom descobre que Ver\u00f4nica foi a um vel\u00f3rio e deduz que ela foi paquerar. Ot\u00e1vio pergunta a Tom se deu muita pinta dan\u00e7ando no Encontro de Solteiros e Tom pede que ele se abra: \u00e9 gay ou n\u00e3o \u00e9? Ot\u00e1vio, inconformado, afirma que n\u00e3o \u00e9 gay. Nicole briga com Nicanor porque ele marcou um encontro pela Internet e n\u00e3o foi com \u00c2ngela. Danilo traz o exame de DNA e Isabela pergunta como poder mudar o resultado. Ot\u00e1vio conta para Tom que Ver\u00f4nica lhe pediu para selecionar uns pretendentes para ela encontrar aqui na Relacionamentospontocom. Tom diz que estar\u00e1 l\u00e1 no dia dessa sele\u00e7\u00e3o, pois faz quest\u00e3o de te ajudar a escolher uns bons partidos pra Dona Doida.<\/p>\n<p>Isabela manda Pedro procurar nas coisas do Marcelo onde est\u00e1 o papel com o n\u00famero de identifica\u00e7\u00e3o, pra retirar o exame. E assim, substituir\u00e3o o resultado verdadeiro pelo falso. Num hall, pr\u00f3ximo ao camarim de Luckystar, Felipe Dylon pede informa\u00e7\u00f5es a Yvonne e Belquiss tem que segurar a fofoqueira para que ela n\u00e3o agarre o artista. Dylon \u00e9 simp\u00e1tico e pede um beijo a Yvonne, que se pendura nele e ainda pede um aut\u00f3grafo na sua blusa. Triste porque Marcelo n\u00e3o tem lhe dado muita aten\u00e7\u00e3o, Cleo conta a Zo\u00e9 que Xico a convidou para jantar. Zo\u00e9 d\u00e1 a maior for\u00e7a para que ela saia com o professor. Cherry s\u00f3 permite a entrada de Yvonne no camarim. Ao inv\u00e9s de sa\u00edrem, Cleo convida Xico para ir \u00e0 sua casa, para n\u00e3o deixarem In\u00e1cio sozinho. Milena pega Pedro mexendo na pasta de Marcelo, mas ele d\u00e1 uma desculpa. Pelo monitor, Nina v\u00ea a m\u00e3e na \u00e1rea vip, se desespera e avisa a Cherry que vai cancelar o show.<\/p>\n<p>..Para Luckystar subir ao palco, Cherry promete a Nina que vai dar um jeito de tirar Belquiss da plat\u00e9ia e levar para longe. Kayla chora arrasada, Freddy fica penalizado e acaba a beijando. Stella liga para Freddy, mas para sa\u00edrem o celular dele est\u00e1 desligado. A Banda \u201cWWW\u201d faz a abertura do show de Luckystar. Yan, todo simp\u00e1tico, faz galanteios a Drica. Hel\u00f4 est\u00e1 de olho. Duda larga Hel\u00f4 e vai atr\u00e1s de Joaquim. In\u00e1cio sai com os amigos e Cl\u00e9o fica sozinha no apartamento com Xico, que chega com queijos e vinhos. Cherry inventa que o Luckystar, os m\u00fasicos e a equipe passaram mal com a comida do buf\u00ea e manda Belquiss \u00e0 farm\u00e1cia comprar rem\u00e9dios, caso contr\u00e1rio, n\u00e3o haver\u00e1 show. Belquiss diz que n\u00e3o \u00e9 mulher delivery, e que se eles est\u00e3o passando mal \u00e9 porque comeram demais as porcarias. E n\u00e3o se move da plat\u00e9ia, para o desespero de Cherry. <\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cLuz do Sol\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cLuz do Sol\u201d resumo 30\/04: no capitulo 076 (*) da novela \u201cLuz do Sol\u201d, segunda-feira, 30 de abril, Leonardo se anima em ir ao show de Luckystar ao saber que Zo\u00e9 vai ser a DJ. Drica conta a Bernardo que Hel\u00f4 resolveu se juntar com Isabela pra armar alguma contra ela. Clemente mente para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,371,343],"tags":[441],"class_list":["post-140129","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-record","category-televisao","tag-resumo-do-dia","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/luz-do-sol-resumo-novela-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=140129"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/140129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/131397"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=140129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=140129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=140129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}